{"id":10197,"date":"2022-04-08T17:46:24","date_gmt":"2022-04-08T15:46:24","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=10197"},"modified":"2022-04-08T17:46:24","modified_gmt":"2022-04-08T15:46:24","slug":"mesures-presidentielles-automobile","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/actualites-automobile\/mesures-presidentielles-automobile\/","title":{"rendered":"Automobile : les mesures des candidats a\u0300 la pre\u0301sidentielle"},"content":{"rendered":"<p>Les e\u0301lections pre\u0301sidentielles de 2022 arrivent a\u0300 tr\u00e8s grands pas, Coyote vous propose de faire le point sur les mesures concernant le secteur de l\u2019automobile et du transport.<\/p>\n<p>Alors que vous he\u0301sitez peut-\u00eatre encore pour quel candidat vous allez voter, nous faisons le point sur les conse\u0301quences que pourraient avoir l\u2019e\u0301lection potentielle des diffe\u0301rents pre\u0301tendants\u00a0! Prix du carburant, normes environnementales, permis a\u0300 point\u2026 Coyote vous dit tout\u00a0!<\/p>\n<h2 style=\"color: #64e600\">Jean-Luc Me\u0301lenchon (France Insoumise)<\/h2>\n<p>Le candidat de la France Insoumise a annonce\u0301 plusieurs mesures concernant le secteur du transport et de l\u2019automobile, il a dit vouloir bloquer <strong>le prix de l\u2019essence a\u0300 1,40 euro le litre<\/strong> en re\u0301duisant la marge des grands groupes pe\u0301troliers.<\/p>\n<p>Jean-Luc Me\u0301lenchon se veut anti SUV et souhaite encourager le covoiturage ainsi que l\u2019usage de carburants alternatifs a\u0300 des fins e\u0301cologiques. Voici ses mesures phares\u00a0:<\/p>\n<ul>\n<li>Renationaliser les autoroutes afin qu\u2019elles redeviennent publiques et revenir aux tarifs ante\u0301rieurs ;<\/li>\n<li>Mise a\u0300 disposition de ve\u0301hicules a\u0300 faibles e\u0301missions pour les me\u0301nages a\u0300 faibles revenus\u00a0;<\/li>\n<li>Opter pour une police de la route plut\u00f4t que les radars automatiques \/ radars de vitesse\u00a0;<\/li>\n<li>De\u0301velopper l\u2019usage de carburants plus e\u0301cologiques (re\u0301trofit, e\u0301lectrique) ;<\/li>\n<li>Relocaliser l\u2019industrie automobile en France.<\/li>\n<\/ul>\n<h2 style=\"color: #64e600\">Emmanuel Macron (LREM)<\/h2>\n<p>Le candidat au potentiel second mandat pre\u0301sidentiel a quant a\u0300 lui affirme\u0301 ne pas vouloir plafonner le prix du carburant. <strong>Il pre\u0301voit plut\u00f4t de mettre en place des dispositifs d\u2019aide e\u0301conomique en cas d\u2019augmentation soudaine du co\u00fbt de l\u2019essence.<\/strong> Voici quelques mesures de son programme\u00a0:<\/p>\n<ul>\n<li>Mise en place potentielle d\u2019une clause de revoyure en 2028 sur la possibilite\u0301 de conserver les moteurs thermiques apr\u00e8s 2035 ;<\/li>\n<li>Cre\u0301ation d&rsquo;un \u00ab\u00a0leasing social\u00a0\u00bb avec des ve\u0301hicules a\u0300 prix plancher (a\u0300 partir de 100 \u20ac par mois) pour rendre l&rsquo;e\u0301lectrique plus abordable\u00a0;<\/li>\n<li>Accompagnement des PME dans la transition e\u0301cologique, avec la fin du \u00ab bashing automobile \u00bb (expression employe\u0301e pour de\u0301signer un acharnement le\u0301gislatif contre les automobilistes).<\/li>\n<\/ul>\n<h2 style=\"color: #64e600\">Yannick Jadot (EELV)<\/h2>\n<p><strong>La principale prise de position du candidat des Verts consiste a\u0300 sortir du thermique d\u2019ici 2030.<\/strong> Il souhaite que la vente de ve\u0301hicules a\u0300 moteur thermique soit interdite apr\u00e8s cette date. Il de\u0301fend l\u2019utilisation du re\u0301trofit et de l\u2019e\u0301lectrique comme alternative. Voici quelques-unes de ses propositions\u00a0:<\/p>\n<ul>\n<li>Investissement de 7 milliards d\u2019euros pour la SNCF dans une logique de de\u0301veloppement des chemins de fer avec notamment un \u00ab Pass liberte\u0301 climat \u00bb permettant un acc\u00e8s illimite\u0301 a\u0300 tous les transports d\u00e8s 16 ans ;<\/li>\n<li>Fin des ve\u0301hicules a\u0300 moteur thermique fixe\u0301e en 2030\u00a0;<\/li>\n<li>De\u0301veloppement de p\u00f4les de partage de ve\u0301hicules e\u0301lectriques a\u0300 l\u2019entre\u0301e des zones rurales, du covoiturage et de l\u2019intermodalite\u0301\u00a0;<\/li>\n<li>Aide au de\u0301placement de 1000 euros par an pour les salarie\u0301s.<\/li>\n<\/ul>\n<h2 style=\"color: #64e600\">Marine Le Pen (RN)<\/h2>\n<p>La candidate du Rassemblement National refuse de laisser la transition e\u0301cologique contraindre les citoyens. Elle affirme vouloir supprimer les zones a\u0300 faibles e\u0301missions et les malus automobiles ou encore ajouter les ve\u0301hicules hybrides a\u0300 la liste des ve\u0301hicules propres. Face au prix du carburant<strong>, elle pre\u0301voit de baisser la TVA a\u0300 5,5% et proposer un pr\u00eat de 1000 euros pour la conversion au bioe\u0301thanol<\/strong>.<\/p>\n<ul>\n<li>Suppression des ZFE ;<\/li>\n<li>De\u0301ploiement des bornes de recharge pour les ve\u0301hicules e\u0301lectriques\u00a0;<\/li>\n<li>Fin de la fiscalite\u0301 punitive et des malus automobiles\u00a0;<\/li>\n<li>Mise en place d\u2019une agence nationale de ma\u00eetrise des mati\u00e8res premi\u00e8res.<\/li>\n<\/ul>\n<h2 style=\"color: #64e600\">Anne Hidalgo (PS)<\/h2>\n<p>Anne Hidalgo souhaite poursuivre la dynamique qu\u2019elle a applique\u0301 a\u0300 la capitale afin de re\u0301duire la pollution automobile<strong>. Elle dit vouloir sortir du diesel d\u2019ici 2024.<\/strong> Face au prix du carburant, elle opte elle aussi pour une baisse de la TVA a\u0300 5,5% avec un plafonnement du prix hors-taxes.<\/p>\n<ul>\n<li>Favorable au de\u0301veloppement des bornes de recharge et des stations a\u0300 hydrog\u00e8ne ainsi que du leasing social pour les voitures e\u0301lectriques ;<\/li>\n<li>Aide de 5000 euros pour les jeunes souhaitant passer leur permis de conduire\u00a0;<\/li>\n<li>Sortie du diesel d\u2019ici 2024.<\/li>\n<\/ul>\n<h2 style=\"color: #64e600\">Eric Zemmour (Reconqu\u00eate)<\/h2>\n<p><strong>Le candidat de la Reconqu\u00eate a annonce\u0301 vouloir plafonner le prix de l\u2019essence a\u0300 1,80 euros gr\u00e2ce a\u0300 une refonte de la fiscalite\u0301 lie\u0301e aux carburants.<\/strong> Il souhaite prolonger la dure\u0301e de validite\u0301 du contr\u00f4le technique de 2 ou 3 ans et s\u2019oppose au contr\u00f4le technique pour les deux roues. Voici ses principales mesures\u00a0:<\/p>\n<ul>\n<li>Suppression des zones a\u0300 faibles e\u0301missions ;<\/li>\n<li>Fin du permis a\u0300 points pour le permis conduire (mise en place de suspensions en cas de comportements dangereux et d\u2019amendes plus conse\u0301quentes)\u00a0;<\/li>\n<li>Re\u0301tablissement des limites a\u0300 50km\/h et 90km\/h\u00a0;<\/li>\n<li>Plafonnement du prix du carburant a\u0300 1,80 euro le litre.<\/li>\n<\/ul>\n<h2 style=\"color: #64e600\">Vale\u0301rie Pe\u0301cresse (LR)<\/h2>\n<p>La candidate des Re\u0301publicains se de\u0301clare \u00ab\u00a0pro-voiture\u00a0\u00bb et souhaite mettre un terme aux diffe\u0301rentes mesures contraignant les automobilistes<strong>. Elle veut maintenir les ve\u0301hicules hybrides apr\u00e8s 2035 tout en proposant des pr\u00eats a\u0300 taux ze\u0301ro pour l\u2019achat d\u2019un ve\u0301hicule e\u0301lectrique ou hybride. <\/strong><\/p>\n<ul>\n<li>Report dans le temps du calendrier des zones a\u0300 faibles e\u0301missions ;<\/li>\n<li>Maintien des ve\u0301hicules hybrides apr\u00e8s 2035\u00a0;<\/li>\n<li>De\u0301fense de l\u2019utilisation de la voiture individuelle\u00a0;<\/li>\n<li>Rapatriement de la fili\u00e8re automobile en France.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Les e\u0301lections pre\u0301sidentielles de 2022 arrivent a\u0300 tr\u00e8s grands pas, Coyote vous propose de faire le point sur les mesures [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":10199,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-10197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-automobile"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/10197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=10197"}],"version-history":[{"count":0,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/10197\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/10199"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=10197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=10197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=10197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}