{"id":10859,"date":"2022-12-07T17:29:48","date_gmt":"2022-12-07T16:29:48","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=10859"},"modified":"2022-12-07T17:29:48","modified_gmt":"2022-12-07T16:29:48","slug":"quelle-est-lefficacite-des-voitures-radars-privees","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/radars\/quelle-est-lefficacite-des-voitures-radars-privees\/","title":{"rendered":"Quelle est l&rsquo;efficacite\u0301 des voitures radars prive\u0301es ?"},"content":{"rendered":"<p>Le gouvernement utilise depuis 2018 des voitures radars ge\u0301re\u0301es par des socie\u0301te\u0301s prive\u0301es pour contr\u00f4ler et sanctionner les exc\u00e8s de vitesse. Ces dispositifs, dont le nombre a double\u0301 entre 2020 et 2021, sont aujourd\u2019hui instaure\u0301s dans 39 de\u0301partements fran\u00e7ais. Cette anne\u0301e, la Se\u0301curite\u0301 routi\u00e8re a publie\u0301 des donne\u0301es chiffre\u0301es relatives a\u0300 leur utilisation. Accessibles a\u0300 tous, ces statistiques nous permettent d\u2019e\u0301tablir des premi\u00e8res conclusions quant a\u0300 la pertinence des contr\u00f4les effectue\u0301s et a\u0300 l\u2019efficacite\u0301 des voitures radars pilote\u0301es par des chauffeurs prive\u0301s.<\/p>\n<h2><span style=\"color: #64e61e\">Quelles re\u0301gions sont concerne\u0301es par les voitures radars&nbsp;?<\/span><\/h2>\n<p>Les <strong>voitures radars ge\u0301re\u0301es par des chauffeurs prive\u0301s<\/strong> sont de\u0301sormais de plus en plus utilise\u0301es par les autorite\u0301s pour contr\u00f4ler la circulation routi\u00e8re. Instaure\u0301 en 2018, le dispositif est aujourd\u2019hui <strong>pre\u0301sent dans 8 re\u0301gions me\u0301tropolitaines sur 12<\/strong>&nbsp;: sa mise en place a e\u0301te\u0301 effectue\u0301e de mani\u00e8re progressive, de\u0301partement par de\u0301partement.<\/p>\n<p>Les re\u0301gions o\u00f9 circulent actuellement des voitures radars&nbsp;avec chauffeur&nbsp;: Normandie, Bretagne, Pays de la Loire, Centre-Val-de-Loire, Hauts-de-France, Grand-Est, Bourgogne-Franche-Comte\u0301 et Nouvelle-Aquitaine. Un de\u0301ploiement de voitures radars prive\u0301es est par ailleurs pre\u0301vu dans les quatre re\u0301gions fran\u00e7aises restantes pour fin 2022\/2023.<\/p>\n<h2><span style=\"color: #64e61e\">Quel est le nombre de voitures radars prive\u0301es en France?<\/span><\/h2>\n<p>Actuellement, <strong>la France poss\u00e8de un parc de voitures radars comptant 400 ve\u0301hicules en circulation<\/strong>&nbsp;: 223 voitures sont prises en charge par des ope\u0301rateurs prive\u0301s&nbsp;et 177 sont encore ge\u0301re\u0301s par les forces de l\u2019ordre.<\/p>\n<h2><span style=\"color: #64e61e\">Comment fonctionnent les voitures radars privatise\u0301es&nbsp;?<\/span><\/h2>\n<p>Le parcours, qui est pre\u0301de\u0301fini par les pre\u0301fectures des de\u0301partements, est sillonne\u0301 par l\u2019employe\u0301 durant environ 5h30 avec un ve\u0301hicule dote\u0301 d\u2019un mate\u0301riel embarque\u0301, sans que le chauffeur ne doive s\u2019en soucier. La came\u0301ra infrarouge, place\u0301e dans le ve\u0301hicule, enregistre automatiquement les exc\u00e8s de vitesse (elle n\u2019e\u0301met pas de flash). Les voitures radars peuvent par ailleurs circuler sur tous types de routes, 7 jours sur 7 et 24h\/24.<\/p>\n<h2><span style=\"color: #64e61e\">Voitures radars prive\u0301es&nbsp;: quel bilan tirer des chiffres de la Se\u0301curite\u0301 routi\u00e8re&nbsp;?<\/span><\/h2>\n<p>En 2022, les professionnels du secteur automobile\/routier et les automobilistes ont pu avoir acc\u00e8s a\u0300 plusieurs donne\u0301es relatives a\u0300 l\u2019utilisation des voitures radars en France. D\u2019ordinaires peu communique\u0301es, ces statistiques nous permettent de tirer des premi\u00e8res conclusions quant a\u0300 l\u2019efficacite\u0301 du dispositif sur l\u2019anne\u0301e 2021.<\/p>\n<h3>Les principales donne\u0301es a\u0300 retenir<\/h3>\n<ul>\n<li>En 2021, le nombre de contr\u00f4les effectue\u0301s par des voitures radars privatise\u0301es a triple\u0301, passant de 758&nbsp;000 (premier trimestre) a\u0300 2&nbsp;886&nbsp;000 contr\u00f4les (dernier trimestre).<\/li>\n<li>6,65 millions de ve\u0301hicules se sont fait contr\u00f4ler par des voitures radars en 2021.<\/li>\n<li>Une voiture sur 15 a e\u0301te\u0301 releve\u0301e en exc\u00e8s de vitesse par les voitures radars privatise\u0301es, soit 7,5 % en moyenne, ce qui repre\u0301sente pr\u00e8s de 499&nbsp;000 infractions.<\/li>\n<li>Les contr\u00f4les effectue\u0301s en 2021 par les voitures passe\u0301es sous pilotage prive\u0301 repre\u0301sentent 38 % des infractions releve\u0301es par l\u2019ensemble des voitures radars (prive\u0301es comme publiques). En 2020, ils ne repre\u0301sentaient que 9 % des infractions.<\/li>\n<li>96 % des contr\u00f4les re\u0301alise\u0301s par des chauffeurs prive\u0301s ont eu lieu sur des routes appartenant au re\u0301seau secondaire bidirectionnel, soit des voies o\u00f9 la vitesse maximale autorise\u0301e est de 80 ou 90 kilom\u00e8tres\/heure.<\/li>\n<\/ul>\n<p>D\u2019importantes disparite\u0301s ont e\u0301te\u0301 observe\u0301es selon le type de route et les re\u0301gions.<\/p>\n<h3>Voiture radar publique VS voiture radar prive\u0301e&nbsp;: quel est le dispositif le plus efficace&nbsp;?<\/h3>\n<p>Si on se re\u0301f\u00e8re a\u0300 la part des infractions releve\u0301es en 2021 par les dispositifs prive\u0301s (part de 38 %), force est de constater que ces derniers ne sont pas plus efficaces que les voitures prises en charge par les forces de l\u2019ordre, alors qu\u2019elles circulent actuellement 4 a\u0300 5 fois moins (chaque jour) que les ve\u0301hicules privatise\u0301s.<\/p>\n<p style=\"text-align: center\"><a href=\"https:\/\/www.moncoyote.com\/fr\/service.html\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #64e61e\"><strong>De\u0301couvrez le service Coyote<\/strong><\/span><\/a><\/p>\n<p>L\u2019explication est a\u0300 trouver dans le mode ope\u0301ratoire privile\u0301gie\u0301 lors des contr\u00f4les&nbsp;: <strong>les voitures radars ont, jusqu\u2019a\u0300 ce jour, toujours re\u0301alise\u0301 de meilleures performances a\u0300 l\u2019arr\u00eat<\/strong>. Or, les ope\u0301rateurs de voitures privatise\u0301es ne sont pas habilite\u0301s a\u0300 effectuer ce type de contr\u00f4le.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le gouvernement utilise depuis 2018 des voitures radars ge\u0301re\u0301es par des socie\u0301te\u0301s prive\u0301es pour contr\u00f4ler et sanctionner les exc\u00e8s de [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":10861,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14,30],"tags":[],"class_list":["post-10859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-radars","category-securite-routiere"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/10859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=10859"}],"version-history":[{"count":0,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/10859\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/10861"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=10859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=10859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=10859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}