{"id":10965,"date":"2023-01-26T09:06:33","date_gmt":"2023-01-26T08:06:33","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=10965"},"modified":"2023-01-26T09:06:33","modified_gmt":"2023-01-26T08:06:33","slug":"here-elu-premier-service-de-cartographie-en-2023","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/actualites-coyote\/here-elu-premier-service-de-cartographie-en-2023\/","title":{"rendered":"Here, e\u0301lu premier service de cartographie en 2023"},"content":{"rendered":"<p>Utilise\u0301 par les solutions d\u2019aide a\u0300 la conduite Coyote, le service de cartographie Here a de\u0301croche\u0301 en 2023 la premi\u00e8re place du classement Counterpoint. Retour sur cette attribution ainsi que sur les performances des services Coyote et les avantages qu\u2019ils offrent aujourd\u2019hui aux automobilistes.<\/p>\n<h2><span style=\"color: #64e61e\">Des services de localisation toujours plus a\u0300 la pointe<\/span><\/h2>\n<p>Depuis quelques anne\u0301es,<strong> les services de localisation nume\u0301riques n\u2019ont eu de cesse de se perfectionner<\/strong>. Ayant fortement fait e\u0301voluer le domaine de l\u2019automobile et l\u2019expe\u0301rience des usagers de la route, les plateformes comme Coyote proposent de\u0301sormais des interfaces de programmation d\u2019itine\u0301raire et de navigation intelligentes capables de <strong>se\u0301curiser et simplifier les trajets des automobilistes<\/strong>. Trouver le meilleur itine\u0301raire est ainsi plus simple\u00a0!<\/p>\n<h3>2022, une anne\u0301e de\u0301cisive pour les plateformes de navigation<\/h3>\n<p><strong>Here Technologies<\/strong> (cre\u0301e\u0301 par Here Apps LLC) a obtenu cette anne\u0301e la premi\u00e8re place (devant TomTom et Google) du tr\u00e8s se\u0301rieux<strong> classement Counterpoin<\/strong>t, gr\u00e2ce a\u0300 son service de cartographie \u2013 utilise\u0301 par les solutions d<strong>\u2019<\/strong><span style=\"color: #64e61e\"><a style=\"color: #64e61e\" href=\"https:\/\/www.moncoyote.com\/fr\/service.html\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>aide a\u0300 la conduite Coyote<\/strong><\/a><\/span>.<\/p>\n<p>Analysant les offres de 35 fournisseurs, <strong>le classement prend en compte 7 crit\u00e8res<\/strong> particuli\u00e8rement pertinents pour e\u0301valuer la qualite\u0301 des plateformes\u00a0:<\/p>\n<ul>\n<li>services de localisation\u00a0;<\/li>\n<li>plateforme de donne\u0301es\u00a0;<\/li>\n<li>donne\u0301es cartographiques\u00a0;<\/li>\n<li>intelligences de localisation e\u0301cosyst\u00e8me de de\u0301veloppeurs\u00a0;<\/li>\n<li>croissances du fichier\u00a0;<\/li>\n<li>partenaires.<\/li>\n<\/ul>\n<h2><span style=\"color: #64e61e\">Here, un fournisseur de Coyote sur la premi\u00e8re place du podium<\/span><\/h2>\n<p>Cre\u0301e\u0301e au Pays-Bas, <strong>la plateforme Here<\/strong> a su se distinguer dans le classement Counterpoint gr\u00e2ce aux <strong>performances de son service de planification d\u2019itine\u0301raires et de cartographie en lign<\/strong>e. Une expertise qui lui avait de\u0301ja\u0300 permis de devenir le principal fournisseur de services cartographiques des solutions de localisation et navigation Coyote.<\/p>\n<h3>Un partenariat avantageux pour les utilisateurs de Coyote<\/h3>\n<p>Fort de son expertise et de ses nombreux partenariats noue\u0301s avec des acteurs de re\u0301fe\u0301rence sur le marche\u0301, Coyote propose aux automobilistes des services toujours plus performants. Les utilisateurs de l\u2019<strong><span style=\"color: #64e61e\"><a style=\"color: #64e61e\" href=\"https:\/\/www.moncoyote.com\/fr\/product\/581\/app-coyote.html\" target=\"_blank\" rel=\"noopener noreferrer\">application Coyote<\/a><\/span><\/strong> <strong>et du bo\u00eetier connecte\u0301 NAV +<\/strong> ont notamment l\u2019opportunite\u0301 d\u2019\u00eatre assiste\u0301s par le logiciel de cartographie re\u0301compense\u0301 par le classement Counterpoint, et par un <strong>service de navigation GPS a\u0300 commande vocale<\/strong> pouvant \u00eatre utilise\u0301 dans toute l\u2019Europe.<\/p>\n<h3>L\u2019expertise Coyote au service des automobilistes<\/h3>\n<p>Coyote permet aujourd\u2019hui de be\u0301ne\u0301ficier d\u2019une application tout-en-un (alertes, trafic et navigation) proposant des services souvent ine\u0301dits sur le marche\u0301\u00a0:<\/p>\n<ul>\n<li>indication en temps re\u0301el de l\u2019itine\u0301raire optimal avec re-calcul automatique de l\u2019itine\u0301raire\u00a0;<\/li>\n<li>pre\u0301vision actualise\u0301e des incidents de la route sur 30 kilom\u00e8tres (syst\u00e8me d\u2019alertes personnalise\u0301es effectif dans toute l\u2019Europe)\u00a0;<\/li>\n<li>indication de vitesse et alerte en cas de vitesse excessive&#8230;<\/li>\n<\/ul>\n<p>En plus de l\u2019application, Coyote propose aux automobilistes plusieurs autres supports tout aussi performants tels que <span style=\"color: #64e61e\"><strong><a style=\"color: #64e61e\" href=\"https:\/\/www.moncoyote.com\/fr\/products-fr.html\">les bo\u00eetiers GPS connecte\u0301s<\/a><\/strong><\/span> ou les solutions embarque\u0301es (application pre\u0301installe\u0301e dans le ve\u0301hicule via son e\u0301cran inte\u0301gre\u0301). Ces solutions permettent a\u0300 leurs utilisateurs de pouvoir utiliser les m\u00eames services de localisation que l\u2019application, en profitant notamment du <strong>syst\u00e8me d\u2019alertes en temps re\u0301el de\u0301veloppe\u0301 par Coyot<\/strong>e.<\/p>\n<p>Pionner et leader fran\u00e7ais des solutions d\u2019aide a\u0300 la conduite, <strong>Coyote a e\u0301galement le privil\u00e8ge de posse\u0301der ses propres algorithmes<\/strong> prote\u0301ge\u0301s par 13 brevets europe\u0301ens. Cette technologie unique, qui re\u0301pond aux exigences de la norme NF, permet aux bo\u00eetiers GPS comme a\u0300 l\u2019appli Coyote d\u2019<strong>analyser et de filtrer toutes les alertes<\/strong> recueillies par le syst\u00e8me.<\/p>\n<p>Les outils de navigation Coyote sont chaque jour enrichis par les milliers de donne\u0301es provenant de sa communaute\u0301, forte <strong>5 millions de membres<\/strong>. Un fonctionnement qui donne aux automobilistes la possibilite\u0301 d\u2019\u00eatre alerte\u0301s a\u0300 tout moment sur les dangers se trouvant sur leur route (zones de radars, zones de dangers, perturbations&#8230;).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Utilise\u0301 par les solutions d\u2019aide a\u0300 la conduite Coyote, le service de cartographie Here a de\u0301croche\u0301 en 2023 la premi\u00e8re [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":10969,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[22,28],"tags":[],"class_list":["post-10965","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-coyote","category-coyote"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/10965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=10965"}],"version-history":[{"count":0,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/10965\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/10969"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=10965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=10965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=10965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}