<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Warning</b>:  Cannot modify header information - headers already sent by (output started at /var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php:129) in <b>/var/www/html/web/wp/wp-includes/rest-api/class-wp-rest-server.php</b> on line <b>1896</b><br />
<br />
<b>Warning</b>:  Cannot modify header information - headers already sent by (output started at /var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php:129) in <b>/var/www/html/web/wp/wp-includes/rest-api/class-wp-rest-server.php</b> on line <b>1896</b><br />
{"id":11173,"date":"2023-03-16T07:00:11","date_gmt":"2023-03-16T06:00:11","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=11173"},"modified":"2023-03-16T07:00:11","modified_gmt":"2023-03-16T06:00:11","slug":"lobservatoire-des-vols-2023","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/vol-tracking\/lobservatoire-des-vols-2023\/","title":{"rendered":"L&rsquo;observatoire des vols 2023"},"content":{"rendered":"\n<p>Comme chaque anne\u0301e depuis 2017, COYOTE publie son Observatoire des vols, base\u0301 sur l\u2019activite\u0301 2022 de <strong>Coyote Secure<\/strong>, son service de re\u0301cupe\u0301ration de ve\u0301hicules vole\u0301s dont 400 000 ve\u0301hicules sont e\u0301quipe\u0301s en France et en Belgique, en comple\u0301ment des donne\u0301es officielles du minist\u00e8re de l\u2019Inte\u0301rieur.<br>Pour la premi\u00e8re fois depuis plus d\u2019une de\u0301cennie, le vol de ve\u0301hicules est en tr\u00e8s nette augmentation sur l\u2019anne\u0301e 2022. Les fili\u00e8res se sont montre\u0301es tr\u00e8s actives l\u2019an dernier en France, portant le nombre de vols de ve\u0301hicules a\u0300 <strong>133 800 en 2022, en hausse de 9%<\/strong>, soit <strong>1 vol de ve\u0301hicule toutes les 4 minutes sur l\u2019ensemble du territoire fran\u00e7ais<\/strong>.<br>En France, pr\u00e8s de 60% des ve\u0301hicules vole\u0301s ne sont jamais retrouve\u0301s. <strong>91% des ve\u0301hicules vole\u0301s e\u0301quipe\u0301s de la solution Coyote Secure sont re\u0301cupe\u0301re\u0301s en 48h<\/strong>. Et dans 93% des cas, les ve\u0301hicules re\u0301cupe\u0301re\u0301s sont restitue\u0301s a\u0300 leurs proprie\u0301taires avec peu ou pas de de\u0301gradation. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Les chiffres cle\u0301s au niveau national<\/h3>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"625\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2023\/03\/Observatoire-des-vols-chiffres-cles-au-niveau-national-1024x625.jpg\" alt=\"\" class=\"wp-image-11183\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-chiffres-cles-au-niveau-national-1024x625.jpg 1024w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-chiffres-cles-au-niveau-national-300x183.jpg 300w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-chiffres-cles-au-niveau-national-768x469.jpg 768w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-chiffres-cles-au-niveau-national-1536x937.jpg 1536w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-chiffres-cles-au-niveau-national-1568x957.jpg 1568w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-chiffres-cles-au-niveau-national.jpg 1663w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Les chiffres cle\u0301s de l\u2019Observatoire des vols Coyote Secure 2023<\/h3>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Top-region.jpg\" alt=\"\" class=\"wp-image-11187\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Top-region.jpg 800w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Top-region-300x167.jpg 300w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Top-region-768x427.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"457\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-chiffres-cles.jpg\" alt=\"\" class=\"wp-image-11189\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-chiffres-cles.jpg 800w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-chiffres-cles-300x171.jpg 300w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-chiffres-cles-768x439.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Des fili\u00e8res toujours plus actives sur le vol de ve\u0301hicules en 2022<\/h4>\n\n\n\n<p>Les services de police et du minist\u00e8re de l\u2019Inte\u0301rieur ont enregistre\u0301 <strong>133 800 vols de ve\u0301hicules en 2022<\/strong> en France, soit environ <strong>1 vol toutes les 4 minutes<\/strong>. Ce chiffre est en tr\u00e8s nette hausse par rapport a\u0300 2021 (+9%). Parmi ces vols, <strong>la part des ve\u0301hicules particuliers (c\u2019est-a\u0300-dire les voitures) est estime\u0301e a\u0300 70%<\/strong>. Le reste e\u0301tant principalement des deux roues, des utilitaires et des ve\u0301hicules professionnels.<br>L\u2019activite\u0301 des fili\u00e8res tr\u00e8s organise\u0301es qui op\u00e8rent sur le vol de ve\u0301hicules s\u2019est acce\u0301le\u0301re\u0301e au cours du deuxi\u00e8me trimestre. Le constat est similaire sur l\u2019activite\u0301 des de\u0301tectives Coyote Secure, qui ont enregistre\u0301 <strong>un premier pic au mois de juin<\/strong>, suivi d\u2019un second au mois de septembre, pour ensuite se stabiliser sur le dernier trimestre.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Re\u0301partition des vols par mois sur le parc e\u0301quipe\u0301 Coyote Secure en 2022<\/h4>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Repartition-des-vols-par-mois-sur-le-parc-equipe-Coyote-Secure-en-2022.jpg\" alt=\"\" class=\"wp-image-11191\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Repartition-des-vols-par-mois-sur-le-parc-equipe-Coyote-Secure-en-2022.jpg 800w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Repartition-des-vols-par-mois-sur-le-parc-equipe-Coyote-Secure-en-2022-300x150.jpg 300w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Repartition-des-vols-par-mois-sur-le-parc-equipe-Coyote-Secure-en-2022-768x384.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"319\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-En2022-1-vol-de-vechicule-toutes-les-4-minutes.jpg\" alt=\"\" class=\"wp-image-11193\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-En2022-1-vol-de-vechicule-toutes-les-4-minutes.jpg 800w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-En2022-1-vol-de-vechicule-toutes-les-4-minutes-300x120.jpg 300w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-En2022-1-vol-de-vechicule-toutes-les-4-minutes-768x306.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">La sinistralite\u0301 en re\u0301gion : personne n\u2019est e\u0301pargne\u0301 face au risque croissant de vol<\/h4>\n\n\n\n<p><strong>Le nombre de vols est en augmentation pour l\u2019inte\u0301gralite\u0301 des re\u0301gions de France me\u0301tropolitaine.<\/strong> Les re\u0301gions les plus touche\u0301es par le vol enregistrent une hausse du nombre de vols sur l\u2019anne\u0301e 2022 avec <strong>+12% en Provence Alpes C\u00f4te d\u2019Azur,<\/strong> <strong>+11% en Auvergne-Rh\u00f4ne-Alpes et +4% en Ile-de-France<\/strong>. A elles seules, ces 3 re\u0301gions p\u00e8sent pour 52% des vols recense\u0301s en France l\u2019an dernier.<br>Nouveaute\u0301 en 2022,<strong> les re\u0301gions historiquement les moins touche\u0301es enregistrent, elles aussi, des hausses importantes<\/strong> du nombre de vols : +29% en Bretagne, +21% en Centre Val de Loire, +14% en Bourgogne-Franche-Comte\u0301.<\/p>\n\n\n\n<p>\u00ab <em>Le risque de vol se mate\u0301rialise par un taux de sinistralite\u0301, c\u2019est a\u0300 dire le nombre de ve\u0301hicules vole\u0301s pour 1000 ve\u0301hicules e\u0301quipe\u0301s de la solution Coyote Secure <\/em>\u00bb, pre\u0301cise Ste\u0301phane CURTELIN, Directeur Marketing et Produits chez Coyote.<\/p>\n\n\n\n<p><strong>L\u2019\u00cele-de-France est comme chaque anne\u0301e la re\u0301gion qui enregistre a\u0300 la fois le plus grand nombre de vols et le taux de sinistralite\u0301 le plus important a\u0300 5,9\/1000.<\/strong><br>Vient ensuite la re\u0301gion Provence-Alpes-C\u00f4te d\u2019Azur avec un taux de sinistralite\u0301 de 4,2\/1000 (en augmentation de 2,4% par rapport a\u0300 2021).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Les 5 re\u0301gions les plus sinistre\u0301es de France<\/h4>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"446\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-5-regions-les-plus-sinitrees-en-France-1.jpg\" alt=\"\" class=\"wp-image-11197\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-5-regions-les-plus-sinitrees-en-France-1.jpg 800w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-5-regions-les-plus-sinitrees-en-France-1-300x167.jpg 300w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-5-regions-les-plus-sinitrees-en-France-1-768x428.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Sur l\u2019anne\u0301e 2022, <strong>c\u2019est en Auvergne-Rh\u00f4ne-Alpes que la hausse du taux<br>de sinistralite\u0301 est la plus significative (+26,1%), avec un volume important de ve\u0301hicules vole\u0301s dans la re\u0301gion.<\/strong><br><\/p>\n\n\n\n<figure class=\"wp-block-gallery alignright has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"595\" data-id=\"11199\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-zoom-auvergne-rhone-alpes.jpg\" alt=\"\" class=\"wp-image-11199\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-zoom-auvergne-rhone-alpes.jpg 800w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-zoom-auvergne-rhone-alpes-300x223.jpg 300w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-zoom-auvergne-rhone-alpes-768x571.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>L\u2019Auvergne-Rh\u00f4ne-Alpes se positionne ainsi comme la troisi\u00e8me re\u0301gion la plus sinistre\u0301e de France (2,9\/1000), devant les Hauts-de-France (2,8\/1000) et les Pays de la Loire (2,7\/1000), o\u00f9 le risque de vol reste important.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"187\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Stephane-Curtelin.jpg\" alt=\"\" class=\"wp-image-11201\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Stephane-Curtelin.jpg 800w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Stephane-Curtelin-300x70.jpg 300w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Stephane-Curtelin-768x180.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-400000vehiculesequipesdesolutioncoyotesecure.jpg\" alt=\"\" class=\"wp-image-11249\" width=\"370\" height=\"129\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-400000vehiculesequipesdesolutioncoyotesecure.jpg 800w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-400000vehiculesequipesdesolutioncoyotesecure-300x105.jpg 300w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-400000vehiculesequipesdesolutioncoyotesecure-768x268.jpg 768w\" sizes=\"auto, (max-width: 370px) 100vw, 370px\" \/><\/figure><\/div>\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"805\" height=\"374\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2023\/03\/Coyote-Secure.png\" alt=\"\" class=\"wp-image-11205\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Coyote-Secure.png 805w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Coyote-Secure-300x139.png 300w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Coyote-Secure-768x357.png 768w\" sizes=\"auto, (max-width: 805px) 100vw, 805px\" \/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Hausse de la sinistralite\u0301 des ve\u0301hicules hybrides, les SUV, toujours aussi prise\u0301s<\/h4>\n\n\n\n<p>La grande majorite\u0301 des vols en 2022, concerne des ve\u0301hicules quatre roues et notamment des voitures particuli\u00e8res.<br><strong>67% des vols de voitures concernent des mod\u00e8les SUV du fait de leur grand succ\u00e8s commercial et donc du potentiel que ces ve\u0301hicules repre\u0301sentent a\u0300 la revente ou a\u0300 l\u2019export.<\/strong> Le taux de sinistralite\u0301 des SUV reste e\u0301leve\u0301 a\u0300 3,2\/1000, un chiffre stable par rapport a\u0300 2021.<br><strong>La hausse la plus significative sur un an concerne les mod\u00e8les hybrides, dont le risque de vol augmente de plus de 40% en 2022 pour atteindre 3,3\/1000.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"303\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Classement-modele-les-plus-volesjpg.jpg\" alt=\"\" class=\"wp-image-11207\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Classement-modele-les-plus-volesjpg.jpg 800w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Classement-modele-les-plus-volesjpg-300x114.jpg 300w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Classement-modele-les-plus-volesjpg-768x291.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"263\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-SUV-et-hyrbides.jpg\" alt=\"\" class=\"wp-image-11209\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-SUV-et-hyrbides.jpg 800w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-SUV-et-hyrbides-300x99.jpg 300w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-SUV-et-hyrbides-768x252.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Stephane-Curtelin-2.jpg\" alt=\"\" class=\"wp-image-11211\" width=\"595\" height=\"154\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Stephane-Curtelin-2.jpg 800w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Stephane-Curtelin-2-300x78.jpg 300w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Stephane-Curtelin-2-768x200.jpg 768w\" sizes=\"auto, (max-width: 595px) 100vw, 595px\" \/><\/figure>\n\n\n\n<p>Les ve\u0301hicules dits professionnels pre\u0301sentent toujours un risque plus important face au vol que les ve\u0301hicules particuliers, de par leur tr\u00e8s forte valeur marchande. <strong>Les ve\u0301hicules d\u2019entreprise et les ve\u0301hicules utilitaires pre\u0301sentent un risque de vol quasiment 2x plus grand que les ve\u0301hicules particuliers. <\/strong>Par ailleurs, <strong>le risque de vol est toujours excessivement important sur les deux-roues (45\/1000) et sur les engins de chantier<\/strong> qui voit leur taux de sinistralite\u0301 encore progresser de 13% pour atteindre 26\/1000.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"449\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Vol-deux-roues.jpg\" alt=\"\" class=\"wp-image-11213\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Vol-deux-roues.jpg 800w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Vol-deux-roues-300x168.jpg 300w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Vol-deux-roues-768x431.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"431\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Vol-vehicules-pro.jpg\" alt=\"\" class=\"wp-image-11217\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Vol-vehicules-pro.jpg 800w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Vol-vehicules-pro-300x162.jpg 300w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Vol-vehicules-pro-768x414.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Que deviennent les ve\u0301hicules vole\u0301s ?<\/h4>\n\n\n\n<p>M\u00eame s\u2019il semble assez simple de voler un ve\u0301hicule en quelques minutes seulement, notamment gr\u00e2ce aux outils technologiques, les fili\u00e8res professionnalise\u0301es les plus actives ont des spe\u0301cialite\u0301s identifie\u0301es. En 2022, pr\u00e8s de 9 ve\u0301hicules sur 10 ont e\u0301te\u0301 de\u0301robe\u0301s gr\u00e2ce a\u0300 la technologie ou par voie e\u0301lectronique, sans laisser de trace et donc la plupart du temps sans causer de de\u0301gradation au ve\u0301hicule.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Vol-electronique.jpg\" alt=\"\" class=\"wp-image-11221\" width=\"271\" height=\"266\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Vol-electronique.jpg 763w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Vol-electronique-300x295.jpg 300w\" sizes=\"auto, (max-width: 271px) 100vw, 271px\" \/><\/figure><\/div>\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"207\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Stephane-Curtelin-3.jpg\" alt=\"\" class=\"wp-image-11223\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Stephane-Curtelin-3.jpg 800w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Stephane-Curtelin-3-300x78.jpg 300w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Stephane-Curtelin-3-768x199.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>En 2022, on estime que les ve\u0301hicules vole\u0301s qui ne sont pas e\u0301quipe\u0301s de solution de re\u0301cupe\u0301ration apr\u00e8s-vol sont dans plus de 60% des cas jamais retrouve\u0301s. Ces ve\u0301hicules sont exploite\u0301s diffe\u0301remment par les fili\u00e8res :<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"79\" height=\"79\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2023\/03\/Lexport-de-vehicules-voles.png\" alt=\"\" class=\"wp-image-11239\" \/><\/figure><\/div>\n\n\n<p><strong>L\u2019export de ve\u0301hicules vole\u0301s vers l\u2019e\u0301tranger<\/strong><\/p>\n\n\n\n<p>Tr\u00e8s prise\u0301 par les fili\u00e8res d\u2019Afrique de l\u2019Ouest et d\u2019Afrique du Nord, cela concerne e\u0301galement d\u2019autres territoires comme les pays baltes et certains pays d\u2019Europe de l\u2019Est. Les e\u0301quipes travaillent a\u0300 la commande et la revente des ve\u0301hicules est facilite\u0301e par la possibilite\u0301 d\u2019une reconfiguration e\u0301lectronique des ve\u0301hicules.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"79\" height=\"79\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2023\/03\/La-revente-de-piece-detaches-1.png\" alt=\"\" class=\"wp-image-11241\" \/><\/figure><\/div>\n\n\n<p><strong>La revente de pi\u00e8ces de\u0301tache\u0301es<\/strong><\/p>\n\n\n\n<p>Permet d\u2019alimenter un large marche\u0301 noir a\u0300 l\u2019e\u0301tranger ou sur le web. Parmi  les pi\u00e8ces prise\u0301es des malfaiteurs, les pots catalytiques sont de\u0301robe\u0301s pour<br> le rhodium qu\u2019ils contiennent, une spe\u0301cialite\u0301 des fili\u00e8res de l\u2019Est.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"79\" height=\"79\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2023\/03\/Le-blanchiment-des-vehicules.png\" alt=\"\" class=\"wp-image-11243\" \/><\/figure><\/div>\n\n\n<p><strong>Le blanchiment des ve\u0301hicules<\/strong><\/p>\n\n\n\n<p>Par le biais de diffe\u0301rents moyens comme la cre\u0301ation frauduleuse de<br> nume\u0301ro de ch\u00e2ssis, ou la production de documents vole\u0301s ou falsifie\u0301s qui<br> permettent avec ou sans maquillage de remettre un ve\u0301hicule vole\u0301 en circulation sur le territoire.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"79\" height=\"79\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2023\/03\/Grand-banditisme.png\" alt=\"\" class=\"wp-image-11245\" \/><\/figure><\/div>\n\n\n<p>Le vol de ve\u0301hicule peut e\u0301galement permettre d\u2019alimenter des zones de guerre (Afrique, Moyen-Orient) ou encore le grand banditisme pour la re\u0301alisation de braquages ou de go fasts.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Dans 43%, soit pr\u00e8s d\u2019un cas sur deux, les ve\u0301hicules vole\u0301s sont dissimule\u0301s<\/strong> en attendant la destination finale, parfois plusieurs jours, <strong>soit a\u0300 couvert dans des ve\u0301hicules, des boxes ou des conteneurs, mais aussi dans des caves ou des sous-sols.<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-43-des-vehicules-sont-dissimules-a-couvert-ou-en-sous-sol.jpg\" alt=\"\" class=\"wp-image-11229\" width=\"295\" height=\"284\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-43-des-vehicules-sont-dissimules-a-couvert-ou-en-sous-sol.jpg 720w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-43-des-vehicules-sont-dissimules-a-couvert-ou-en-sous-sol-300x290.jpg 300w\" sizes=\"auto, (max-width: 295px) 100vw, 295px\" \/><\/figure><\/div>\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"284\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Stephane-Curtelin-4-1.jpg\" alt=\"\" class=\"wp-image-11227\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Stephane-Curtelin-4-1.jpg 800w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Stephane-Curtelin-4-1-300x107.jpg 300w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/Observatoire-des-vols-Coyote-Secure-Stephane-Curtelin-4-1-768x273.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Coyote Secure, la re\u0301fe\u0301rence de la re\u0301cupe\u0301ration apr\u00e8s-vol<\/h4>\n\n\n\n<p>La solution Coyote Secure repose sur un traceur autonome be\u0301ne\u0301ficiant de la <strong>technologie brevete\u0301e Traqueur<\/strong>\u00ae et re\u0301sistant aux brouillages, dissimule\u0301 par un professionnel dans le ve\u0301hicule. Cette technologie ultra-performante base\u0301e sur des re\u0301seaux IoT (Sigfox, LoRaWAN et LTE-M) qui ont la proprie\u0301te\u0301 d\u2019\u00eatre e\u0301conomes en e\u0301nergie, est associe\u0301e a\u0300 <strong>une e\u0301quipe de de\u0301tectives de\u0301die\u0301s en alerte 24h\/24, 7j\/7<\/strong>, qui re\u0301cup\u00e8rent les ve\u0301hicules vole\u0301s sur le terrain, <strong>partout en Europe, en partenariat avec les forces de l\u2019ordre<\/strong>. Bien plus qu\u2019un antivol ou qu\u2019un syst\u00e8me de ge\u0301olocalisation, le mod\u00e8le unique de cette solution efficace pour tout type de ve\u0301hicules, permet de retrouver les ve\u0301hicules vole\u0301s m\u00eame enfouis en sous-sol ou en zone blanche : <strong>91% des ve\u0301hicules vole\u0301s sont re\u0301cupe\u0301re\u0301s dans les 48 heures apr\u00e8s la de\u0301claration du vol<\/strong>*.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"805\" height=\"294\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2023\/03\/il-y-a-plus-simple-contre-le-vol-Coyote-Secure.png\" alt=\"\" class=\"wp-image-11179\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/il-y-a-plus-simple-contre-le-vol-Coyote-Secure.png 805w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/il-y-a-plus-simple-contre-le-vol-Coyote-Secure-300x110.png 300w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2023\/03\/il-y-a-plus-simple-contre-le-vol-Coyote-Secure-768x280.png 768w\" sizes=\"auto, (max-width: 805px) 100vw, 805px\" \/><\/figure>\n\n\n\n<p><em>*Donne\u0301es Coyote du 1er ao\u00fbt au 15 de\u0301cembre 2020<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comme chaque anne\u0301e depuis 2017, COYOTE publie son Observatoire des vols, base\u0301 sur l\u2019activite\u0301 2022 de Coyote Secure, son service [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":11235,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[22,28,8],"tags":[],"class_list":["post-11173","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-coyote","category-coyote","category-vol-tracking"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/11173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=11173"}],"version-history":[{"count":0,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/11173\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/11235"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=11173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=11173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=11173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}