{"id":11385,"date":"2023-04-14T09:58:20","date_gmt":"2023-04-14T07:58:20","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=11385"},"modified":"2023-04-14T09:58:20","modified_gmt":"2023-04-14T07:58:20","slug":"zoom-sur-les-nouveaux-radars-de-covoiturage","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/radars\/zoom-sur-les-nouveaux-radars-de-covoiturage\/","title":{"rendered":"Zoom sur les nouveaux radars de covoiturage"},"content":{"rendered":"\n<p>Nombre\nd\u2019entre vous se demandent sans doute&nbsp;: quoi&nbsp;? Un radar de\ncovoiturage&nbsp;? Mais qu\u2019est-ce que c\u2019est encore&nbsp;que cette\nhistoire&nbsp;? Cela n\u2019a pourtant rien d\u2019une (mauvaise) blague&nbsp;: de\nnouveaux radars sont actuellement en phase d\u2019expe\u0301rimentation dans plusieurs\nvilles de France. Leur mission&nbsp;? De\u0301tecter les fraudes des automobilistes\nsur les voies re\u0301serve\u0301es au covoiturage. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color: #64e61e\">Radar de covoiturage&nbsp;: en quoi consiste le dispositif&nbsp;?<\/span><\/h2>\n\n\n\n<p>Si de nombreux automobilistes n\u2019en ont encore jamais entendu parler,\nles radars de covoiturage ne sont pas si nouveaux que cela. Pense\u0301 depuis 2020, c\u2019est\nsur l\u2019autoroute A48 que l\u2019on retrouve un premier dispositif de ce type a\u0300\nproximite\u0301 de Grenoble (Is\u00e8re). L\u2019installation de ce nouveau radar fait alors\nsuite a\u0300 la cre\u0301ation, sur l\u2019autoroute, d\u2019une voie de 8 kilom\u00e8tres re\u0301serve\u0301e aux\nvoitures faisant du covoiturage. &nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Comment fonctionne la voie de\u0301die\u0301e au covoiturage&nbsp;? <\/strong><\/h3>\n\n\n\n<p>L\u2019objectif de la voie spe\u0301ciale covoiturage est de de\u0301sengorger le trafic\nroutier, et d\u2019encourager l\u2019utilisation des modes de transport plus\n\u00ab&nbsp;e\u0301cologiques&nbsp;\u00bb comme l\u2019autopartage. Son principe de fonctionnement\nest simple&nbsp;: pendant les heures de pointe, la voie de gauche de\nl\u2019autoroute devient une voie exclusivement re\u0301serve\u0301e aux \u00ab&nbsp;covoitureurs&nbsp;\u00bb&nbsp;;\npour avertir les automobilistes, la voie est alors de\u0301limite\u0301e par un panneau\nlumineux (un losange blanc sur fond noir). <\/p>\n\n\n\n<p>Durant cette pe\u0301riode, seules les voitures qui font du covoiturage, les\ntaxis et les ve\u0301hicules a\u0300 tr\u00e8s faible e\u0301mission (dote\u0301s de la vignette Crit\u2019Air 0)\npeuvent emprunter la voie spe\u0301ciale. Le reste de la journe\u0301e, la voie est\nutilise\u0301e normalement par les automobilistes. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Le radar comme solution de contr\u00f4le<\/strong><\/h3>\n\n\n\n<p>Mais un probl\u00e8me se pose&nbsp;: comment ve\u0301rifier que les voitures situe\u0301es\nsur la voie font bien du covoiturage&nbsp;? Pour ne pas trop compliquer la\nchose, le gouvernement a de\u0301cide\u0301 que tous les ve\u0301hicules posse\u0301dant a\u0300 bord au\nmoins deux occupants doivent \u00eatre conside\u0301re\u0301s comme des voitures de covoiturage\n(et peuvent donc circuler sur la voie spe\u0301ciale). C\u2019est ici que les radars\ninterviennent&nbsp;: ces dispositifs ont la mission de contr\u00f4ler le nombre de\npersonnes pre\u0301sentes dans les voitures situe\u0301es sur la voie de covoiturage&nbsp;;\net, bien s\u00fbr, de sanctionner les automobilistes en cas de fraude. <\/p>\n\n\n\n<p>Vous souhaitez rouler en toute se\u0301re\u0301nite\u0301&nbsp;? &nbsp;Gr\u00e2ce a\u0300 l\u2019<a href=\"https:\/\/www.moncoyote.com\/fr\/product\/581\/App-Coyote.html\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (opens in a new tab)\">application GPS Coyote<\/a>, vous \u00eates alerte\u0301 en temps re\u0301el sur la pre\u0301sence des dangers et des radars situe\u0301s sur votre itine\u0301raire&nbsp;!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"color: #64e61e\">Comment fonctionnent les nouveaux radars de covoiturage&nbsp;?<\/span><\/h2>\n\n\n\n<p>Les radars de covoiturage sont capables de de\u0301tecter la pre\u0301sence d\u2019une\npersonne (ou d\u2019un objet) via des came\u0301ras thermiques. Equipe\u0301es de capteurs, ces\ncame\u0301ras de\u0301tectent le rayonnement infrarouge e\u0301mis par la personne&nbsp;; elles peuvent\nainsi de\u0301terminer le nombre d\u2019occupants pre\u0301sents dans l\u2019habitacle. Lorsque le radar\nper\u00e7oit une fraude (soit quand une voiture avec un seul occupant a\u0300 bord circule\nsur une voie de covoiturage), il peut alors flasher la plaque d\u2019immatriculation\nde la voiture. Si l\u2019infraction est ve\u0301rifie\u0301e, l\u2019automobiliste s\u2019expose a\u0300 une\namende de 135 euros. <\/p>\n\n\n\n<p>Attention toutefois&nbsp;: le syst\u00e8me de flash automatique du ve\u0301hicule\nn\u2019a pas encore e\u0301te\u0301 expe\u0301rimente\u0301 en situation re\u0301elle. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Radars de covoiturage&nbsp;: o\u00f9 sont-ils installe\u0301s&nbsp;? <\/strong><\/h3>\n\n\n\n<p>Plusieurs radars de covoiturage sont aujourd\u2019hui installe\u0301s sur les routes fran\u00e7aises. On en compte notamment a\u0300 Lyon, Grenoble et <a href=\"https:\/\/www.moncoyote.com\/blog\/securite-routiere\/radars\/paris-bientot-la-mise-en-place-de-radars-de-covoiturage\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (opens in a new tab)\">Paris<\/a>. Pour la plupart, il s\u2019agit encore de dispositifs en phase de test, qui ne donnent pas lieu a\u0300 des sanctions. Dans l\u2019agglome\u0301ration de Lyon, toutefois, le dispositif n\u2019est plus uniquement \u00ab&nbsp;pe\u0301dagogique&nbsp;\u00bb&nbsp;: les automobilistes qui circulent sur la voie de covoiturage sans y \u00eatre autorise\u0301s sont d\u2019ores et de\u0301ja\u0300 verbalise\u0301s. Pour l\u2019instant, les PV sont dresse\u0301s apr\u00e8s interpellation des forces de l\u2019ordre. Mais des contr\u00f4les automatiques avec sanction ne sont pas a\u0300 exclure prochainement, la loi LOM (Orientation des Mobilite\u0301s) autorisant de\u0301sormais l\u2019utilisation a\u0300 cet effet des dispositifs fixes\/mobiles de contr\u00f4le automatise\u0301. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nombre d\u2019entre vous se demandent sans doute&nbsp;: quoi&nbsp;? Un radar de covoiturage&nbsp;? Mais qu\u2019est-ce que c\u2019est encore&nbsp;que cette histoire&nbsp;? Cela [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":11387,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-11385","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-radars"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/11385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=11385"}],"version-history":[{"count":0,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/11385\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/11387"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=11385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=11385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=11385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}