{"id":12823,"date":"2023-11-06T12:15:00","date_gmt":"2023-11-06T11:15:00","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=12823"},"modified":"2023-11-06T12:15:00","modified_gmt":"2023-11-06T11:15:00","slug":"protection-des-donnees-personnelles-comment-les-voitures-connectees-espionnent-votre-vie-privee","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/automobile\/protection-des-donnees-personnelles-comment-les-voitures-connectees-espionnent-votre-vie-privee\/","title":{"rendered":"Protection des donne\u0301es personnelles\u00a0: Comment les voitures connecte\u0301es espionnent votre vie prive\u0301e\u00a0?"},"content":{"rendered":"\n<p>De plus en plus nombreux, les objets connecte\u0301s ont la capacite\u0301 de collecter nos donne\u0301es personnelles et de les transmettre a\u0300 des serveurs informatiques partout dans le monde. Mais saviez-vous que les voitures connecte\u0301es sont aujourd\u2019hui conside\u0301re\u0301es comme \u00ab&nbsp;le pire produit teste\u0301&nbsp;\u00bb en mati\u00e8re de protection des donne\u0301es personnelles par une re\u0301cente e\u0301tude ame\u0301ricaine&nbsp;? Coyote fait le point.<\/p>\n\n\n\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#64e61e\"><strong>Les voitures connecte\u0301es, un \u00ab&nbsp;cauchemar&nbsp;\u00bb pour la protection de vos donne\u0301es personnelles<\/strong><\/h2>\n\n\n\n<p>Les voitures connecte\u0301es facilitent aujourd\u2019hui la conduite des automobilistes a\u0300 bien des e\u0301gards. En constante ame\u0301lioration, leur syst\u00e8me va sans doute continuer a\u0300 ame\u0301liorer le confort des conducteurs, tout en &nbsp;jouant <a href=\"https:\/\/www.moncoyote.com\/blog\/automobile\/batteries-lenjeu-ecologique-pour-les-voitures-electriques\/\" target=\"_blank\" rel=\"noreferrer noopener\">un enjeu e\u0301cologique<\/a> et en renfor\u00e7ant leur se\u0301curite\u0301 au volant. Mais un point vient passablement noircir le tableau&nbsp;: une e\u0301tude mene\u0301e par la fondation Mozilla, affirme que les voitures connecte\u0301es actuelles seraient un ve\u0301ritable \u00ab&nbsp;cauchemar&nbsp;\u00bb pour la protection des donne\u0301es personnelles de leurs usagers.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Des donne\u0301es personnelles collecte\u0301es et vendues<\/strong><\/h3>\n\n\n\n<p>Mene\u0301e par la tr\u00e8s se\u0301rieuse fondation californienne Mozilla (association a\u0300 but non lucratif), l\u2019e\u0301tude s\u2019est penche\u0301e sur le fonctionnement des voitures connecte\u0301es fabrique\u0301es par les 25 marques les plus populaires du marche\u0301. Son objectif&nbsp;: ve\u0301rifier le respect des normes de confidentialite\u0301 les plus e\u0301le\u0301mentaires en mati\u00e8re de donne\u0301es personnelles. Et le constat est clair&nbsp;: selon Mozilla, tous les constructeurs dont les mod\u00e8les ont e\u0301te\u0301 pris en compte par l\u2019e\u0301tude (BMW, Mercedes-Benz, Renault, Nissan, Volkswagen ou Dacia) \u00ab&nbsp;collectent davantage de donne\u0301es que ne\u0301cessaire&nbsp;\u00bb et les utilisent a\u0300 des \u00ab&nbsp;fins autres que l\u2019utilisation du ve\u0301hicule et la gestion de la relation avec le conducteur&nbsp;\u00bb.<\/p>\n\n\n\n<p>Parue en septembre dernier (2023), l\u2019e\u0301tude affirme m\u00eame que \u00ab&nbsp;les voitures sont le pire produit teste\u0301 pour la protection des donne\u0301es personnelles&nbsp;\u00bb &#8211; Mozilla avait de\u0301ja\u0300 analyse\u0301 le fonctionnement des montres, enceintes connecte\u0301es, smartphones et applications de me\u0301ditation.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quelles sont les donne\u0301es personnelles collecte\u0301es ?<\/strong><\/h3>\n\n\n\n<p>Selon la fondation, les voitures connecte\u0301es seraient actuellement capables de collecter de tr\u00e8s nombreuses informations personnelles, dont certaines tr\u00e8s intimes&nbsp;: vitesse de conduite, pre\u0301fe\u0301rences musicales, appartenance ethnique, informations me\u0301dicales, croyances religieuses et politiques\u2026 Pour collecter ces donne\u0301es, la voiture poss\u00e8de plusieurs outils sciemment de\u0301veloppe\u0301s par les constructeurs&nbsp;: capteurs, micros\u2026<\/p>\n\n\n\n<p>Par ailleurs, Mozilla a constate\u0301 qu\u2019une marque comme Nissan pouvait aussi extraire des donne\u0301es relatives a\u0300 l\u2019activite\u0301 sexuelle, et utilisait des donne\u0301es pour de\u0301duire (a\u0300 partir du suppose\u0301 niveau d\u2019intelligence du conducteur constate\u0301 par le ve\u0301hicule) de nombreuses autres informations prive\u0301es telles que les tendances psychologiques, les pre\u0301dispositions comportementales et les attitudes du conducteur. Un fonctionnement qui fait dire a\u0300 la fondation ame\u0301ricaine que les constructeurs ont \u00ab&nbsp;transforme\u0301 leurs ve\u0301hicules en de puissantes machines a\u0300 surveiller, espionner et collecter des informations sur ce que vous faites et o\u00f9 vous allez avec votre voiture&nbsp;\u00bb.<\/p>\n\n\n\n<p>Voiture e\u0301lectrique ou non, soyez alerte\u0301 en temps re\u0301el des zones de dangers situe\u0301es sur votre itine\u0301raire gr\u00e2ce a\u0300 l\u2019<a href=\"https:\/\/www.moncoyote.com\/fr\/product\/581\/App-Coyote.html\" target=\"_blank\" rel=\"noreferrer noopener\">application Coyote<\/a> 100 % le\u0301gale&nbsp;!<\/p>\n\n\n\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#64e61e\"><strong>Comment sont utilise\u0301es les donne\u0301es personnelles par les constructeurs automobiles&nbsp;?<\/strong><\/h2>\n\n\n\n<p>Apr\u00e8s avoir analyse\u0301 les donne\u0301es personnelles, les constructeurs automobiles les partagent ou les revendent a\u0300 des tiers \u2013 19 constructeurs sur 25 ont de\u0301clare\u0301 les revendre a\u0300 des courtiers de donne\u0301es, des compagnies d\u2019assurance, des annonceurs ou divers fournisseurs de services. Par ailleurs, toujours selon cette m\u00eame e\u0301tude, 56 % des fabricants transmettraient les informations recueillies aux gouvernements ou aux forces de l\u2019ordre sur demande.<\/p>\n\n\n\n<p>Pour obtenir une meilleure protection de vos donne\u0301es personnelles, aucune solution n\u2019est actuellement pre\u0301vue par les constructeurs. Seuls Renault et Dacia (qui font partie du m\u00eame groupe) proposent aux conducteurs une fonctionnalite\u0301 permettant de demander l\u2019effacement des donne\u0301es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De plus en plus nombreux, les objets connecte\u0301s ont la capacite\u0301 de collecter nos donne\u0301es personnelles et de les transmettre [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":12825,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[12,32],"tags":[],"class_list":["post-12823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-automobile","category-innovation"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/12823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=12823"}],"version-history":[{"count":0,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/12823\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/12825"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=12823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=12823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=12823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}