{"id":4922,"date":"2018-02-20T12:46:14","date_gmt":"2018-02-20T11:46:14","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=4922"},"modified":"2018-02-20T12:46:14","modified_gmt":"2018-02-20T11:46:14","slug":"telephone-au-volant-prenez-garde-la-suspension-de-permis","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/reglementation-routiere\/telephone-au-volant-prenez-garde-la-suspension-de-permis\/","title":{"rendered":"Te\u0301le\u0301phone au volant : prenez garde a\u0300 la suspension de permis !"},"content":{"rendered":"<p>Plusieurs mesures concernant la se\u0301curite\u0301 routi\u00e8re ont e\u0301te\u0301 mises en place depuis le Comite\u0301 interministe\u0301riel de la se\u0301curite\u0301 routi\u00e8re (CISR) qui a eu lieu l\u2019anne\u0301e derni\u00e8re. Parmi les 18 mesures nouvellement mises en place, l\u2019abaissement de la limitation de vitesse a\u0300 80km\/h sur certaines routes, a largement fait parler d\u2019elle. Revenons sur une autre mesure importante qui fut discute\u0301e lors de ce comite\u0301 :\u00a0<strong>la suspension de permis en cas d\u2019utilisation du te\u0301le\u0301phone portable au volant<\/strong>.<\/p>\n<h2><span style=\"color: #64e600\">Un changement de comportement au volant<\/span><\/h2>\n<p>Les smartphones d\u2019aujourd\u2019hui ont bouleverse\u0301 nos vies. Nous sommes connecte\u0301s partout et tout le temps. Un bouleversement de nos modes de vie qui est non sans conse\u0301quence sur l\u2019usage du te\u0301le\u0301phone au volant.<\/p>\n<p>Le syndrome FOMO \u00ab\u00a0Fear Of Missing Out\u00a0\u00bb, ou en fran\u00e7ais<strong> la peur de rater quelque chose<\/strong>, se traduit par un besoin sans pre\u0301ce\u0301dent d\u2019\u00eatre constamment en relation avec les autres, d\u2019\u00eatre au courant de tout nouvel e\u0301ve\u0301nement et d\u2019\u00eatre joignable a\u0300 tout moment.<\/p>\n<p>Cette anxie\u0301te\u0301 sociale rend l\u2019utilisateur accro a\u0300 son smartphone, qui ne peut s\u2019en de\u0301tacher, et ne peut re\u0301sister a\u0300 l\u2019envie de le consulter constamment de peur de rater quelque chose d\u2019important.<\/p>\n<p>Les chiffres parlent d\u2019eux-m\u00eames\u00a0: En France, <strong>38% des conducteurs ont le re\u0301flexe de consulter leur smartphone d\u00e8s qu\u2019un son est e\u0301mis<\/strong>.<sup>1<\/sup><\/p>\n<p><em>1.Source: Minist\u00e8re de l\u2019inte\u0301rieur, 2018.<\/em><\/p>\n<h2><span style=\"color: #64e600\">Le te\u0301le\u0301phone portable en voiture : un facteur d\u2019accidents<\/span><\/h2>\n<p>SMS, appels, notifications\u2026 notre regard est sans cesse attire\u0301 vers l\u2019e\u0301cran de notre te\u0301le\u0301phone. Au volant, 5 secondes passe\u0301es sur votre smartphone sont 5 secondes durant lesquelles vous ne regardez pas la route.<br \/>\nLes chiffres d\u2019accidents lie\u0301s a\u0300 l\u2019usage du te\u0301le\u0301phone sont assez parlants :\u00a0<strong>les coups de fil au volant sont responsables d\u20191 accident corporel sur 10 et lire un message au volant multiplie par 23 le risque d\u2019accident<\/strong>. M\u00eame si l\u2019on ne s\u2019en rend pas force\u0301ment compte, une conversation te\u0301le\u0301phonique ou un SMS re\u0301duisent notre capacite\u0301 de concentration. Nous sommes donc moins enclins a\u0300 identifier et anticiper la survenue d\u2019un danger.<\/p>\n<h2><span style=\"color: #64e600\">Les sanctions en cas d\u2019usage du te\u0301le\u0301phone au volant<\/span><\/h2>\n<p>Les sanctions pour usage du te\u0301le\u0301phone au volant vont \u00eatre alourdies afin d\u2019inciter les automobilistes a\u0300 passer en mode silencieux ou avion lorsqu\u2019ils sont au volant. En juillet 2015,\u00a0<strong>l\u2019usage de kit main libres ou de tout dispositif permettant de diffuser du son directement a\u0300 l\u2019oreille avait e\u0301te\u0301 interdit, au volant et a\u0300 ve\u0301lo<\/strong>. La loi pre\u0301voyait une amende de 135 euros et la perte de 3 points en cas d\u2019infraction mais beaucoup d\u2019automobilistes occultent facilement cette de\u0301cision.<br \/>\nEn janvier 2018, les textes avaient e\u0301te\u0301 encore plus renforce\u0301s par Edouard Philippe en e\u0301voquant la possibilite\u0301 par les forces de l\u2019ordre\u00a0de : <strong>\u00ab\u00a0<em>retenir le permis de conduire d\u2019une personne sanctionne\u0301e pour conduite avec usage de te\u0301le\u0301phone tenu a\u0300 la main lorsqu\u2019elle a commis en m\u00eame temps une infraction susceptible de porter atteinte a\u0300 sa propre se\u0301curite\u0301 ou a\u0300 celle des tiers.<\/em><\/strong><em> \u00bb<\/em> Cette sanction pourra donc \u00eatre applique\u0301e par exemple si l\u2019automobiliste grille un stop alors qu\u2019il est au te\u0301le\u0301phone ou qu\u2019il le tient en main.\u00a0<strong>La suspension de permis de conduire s\u2019ajoute donc a\u0300 l\u2019amende de 135 euros et le retrait de 3 points. <\/strong><\/p>\n<p><em>Qu\u2019est-ce que la suspension de permis ?<\/em><br \/>\n<em>La suspension de permis est une annulation temporaire du permis de conduire. Le conducteur n\u2019a plus le droit de se servir de son ve\u0301hicule pendant cette pe\u0301riode, et toute infraction est passible de 2 ans d\u2019emprisonnement et de 4 500 euros d\u2019amende. Une suspension de permis dure ge\u0301ne\u0301ralement au maximum 6 mois mais elle peut \u00eatre prolonge\u0301e jusqu\u2019a\u0300\u00a01 an dans plusieurs cas (tels que la conduite en e\u0301tat d\u2019ivresse ou sous l\u2019emprise de drogue).<\/em><\/p>\n<p>La Revue de tweets :<\/p>\n<blockquote class=\"twitter-tweet\" data-lang=\"fr\">\n<p dir=\"ltr\" lang=\"fr\">Paru dans <a href=\"https:\/\/twitter.com\/OuestFrance?ref_src=twsrc%5Etfw\">@OuestFrance<\/a> aujourd&rsquo;hui : <a href=\"https:\/\/twitter.com\/hashtag\/80kmh?src=hash&amp;ref_src=twsrc%5Etfw\">#80kmh<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Telephone?src=hash&amp;ref_src=twsrc%5Etfw\">#Telephone<\/a> au volant <a href=\"https:\/\/twitter.com\/hashtag\/sanctions?src=hash&amp;ref_src=twsrc%5Etfw\">#sanctions<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/securiteroutiere?src=hash&amp;ref_src=twsrc%5Etfw\">#securiteroutiere<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/dessin?src=hash&amp;ref_src=twsrc%5Etfw\">#dessin<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/actualite?src=hash&amp;ref_src=twsrc%5Etfw\">#actualite<\/a> <a href=\"https:\/\/t.co\/dbDk3TH46j\">pic.twitter.com\/dbDk3TH46j<\/a><\/p>\n<p>\u2014 CHAUNU (@ChaunuShow) <a href=\"https:\/\/twitter.com\/ChaunuShow\/status\/951013907237408769?ref_src=twsrc%5Etfw\">10 janvier 2018<\/a><\/p><\/blockquote>\n<blockquote class=\"twitter-tweet\" data-lang=\"fr\">\n<p dir=\"ltr\" lang=\"fr\">Portable au volant : un conducteur sanctionne\u0301 pour avoir commis une infraction pouvant mettre en danger quelqu\u2019un alors qu&rsquo;il utilisait son te\u0301le\u0301phone pourra de\u0301sormais voir son permis retenu.<a href=\"https:\/\/twitter.com\/hashtag\/SauvonsPlusDeVies?src=hash&amp;ref_src=twsrc%5Etfw\">#SauvonsPlusDeVies<\/a> <a href=\"https:\/\/t.co\/xVmJTZ3pMV\">pic.twitter.com\/xVmJTZ3pMV<\/a><\/p>\n<p>\u2014 Edouard Philippe (@EPhilippePM) <a href=\"https:\/\/twitter.com\/EPhilippePM\/status\/950779942345887746?ref_src=twsrc%5Etfw\">9 janvier 2018<\/a><\/p><\/blockquote>\n<blockquote class=\"twitter-tweet\" data-lang=\"fr\">\n<p dir=\"ltr\" lang=\"fr\"><a href=\"https:\/\/twitter.com\/hashtag\/AuCinemaJeDetesteQuand?src=hash&amp;ref_src=twsrc%5Etfw\">#AuCinemaJeDetesteQuand<\/a> quelqu&rsquo;un utilise son <a href=\"https:\/\/twitter.com\/hashtag\/t%C3%A9l%C3%A9phone?src=hash&amp;ref_src=twsrc%5Etfw\">#te\u0301le\u0301phone<\/a> portable. Ici, il me de\u0301range. Au volant, il me tue. <a href=\"https:\/\/twitter.com\/hashtag\/s%C3%A9curit%C3%A9routi%C3%A8re?src=hash&amp;ref_src=twsrc%5Etfw\">#se\u0301curite\u0301routi\u00e8re<\/a> cc <a href=\"https:\/\/twitter.com\/MDDI_LU?ref_src=twsrc%5Etfw\">@MDDI_LU<\/a> <a href=\"https:\/\/t.co\/QWRkWNQeC4\">pic.twitter.com\/QWRkWNQeC4<\/a><\/p>\n<p>\u2014 Roulons Autrement (@RoulonsA) <a href=\"https:\/\/twitter.com\/RoulonsA\/status\/800681873995350016?ref_src=twsrc%5Etfw\">21 novembre 2016<\/a><\/p><\/blockquote>\n<blockquote class=\"twitter-tweet\" data-lang=\"fr\">\n<p dir=\"ltr\" lang=\"fr\">Au volant, le te\u0301le\u0301phone peut tuer ! <a href=\"https:\/\/twitter.com\/hashtag\/TousTouch%C3%A9s?src=hash&amp;ref_src=twsrc%5Etfw\">#TousTouche\u0301s<\/a> avec <a href=\"https:\/\/twitter.com\/RoutePlusSure?ref_src=twsrc%5Etfw\">@RoutePlusSure<\/a><a href=\"https:\/\/twitter.com\/hashtag\/S%C3%A9curit%C3%A9Routi%C3%A8re?src=hash&amp;ref_src=twsrc%5Etfw\">#Se\u0301curite\u0301Routi\u00e8re<\/a> <a href=\"https:\/\/t.co\/hB7IwJMMQ5\">pic.twitter.com\/hB7IwJMMQ5<\/a><\/p>\n<p>\u2014 Tunnel de Toulon (@TunnelToulon) <a href=\"https:\/\/twitter.com\/TunnelToulon\/status\/955143488814895106?ref_src=twsrc%5Etfw\">21 janvier 2018<\/a><\/p><\/blockquote>\n<blockquote class=\"twitter-tweet\" data-lang=\"fr\">\n<p dir=\"ltr\" lang=\"fr\">[Infographie] 43% des conducteurs utilisent leur te\u0301le\u0301phone au volant ! Retour sur les chiffres du barom\u00e8tre des usages du te\u0301le\u0301phone au volant &#x1f4f1; cc <a href=\"https:\/\/twitter.com\/Ifsttar?ref_src=twsrc%5Etfw\">@Ifsttar<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/s%C3%A9curit%C3%A9routi%C3%A8re?src=hash&amp;ref_src=twsrc%5Etfw\">#se\u0301curite\u0301routi\u00e8re<\/a> <a href=\"https:\/\/t.co\/90jwV5oxCj\">pic.twitter.com\/90jwV5oxCj<\/a><\/p>\n<p>\u2014 Fondation MAIF (@FondationMAIF) <a href=\"https:\/\/twitter.com\/FondationMAIF\/status\/954998753039065088?ref_src=twsrc%5Etfw\">21 janvier 2018<\/a><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Plusieurs mesures concernant la se\u0301curite\u0301 routi\u00e8re ont e\u0301te\u0301 mises en place depuis le Comite\u0301 interministe\u0301riel de la se\u0301curite\u0301 routi\u00e8re (CISR) [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":4924,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18,30],"tags":[],"class_list":["post-4922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reglementation-routiere","category-securite-routiere"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/4922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=4922"}],"version-history":[{"count":0,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/4922\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/4924"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=4922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=4922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=4922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}