<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Warning</b>:  Cannot modify header information - headers already sent by (output started at /var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php:129) in <b>/var/www/html/web/wp/wp-includes/rest-api/class-wp-rest-server.php</b> on line <b>1896</b><br />
<br />
<b>Warning</b>:  Cannot modify header information - headers already sent by (output started at /var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php:129) in <b>/var/www/html/web/wp/wp-includes/rest-api/class-wp-rest-server.php</b> on line <b>1896</b><br />
{"id":5196,"date":"2018-04-17T11:00:02","date_gmt":"2018-04-17T10:00:02","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=5196"},"modified":"2018-04-17T11:00:02","modified_gmt":"2018-04-17T10:00:02","slug":"controle-technique-2018","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/reglementation-routiere\/controle-technique-2018\/","title":{"rendered":"CONTR\u00d4LE TECHNIQUE :  LES NOUVEAUTE\u0301S DE 2018"},"content":{"rendered":"<p><em>La re\u0301forme du contr\u00f4le technique fera son apparition d\u00e8s le 20 mai prochain.\u00a0Entre fausses rumeurs et vrais changements : a\u0300 quoi devez-vous re\u0301ellement vous attendre ?\u00a0Coyote de\u0301chiffre pour vous cette nouvelle mesure !<\/em><\/p>\n<h3><span style=\"color: #64e600\">\u00c0 quoi sert le contr\u00f4le technique ?\u00a0<\/span><\/h3>\n<p>Instaure\u0301 en France depuis 1992,\u00a0<span class=\"txt_bold\">le contr\u00f4le technique a pour double objectif de <strong>renforcer la se\u0301curite\u0301 sur les routes<\/strong>, et par la m\u00eame occasion de <strong>pre\u0301server l&rsquo;environnement<\/strong><\/span><strong>\u00a0par un contr\u00f4le re\u0301gulier des e\u0301missions polluantes<\/strong>. En fonction des de\u0301fauts constate\u0301s, le proprie\u0301taire est tenu a\u0300 une remise en e\u0301tat dans un de\u0301lai de deux mois.<br \/>\nJusqu&rsquo;alors, 123 points de contr\u00f4le sont examine\u0301s a\u0300 la loupe, avec 453 de\u0301fauts possibles.\u00a0<span class=\"txt_bold\">Le contr\u00f4le technique initial est obligatoire dans les six mois qui pre\u0301c\u00e8dent la quatri\u00e8me anne\u0301e du ve\u0301hicule<\/span>, puis tous les deux ans.<\/p>\n<h3><span style=\"color: #64e600\">Ce qui va changer avec le nouveau contr\u00f4le technique, le point sur les ide\u0301es re\u00e7ues<\/span><\/h3>\n<p><span style=\"padding: 15px;background-color: #f3f3f3;line-height: 40px\"><strong>Le nombre de points de contr\u00f4le va augmenter<\/strong><\/span><\/p>\n<p><strong><span style=\"color: #64e600\">VRAI !<\/span> 132 points de contr\u00f4les<\/strong> seront a\u0300 pre\u0301sent passe\u0301s au crible contre 123 aujourd&rsquo;hui. Mais c&rsquo;est surtout le <strong>nombre de de\u0301faillances constatables qui e\u0301volue<\/strong>. Il passe de 407 a\u0300 <strong>606<\/strong>. Un m\u00eame point de contr\u00f4le peut en effet re\u0301ve\u0301ler plusieurs de\u0301fauts. Le pneu, par exemple, peut \u00eatre lisse, mal gonfle\u0301 ou encore pre\u0301senter une usure anormale sur le flanc.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"padding: 15px;background-color: #f3f3f3;line-height: 40px\"><strong>Un nouveau niveau de de\u0301faillance sera pre\u0301sent\u00a0 \u00a0<\/strong><\/span><\/p>\n<p><strong><span style=\"color: #64e600\">VRAI !<\/span> <\/strong>Pour\u00a0coller\u00a0aux directives europe\u0301ennes, le nouveau contr\u00f4le technique sera plus se\u0301v\u00e8re. <strong>Il n&rsquo;y aura donc plus deux mais trois niveaux de de\u0301faillance\u00a0<\/strong>mentionne\u0301s sur le proc\u00e8s-verbal du contr\u00f4leur :<\/p>\n<ol>\n<li style=\"list-style-type: none\">\n<ol>\n<li style=\"text-align: left\"><strong>mineures<\/strong> (139 de\u0301fauts possibles devant \u00eatre re\u0301pare\u0301s mais ne ne\u0301cessitant pas de contre-visite)<\/li>\n<li><strong>majeures<\/strong> (340 de\u0301fauts regroupant les anomalies ne\u0301cessitant une contre-visite)<\/li>\n<li><strong>critiques<\/strong> (au nombre de 127, elles entra\u00eeneront\u00a0<span class=\"txt_bold\"><span class=\"txt_bold\">une contre-visite mais\u00a0 e\u0301galement une immobilisation de votre ve\u0301hicule)<\/span><\/span><\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><span style=\"padding: 15px;background-color: #f3f3f3;line-height: 40px\"><strong>Pour certains ve\u0301hicules, le contr\u00f4le technique va devenir\u00a0annuel<\/strong><\/span><\/p>\n<p><span style=\"color: #fa003c\"><strong>FAUX !\u00a0<\/strong><span style=\"color: #000000\">Les ve\u0301hicules de plus de huit ans ou ayant passe\u0301 le cap de 160.000 km ne seront pas soumis a\u0300 un contr\u00f4le obligatoire tous les ans.\u00a0L&rsquo;Europe le souhaitait mais plusieurs e\u0301tats s&rsquo;y sont oppose\u0301s.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5245 size-full\" title=\"contr\u00f4le technique\" src=\"https:\/\/medias.csi.int.coyotesystems.com\/wordpress\/2018\/04\/AdobeStock_140070209-min.jpeg\" alt=\"contr\u00f4le technique\" width=\"5107\" height=\"3405\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"padding: 15px;background-color: #f3f3f3;line-height: 40px\"><strong>Le prix du contr\u00f4le technique va augmenter<\/strong><\/span><\/p>\n<p><strong><span style=\"color: #64e600\">VRAI !\u00a0<\/span><\/strong><span style=\"color: #000000\">D&rsquo;une part parce que le prix n&rsquo;a pratiquement pas e\u0301volue\u0301 depuis 2008, d&rsquo;autre part parce que les centres ont souvent d\u00fb investir dans du mate\u0301riel ou dans des mises a\u0300 jour, en particulier pour les contr\u00f4les des phares et de la pollution. Son augmentation sera donc comprise <strong>entre\u00a015 % et 20% en moyenne<\/strong>. Aujourd&rsquo;hui, le tarif moyen du contr\u00f4le technique obligatoire en France est de\u00a065 euros.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"padding: 15px;background-color: #f3f3f3;line-height: 40px\"><strong>L\u2019automobiliste disposera de moins de temps\u00a0pour faire re\u0301parer son ve\u0301hicule<\/strong><\/span><\/p>\n<p><span style=\"color: #fa003c\"><strong>FAUX !\u00a0<\/strong><span style=\"color: #000000\">Le ve\u0301hicule ne peut plus rouler a\u0300 partir de minuit le jour du contr\u00f4le s\u2019il pre\u0301sente une de\u0301faillance critique et <strong>la contre-visite est a\u0300 re\u0301aliser dans un de\u0301lai de deux mois<\/strong>, comme pour le contr\u00f4le technique actuel. Cette mesure est de\u0301ja\u0300 en vigueur pour les poids-lourds, mais avec un de\u0301lai supple\u0301mentaire de 24 heures.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"padding: 15px;background-color: #f3f3f3;line-height: 40px\"><strong>La contre-visite sera plus longue et payante<\/strong><\/span><\/p>\n<p><span style=\"color: #64e600\"><strong>VRAI !\u00a0<\/strong><span style=\"color: #000000\">La dure\u0301e des contre-visites va augmenter, puisque des fonctions enti\u00e8res seront a\u0300 contr\u00f4ler selon les de\u0301faillances releve\u0301es. Le tarif devrait \u00eatre de l\u2019ordre de <strong>20 a\u0300 30\u20ac<\/strong> selon les centres et la nature de la contre-visite. Jusqu&rsquo;a\u0300 pre\u0301sent, le prix moyen d&rsquo;une contre-visite e\u0301tait de 14\u20ac.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #ffb400\">Selon vous, ce nouveau contr\u00f4le technique permettra-t-il d&rsquo;ame\u0301liorer la se\u0301curite\u0301 des automobilistes ?\u00a0\u00a0<\/span><\/h3>\n<p>[totalpoll id=\u00a0\u00bb5142&Prime;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La re\u0301forme du contr\u00f4le technique fera son apparition d\u00e8s le 20 mai prochain.\u00a0Entre fausses rumeurs et vrais changements : a\u0300 [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":5230,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-5196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reglementation-routiere"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/5196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=5196"}],"version-history":[{"count":0,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/5196\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=5196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=5196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=5196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}