{"id":5274,"date":"2018-04-23T11:48:59","date_gmt":"2018-04-23T10:48:59","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=5274"},"modified":"2018-04-23T11:48:59","modified_gmt":"2018-04-23T10:48:59","slug":"comment-se-forment-les-embouteillages","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/actualites-automobile\/comment-se-forment-les-embouteillages\/","title":{"rendered":"Comment se forment les embouteillages ?"},"content":{"rendered":"<p>Pour mieux comprendre la formation des embouteillages, les scientifiques ont adopte\u0301 une technique simple : comparer le trafic routier a\u0300 un fluide. Ralentissements, bouchons : de\u0301couvrez comment \u00ab le cauchemar des automobilistes \u00bb survient dans le trafic routier.<\/p>\n<h2 style=\"color: #64e61e\">Capacite\u0301 d\u2019absorption et flux du trafic<\/h2>\n<p>L\u2019embouteillage repose sur le flux des ve\u0301hicules et la capacite\u0301 d\u2019une route a\u0300 l\u2019absorber. Contrairement aux ide\u0301es re\u00e7ues, la <strong>vitesse de circulation<\/strong> ne fait pas augmenter la capacite\u0301 d\u2019absorption d\u2019une route. Au-dela\u0300 de 1500 ve\u0301hicules par heure et par voie, la voie atteint sa capacite\u0301 maximale d\u00e8s 70km\/h de vitesse moyenne.<\/p>\n<p>Les ve\u0301hicules dont la vitesse est plus rapide devront tout de m\u00eame respecter un espace plus grand entre eux, face a\u0300 la densite\u0301 accrue du trafic. A force, les ve\u0301hicules sont force\u0301s de freiner, ce qui cre\u0301e un bouchon aussi dit \u00ab <strong>embouteillage par saturation<\/strong> \u00bb.<br \/>\nAutre forme de bouchon, celui lie\u0301 a\u0300 un e\u0301ve\u0301nement tel qu\u2019un accident. Avec une voie en moins par exemple, la capacite\u0301 de l\u2019autoroute est infe\u0301rieure a\u0300 la demande et l\u2019embouteillage fait vite son apparition.<\/p>\n<p>Enfin, le bouchon \u00ab de curiosite\u0301 \u00bb est celui qui survient sur une voie sans proble\u0301matique apparente. Par exemple, il peut survenir lorsqu\u2019un e\u0301ve\u0301nement remarquable survient de l\u2019autre c\u00f4te\u0301 des glissi\u00e8res et que chaque conducteur a le re\u0301flexe de ralentir pour \u00ab observer \u00bb, d\u2019o\u00f9 le nom de curiosite\u0301. Celui qui ralentit force celui qui le suit a\u0300 ralentir, ralentissant le trafic global.<\/p>\n<p><iframe loading=\"lazy\" title=\"Comprenez comment se forment les bouchons sur l&#039;autoroute gr\u00e2ce \u00e0 ce simulateur\" frameborder=\"0\" width=\"500\" height=\"281\" src=\"https:\/\/geo.dailymotion.com\/player.html?video=x4mubh6&#038;\" allowfullscreen allow=\"autoplay; fullscreen; picture-in-picture; web-share\"><\/iframe><\/p>\n<h2 style=\"color: #64e61e\">Re\u0301duire les embouteillages : quelles solutions ?<\/h2>\n<p>A la mani\u00e8re des fluides, les bouchons interviennent surtout quand le trafic est dense. La re\u0301action en cha\u00eene est engendre\u0301e par les ve\u0301hicules a\u0300 haute vitesse qui ralentissent, jusqu\u2019a\u0300 cre\u0301er le bouchon.<\/p>\n<p>Face a\u0300 ce fle\u0301au de\u0301plore\u0301 par tous les conducteurs, des solutions sont envisage\u0301es :<\/p>\n<ul>\n<li>augmenter les distances de se\u0301curite\u0301 entre chaque ve\u0301hicule ;<\/li>\n<li>re\u0301duire la vitesse globale du trafic ;<\/li>\n<li>agrandir les axes routiers ;<\/li>\n<li>re\u0301duire le nombre de ve\u0301hicules en circulation.<\/li>\n<\/ul>\n<p>Dans certaines grandes agglome\u0301rations, les experts de\u0301tectent des embouteillages \u00ab fant\u00f4mes \u00bb sans cause apparente, ou presque. Les automobilistes qui en sont responsables sont ceux qui maintiennent difficilement la distance adapte\u0301e entre eux. Ce manque de fluidite\u0301 sur les routes am\u00e8ne les constructeurs a\u0300 repenser la voiture autonome qui, pour eux, pourrait \u00eatre la solution miracle.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour mieux comprendre la formation des embouteillages, les scientifiques ont adopte\u0301 une technique simple : comparer le trafic routier a\u0300 [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":5275,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,12],"tags":[],"class_list":["post-5274","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-automobile","category-automobile"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/5274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=5274"}],"version-history":[{"count":0,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/5274\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/5275"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=5274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=5274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=5274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}