{"id":6072,"date":"2018-10-05T10:23:14","date_gmt":"2018-10-05T08:23:14","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=6072"},"modified":"2018-10-05T10:23:14","modified_gmt":"2018-10-05T08:23:14","slug":"5-conseils-pour-circuler-en-deux-roues-dans-les-bouchons","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/securite-routiere\/5-conseils-pour-circuler-en-deux-roues-dans-les-bouchons\/","title":{"rendered":"5 conseils pour circuler en deux-roues dans les bouchons"},"content":{"rendered":"<p>Pour circuler plus vite au quotidien et e\u0301viter les embouteillages, nombreux sont ceux a\u0300 opter pour un deux-roues. Pour allier gain de temps et se\u0301curite\u0301 dans les bouchons, voici 5 conseils a\u0300 suivre. <strong>En route\u00a0!<\/strong><\/p>\n<h2 style=\"color: #64e600\">Anticiper l\u2019embouteillage<\/h2>\n<p>Si vous remarquez <strong>un ralentissement ou un bouchon<\/strong>, votre premier re\u0301flexe en arrivant a\u0300 sa hauteur doit \u00eatre de\u00a0:<\/p>\n<ul>\n<li>Ralentir,<\/li>\n<li>Mettre vos feux de de\u0301tresse.<\/li>\n<\/ul>\n<p>Au choix, vous pouvez ensuite de\u0301cider de <strong>vous arr\u00eater<\/strong> sur une aire de repos ou sur le bas-c\u00f4te\u0301 s\u2019il est stabilise\u0301.<\/p>\n<p>Vous pouvez e\u0301galement <strong>rouler dans l\u2019embouteillage<\/strong>\u00a0:<\/p>\n<ul>\n<li>En suivant pas a\u0300 pas les ve\u0301hicules qui vous pre\u0301c\u00e8dent,<\/li>\n<li>En profitant de la tole\u0301rance sur les remonte\u0301es de file.<\/li>\n<\/ul>\n<p>Rappel\u00a0: l\u2019arr\u00eat ou la circulation sur une bande d\u2019arr\u00eat d\u2019urgence est interdite et peut vous co\u00fbter (tr\u00e8s) cher en deux-roues ou quatre-roues.<\/p>\n<h2 style=\"color: #64e600\">Pratiquer la remonte\u0301e de file en respectant les r\u00e8gles<\/h2>\n<p>Remonter les files de voiture par la gauche est fre\u0301quent pour les conducteurs de deux-roues, entre deux files de circulation a\u0300 l\u2019arr\u00eat ou en mouvement. En ville notamment, cette pratique est re\u0301pandue pour e\u0301viter les embouteillages ou se positionner sur la ligne de feu.<\/p>\n<p>Face a\u0300 la congestion de la circulation urbaine ou pe\u0301ri-urbaine, la remonte\u0301e de file fait l\u2019objet d\u2019une expe\u0301rimentation depuis 2016 et concerne les motards ou conducteurs de scooters a\u0300 3 roues (largeur infe\u0301rieure a\u0300 1 m\u00e8tre).<\/p>\n<p><strong>Pour remonter les files prudemment\u00a0:<\/strong><\/p>\n<ul>\n<li>Circulez entre les deux voies <strong>les plus a\u0300 gauche<\/strong> de la chausse\u0301e,<\/li>\n<li>Ne de\u0301passez pas la vitesse de <strong>50km\/h<\/strong>,<\/li>\n<li>Mettez vos <strong>feux antibrouillard<\/strong> pour \u00eatre plus visible,<\/li>\n<li>Respectez <strong>la distance de se\u0301curite\u0301 <\/strong>avec le deux-roues qui vous pre\u0301c\u00e8de,<\/li>\n<li>Signalez votre intention au moment de rejoindre ou quitter l\u2019inter-file.<\/li>\n<\/ul>\n<h2 style=\"color: #64e600\">Rouler prudemment et sans forcer<\/h2>\n<p>En ville ou sur une voie rapide, le risque premier est le changement de file d\u2019un autre ve\u0301hicule qui ne vous aurait pas vu. M\u00eame si la cohabitation entre quatre-roues et deux-roues s\u2019ame\u0301liore, dans les embouteillages, la prudence est de mise.<\/p>\n<p>Parmi les automobilistes, nombreux sont ceux a\u0300 changer de file pour aller plus vite ou ceux qui se divertissent dans les bouchons et sont donc <strong>moins attentifs<\/strong>\u00a0: te\u0301le\u0301phone, cigarette, maquillage etc.<\/p>\n<p>Rappelez-vous que <strong>la circulation inter-files est tole\u0301re\u0301e<\/strong> mais pas (encore) de plein droit. Votre prudence et votre sens de l\u2019anticipation assureront votre se\u0301curite\u0301. A l\u2019inverse, en e\u0301change de toute courtoisie d\u2019un autre usager de la route, n\u2019he\u0301sitez pas a\u0300 remercier.<\/p>\n<h2 style=\"color: #64e600\">User de vos re\u0301flexes en ville<\/h2>\n<p>Si vous circulez en ville, vous vous exposez a\u0300 une route faite de nombreux <strong>obstacles potentiels<\/strong>\u00a0: des pie\u0301tons, automobilistes, livreurs ou motards par exemple. Si vous conduisez un scooter 50cc, vous aurez probablement plus de chances d\u2019outrepasser les embouteillages qu\u2019en moto. Les petits gabarits se faufilent mieux, c\u2019est un fait mais n\u2019oubliez pas que les pie\u0301tons int\u00e8grent aise\u0301ment la pre\u0301sence des voitures ou camions mais beaucoup moins la pre\u0301sence des deux-roues.<\/p>\n<p>Gardez en t\u00eate que <strong>tout le monde ne respecte pas force\u0301ment les r\u00e8gles<\/strong>, qu\u2019il s\u2019agisse de pie\u0301tons ou de ve\u0301hicules. Ainsi, pre\u0301fe\u0301rez la partie gauche de la chausse\u0301e pour circuler et restez attentif. Vous pouvez \u00eatre invisible a\u0300 tout moment <em>(pour les transports en commun, les utilitaires ou aux croisements). <\/em>D\u2019o\u00f9 l\u2019importance de travailler votre <strong>maniement du deux-roues<\/strong>, vos re\u0301flexes et de respecter scrupuleusement les limitations de vitesse.<\/p>\n<h2 style=\"color: #64e600\">Suivre les r\u00e8gles de de\u0301passement<\/h2>\n<p>En cas d\u2019embouteillage, le code de la route n\u2019autorise pas le de\u0301passement par la droite. En deux-roues, vous devrez <strong>de\u0301passer uniquement par la gauche<\/strong> tout en faisant bien usage du clignotant au moment opportun. Egalement, les contr\u00f4les de visibilite\u0301 seront vos allie\u0301s a\u0300 tout moment, notamment pour vous rabattre en toute se\u0301curite\u0301.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Bonne route\u00a0!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour circuler plus vite au quotidien et e\u0301viter les embouteillages, nombreux sont ceux a\u0300 opter pour un deux-roues. Pour allier [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":6074,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[30],"tags":[],"class_list":["post-6072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-securite-routiere"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/6072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=6072"}],"version-history":[{"count":0,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/6072\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/6074"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=6072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=6072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=6072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}