<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Warning</b>:  Cannot modify header information - headers already sent by (output started at /var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php:129) in <b>/var/www/html/web/wp/wp-includes/rest-api/class-wp-rest-server.php</b> on line <b>1896</b><br />
<br />
<b>Warning</b>:  Cannot modify header information - headers already sent by (output started at /var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php:129) in <b>/var/www/html/web/wp/wp-includes/rest-api/class-wp-rest-server.php</b> on line <b>1896</b><br />
{"id":6161,"date":"2018-11-07T10:27:21","date_gmt":"2018-11-07T09:27:21","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=6161"},"modified":"2018-11-07T10:27:21","modified_gmt":"2018-11-07T09:27:21","slug":"les-insolites-du-mondial-de-lauto-2018","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/actualites-automobile\/les-insolites-du-mondial-de-lauto-2018\/","title":{"rendered":"Les insolites du Mondial de l\u2019Auto 2018"},"content":{"rendered":"<p>Pour sa 88\u00e8me e\u0301dition, le Mondial de l\u2019Auto 2018 s\u2019est tenu a\u0300 Paris du 4 au 14 octobre. L\u2019e\u0301ve\u0301nement a accueilli cette anne\u0301e plus d\u2019un million de visiteurs, malgre\u0301 l\u2019absence de grandes marques comme Volkswagen ou Ford.<\/p>\n<h2 style=\"color: #64e600\">En route vers le futur<\/h2>\n<div id=\"attachment_6163\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/medias.csi.int.coyotesystems.com\/wordpress\/2018\/11\/renault-ez.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-6163\" class=\"size-full wp-image-6163\" src=\"https:\/\/medias.csi.int.coyotesystems.com\/wordpress\/2018\/11\/renault-ez.jpg\" alt=\"Nouvelle Renault EZ\" width=\"300\" height=\"168\" \/><\/a><p id=\"caption-attachment-6163\" class=\"wp-caption-text\">Source : Renault<\/p><\/div>\n<p>Cette e\u0301dition du Mondial aura fait la part belle aux ve\u0301hicules futuristes, a\u0300 commencer par Renault. Le constructeur fran\u00e7ais a en effet pre\u0301sente\u0301 trois concept-cars autonomes\u00a0: l\u2019EZ-Pro (utilitaire), l\u2019EZ-Go (taxi) et l\u2019EZ-Ultimo (luxe). Toujours c\u00f4te\u0301\u00a0fran\u00e7ais, l\u2019entreprise Navya a expose\u0301 ses navettes autonomes con\u00e7ues pour les de\u0301placements urbains. Certains mod\u00e8les sont de\u0301ja\u0300 en circulation a\u0300 Lyon et a\u0300 Rouen. Enfin, il ne fallait pas manquer la Vision EQ Silver Arrow de Mercedes, cre\u0301e\u0301 a\u0300 partir de l\u2019ancien mod\u00e8le W125 Rekordwagen datant des anne\u0301es 1940.<\/p>\n<h2 style=\"color: #64e600\">Une Bugatti en Lego<\/h2>\n<div id=\"attachment_6162\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/medias.csi.int.coyotesystems.com\/wordpress\/2018\/11\/mondial-auto-paris-2018-lego-bugatti-chiron.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-6162\" class=\"size-full wp-image-6162\" src=\"https:\/\/medias.csi.int.coyotesystems.com\/wordpress\/2018\/11\/mondial-auto-paris-2018-lego-bugatti-chiron.jpg\" alt=\"\" width=\"600\" height=\"336\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2018\/11\/mondial-auto-paris-2018-lego-bugatti-chiron.jpg 600w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2018\/11\/mondial-auto-paris-2018-lego-bugatti-chiron-300x168.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><p id=\"caption-attachment-6162\" class=\"wp-caption-text\">Source : Mondial de l&rsquo;Auto<\/p><\/div>\n<p>Le fabricant de jouets danois, partenaire du salon, a expose\u0301 une reproduction de la Bugatti Chiron a\u0300 taille re\u0301elle enti\u00e8rement construite en Lego. Cela aura repre\u0301sente\u0301 13\u00a0000 heures de travail, plus d\u2019un million de pi\u00e8ces Lego Technic (se\u0301rie spe\u0301cialise\u0301e dans les ve\u0301hicules) pour un re\u0301sultat qui p\u00e8se une tonne et demi\u00a0! Et en bonus, les visiteurs pouvaient interagir avec le mod\u00e8le en allumant ses feux ou en faisant tourner son petit moteur 5 chevaux (pour une vitesse de pointe de 20 km\/h\u00a0!). Si Lego ne proposait pas son chef d\u2019\u0153uvre a\u0300 une conduite expe\u0301rimentale, on pouvait tout de m\u00eame repartir avec une reproduction miniature de la Bugatti Chiron en briques.<\/p>\n<h2 style=\"color: #64e600\">Des ve\u0301hicules verts a\u0300 tester place de la Concorde<\/h2>\n<p>Peugeot, Renault ou encore Kia proposaient, sur rendez-vous, de tester des mod\u00e8les e\u0301lectriques, hybrides ou m\u00eame hydrog\u00e8ne. En effet, Toyota a pre\u0301sente\u0301 le premier mod\u00e8le de voiture a\u0300 hydrog\u00e8ne industrialise\u0301e a\u0300 grande e\u0301chelle, baptise\u0301 Mirai (<em>voir image a\u0300 la une &#8211; source : Toyota<\/em>). Elle fonctionne gr\u00e2ce a\u0300 deux sources d\u2019e\u0301nergie\u00a0: une pile a\u0300 combustible (114 kW) et une batterie Ni-Mh (1,6 kW) qui alimentent un moteur e\u0301lectrique. Seulement 3 minutes suffisent a\u0300 faire le plein d\u2019hydrog\u00e8ne, pour une autonomie d\u2019environ 650 kilom\u00e8tres. Et en ne rejetant que de l\u2019eau distille\u0301e, on est a\u0300 la pointe de la conduite e\u0301cologique.<\/p>\n<p style=\"text-align: center\">Vous n\u2019avez pas pu nous rencontrer au Mondial\u00a0? <a href=\"https:\/\/www.moncoyote.com\/fr\/service.html\">De\u0301couvrez le service Coyote\u00a0<\/a>!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour sa 88\u00e8me e\u0301dition, le Mondial de l\u2019Auto 2018 s\u2019est tenu a\u0300 Paris du 4 au 14 octobre. L\u2019e\u0301ve\u0301nement a [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":6157,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,12],"tags":[],"class_list":["post-6161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-automobile","category-automobile"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/6161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=6161"}],"version-history":[{"count":0,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/6161\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/6157"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=6161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=6161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=6161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}