{"id":6170,"date":"2018-11-12T10:30:16","date_gmt":"2018-11-12T09:30:16","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=6170"},"modified":"2018-11-12T10:30:16","modified_gmt":"2018-11-12T09:30:16","slug":"la-prime-a-la-conversion-a-seduit-les-francais","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/actualites-automobile\/la-prime-a-la-conversion-a-seduit-les-francais\/","title":{"rendered":"La prime a\u0300 la conversion a se\u0301duit les Fran\u00e7ais"},"content":{"rendered":"<p>La prime a\u0300 la conversion, c\u2019est un peu la prime a\u0300 la casse nouvelle version. Ce dispositif a e\u0301te\u0301 mis en place par le gouvernement en 2015. Il a e\u0301te\u0301 reconduit en 2016, 2017 et 2018. L\u2019objectif affiche\u0301 est clair : renouveler le parc automobile (l\u2019\u00e2ge moyen des ve\u0301hicules est de 9 ans) et inciter les Fran\u00e7ais a\u0300 investir dans un ve\u0301hicule moins polluant.<\/p>\n<p>La version 2018 de la prime a\u0300 la conversion, e\u0301galement appele\u0301e \u201cdispositif Hulot\u201d, du nom de l\u2019ancien ministre de l\u2019Ecologie et de la Transition e\u0301nerge\u0301tique, permet aux proprie\u0301taires de voiture de mettre au rebut leur vieux ve\u0301hicule et de toucher une prime pour s\u2019e\u0301quiper d\u2019un mod\u00e8le plus e\u0301cologique, neuf ou d\u2019occasion. Il peut s\u2019agir d\u2019une voiture, d\u2019une camionnette, d\u2019un deux-roues ou d\u2019un trois roues. La voiture ou la camionnette doivent \u00eatre e\u0301lectriques ou rejeter moins de 130 g de CO2 au kilom\u00e8tre. Les deux et trois-roues ne doivent pas utiliser de batterie au plomb et posse\u0301der une puissance maximale nette du moteur d\u2019au moins 3 kW.<\/p>\n<h2 style=\"color: #64e600\">Bilan tr\u00e8s positif pour la prime a\u0300 la conversion<\/h2>\n<p>Et cette ope\u0301ration semble \u00eatre un beau succ\u00e8s. En septembre 2018, soit 8 mois apr\u00e8s la mise en place du dernier dispositif, 170 000 dossiers de demandes de prime a\u0300 la conversion avaient e\u0301te\u0301 de\u0301pose\u0301s ! Le gouvernement serait m\u00eame victime de son succ\u00e8s puisque l\u2019on de\u0301plore aujourd\u2019hui des retards dans le versement de la prime.<\/p>\n<p>II n\u2019emp\u00eache que l\u2019offre est alle\u0301chante : vous pouvez toucher entre 1000 et 2000 euros de prime, en fonction de votre situation fiscale. Si vous remplacez votre vieille voiture par un ve\u0301hicule e\u0301lectrique, cette prime s\u2019e\u0301l\u00e8ve m\u00eame a\u0300 2500 euros. De plus, cette somme est cumulable avec celle du <a href=\"https:\/\/www.moncoyote.com\/blog\/coyote\/taxe-ecologique-2019\/\">bonus e\u0301cologique<\/a>. Cette aide de l\u2019Etat, mise en place en 2007 dans le cadre du Grenelle de l\u2019Environnement, peut atteindre 6000 euros si la voiture que vous achetez rejette moins de 20 g de CO2 par kilom\u00e8tre. Le bar\u00e8me de cette aide gouvernementale est revu chaque anne\u0301e.<\/p>\n<p>Cependant, les ve\u0301hicules verts ne repre\u0301sentent que 8 % des nouveaux ve\u0301hicules achete\u0301s dans le cadre de ce dispositif. Ce sont finalement les ve\u0301hicules d\u2019occasion qui tirent le mieux leur e\u0301pingle du jeu, puisqu\u2019ils repre\u0301sentent 62 % des ventes. Les Fran\u00e7ais les plus friands de ce dispositif sont les personnes non imposables et les proprie\u0301taires de ve\u0301hicule diesel.<\/p>\n<h2 style=\"color: #64e600\">Qui peut be\u0301ne\u0301ficier de la prime a\u0300 la conversion ?<\/h2>\n<p>Une situation logique puisque, pour be\u0301ne\u0301ficier de la prime a\u0300 la conversion selon les crit\u00e8res e\u0301tablis en janvier 2018, il faut remplir les conditions suivantes :<\/p>\n<ul>\n<li>\u00catre proprie\u0301taire d\u2019une voiture depuis plus de 12 mois<\/li>\n<li>\u00catre immatricule\u0301 en France<\/li>\n<li>Ne pas avoir un ve\u0301hicule conside\u0301re\u0301 comme \u201cendommage\u0301\u201d<\/li>\n<li>Faire l\u2019objet d\u2019un contrat d\u2019assurance en cours de validite\u0301<\/li>\n<li>Acheter une nouvelle voiture dans les 6 mois suivant la mise a\u0300 la casse.<\/li>\n<\/ul>\n<p>Le crit\u00e8re de l\u2019anciennete\u0301 du ve\u0301hicule susceptible d\u2019\u00eatre repris de\u0301pend de la situation fiscale de votre foyer et du carburant de votre voiture.<\/p>\n<p>Si vous \u00eates soumis a\u0300 l\u2019imp\u00f4t sur le revenu et que votre ve\u0301hicule carbure au diesel, il faut que celui-ci soit immatricule\u0301 avant 2001. S\u2019il s\u2019agit d\u2019un ve\u0301hicule essence, son immatriculation doit \u00eatre ante\u0301rieure a\u0300 1997.<\/p>\n<p>Si vous n\u2019\u00eates pas imposable et que vous posse\u0301dez un ve\u0301hicule diesel, celui-ci doit dater d\u2019avant 2006. S\u2019il s\u2019agit d\u2019un ve\u0301hicule essence, elle doit \u00eatre immatricule\u0301e avant 1997.<\/p>\n<p>On comprend donc aise\u0301ment pourquoi ce sont les foyers non imposables et les proprie\u0301taires de voitures diesel qui ont le plus demande\u0301 cette prime a\u0300 la conversion. Cette derni\u00e8re devrait \u00eatre reconduite en 2019.<\/p>\n<p style=\"text-align: center\">Accompagnez votre ve\u0301hicule e\u0301cologique d\u2019un <a href=\"https:\/\/www.moncoyote.com\/fr\/products-fr.html\">assistant d\u2019aide a\u0300 la conduite\u00a0<\/a>!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La prime a\u0300 la conversion, c\u2019est un peu la prime a\u0300 la casse nouvelle version. Ce dispositif a e\u0301te\u0301 mis [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":6176,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,12],"tags":[],"class_list":["post-6170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-automobile","category-automobile"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/6170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=6170"}],"version-history":[{"count":0,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/6170\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/6176"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=6170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=6170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=6170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}