<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Warning</b>:  Cannot modify header information - headers already sent by (output started at /var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php:129) in <b>/var/www/html/web/wp/wp-includes/rest-api/class-wp-rest-server.php</b> on line <b>1896</b><br />
<br />
<b>Warning</b>:  Cannot modify header information - headers already sent by (output started at /var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php:129) in <b>/var/www/html/web/wp/wp-includes/rest-api/class-wp-rest-server.php</b> on line <b>1896</b><br />
{"id":6217,"date":"2018-11-19T16:29:45","date_gmt":"2018-11-19T15:29:45","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=6217"},"modified":"2024-09-06T17:10:48","modified_gmt":"2024-09-06T15:10:48","slug":"controle-technique-plus-severe-janvier","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/actualites-automobile\/controle-technique-plus-severe-janvier\/","title":{"rendered":"Vers un nouveau durcissement du contr\u00f4le technique"},"content":{"rendered":"<p>Vous vous souvenez du durcissement du contr\u00f4le technique de mai 2018\u00a0? Ce n\u2019est pas termine\u0301 : <strong>u<\/strong><strong>ne nouvelle re\u0301forme arrive le 1<sup>er<\/sup> janvier 2019 !<\/strong><\/p>\n<p>Cela fait de\u0301sormais plus de 6 mois que le contr\u00f4le technique est passe\u0301 de 123 a\u0300 133 points de contr\u00f4le et pourtant il se fera encore plus se\u0301v\u00e8re, principalement pour les diesels.<\/p>\n<h2><span style=\"color: #64e600\">Quels seront les nouveaux points de contr\u00f4le\u00a0?<\/span><\/h2>\n<p>A partir de janvier prochain, la lutte s\u2019intensifie contre les diesels trop polluants. Et c\u2019est <strong>l\u2019opacite\u0301 des fume\u0301es e\u0301mises par l\u2019e\u0301chappement qui sera passe\u0301e au crible<\/strong>. Tout ceci est mis en place dans un but e\u0301cologique, afin de de\u0301tecter davantage les e\u0301missions de particules fines.<\/p>\n<p><a href=\"https:\/\/medias.csi.int.coyotesystems.com\/wordpress\/2018\/11\/2018-11-19.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6236 size-medium alignleft\" src=\"https:\/\/medias.csi.int.coyotesystems.com\/wordpress\/2018\/11\/2018-11-19-300x273.jpg\" alt=\"nouveau contr\u00f4le technique\" width=\"300\" height=\"273\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2018\/11\/2018-11-19-300x273.jpg 300w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2018\/11\/2018-11-19-1024x933.jpg 1024w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2018\/11\/2018-11-19-768x700.jpg 768w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2018\/11\/2018-11-19.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>De plus, les <strong>seuils de tole\u0301rance vont \u00eatre abaisse\u0301s<\/strong> <strong>et seront similaires aux valeurs d\u2019homologation<\/strong>, valables au moment de la mise en circulation du ve\u0301hicule.<\/p>\n<p>Plusieurs polluants e\u0301mis par les moteurs a\u0300 essence seront e\u0301galement contr\u00f4le\u0301s et plus se\u0301v\u00e8rement sanctionne\u0301s si leurs taux sont trop e\u0301leve\u0301s.<\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"color: #64e600\">Qui sera concerne\u0301 par ce nouveau contr\u00f4le technique ? <\/span><\/h2>\n<p>Tous les ve\u0301hicules juge\u0301s trop polluants auront l\u2019obligation d\u2019effectuer des re\u0301parations et de se soumettre a\u0300 une contre-visite, qui pourrait concerner 15% des ve\u0301hicules.<\/p>\n<p><strong>Les premiers touche\u0301s par ce nouveau durcissement seront sans surprise les anciens diesels<\/strong>. Certains pourraient e\u0301ventuellement ne pas \u00eatre en mesure d\u2019\u00eatre re\u0301pare\u0301s, car utilisant des technologies trop anciennes pour respecter les e\u0301missions de pollution actuelles.<\/p>\n<p><strong>Ne\u0301anmoins, les ve\u0301hicules re\u0301cents roulant au gazole pourront \u00eatre impacte\u0301s e\u0301galement\u00a0! <\/strong>En effet, s\u2019ils ont e\u0301te\u0301 mal entretenus ou ne roulent tout simplement pas assez, le filtre a\u0300 particules, la vanne EGR ou encore le turbo peuvent \u00eatre encrasse\u0301s, e\u0301mettant trop de particules fines.<\/p>\n<p>Actuellement, seulement 1% des ve\u0301hicules sont recale\u0301s au contr\u00f4le technique pour cause de pollution. Selon certains calculs, ce chiffre devrait atteindre 5 a\u0300 7%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous vous souvenez du durcissement du contr\u00f4le technique de mai 2018\u00a0? Ce n\u2019est pas termine\u0301 : une nouvelle re\u0301forme arrive [&hellip;]<\/p>\n","protected":false},"author":136,"featured_media":6230,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,12],"tags":[],"class_list":["post-6217","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-automobile","category-automobile"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/6217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/136"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=6217"}],"version-history":[{"count":1,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/6217\/revisions"}],"predecessor-version":[{"id":13254,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/6217\/revisions\/13254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/6230"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=6217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=6217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=6217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}