{"id":6222,"date":"2018-11-19T15:49:44","date_gmt":"2018-11-19T14:49:44","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=6222"},"modified":"2024-09-06T17:10:49","modified_gmt":"2024-09-06T15:10:49","slug":"bilan-etat-routes-nationales-francaise","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/actualites-securite-routiere\/bilan-etat-routes-nationales-francaise\/","title":{"rendered":"Etat des routes fran\u00e7aises : le bilan"},"content":{"rendered":"<p>Le Minist\u00e8re des Transport, a\u0300 l\u2019occasion des Assises Nationales de la Mobilite\u0301, a commande\u0301 aux cabinets Nibuxs et IMDM, une e\u0301tude de l\u2019e\u0301tat des routes nationales.<\/p>\n<p>Elle de\u0301voile un inquie\u0301tant bilan\u2026<\/p>\n<h2><span style=\"color: #64e600\">Un audit de l\u2019e\u0301tat des routes commande\u0301 par le Gouvernement<\/span><\/h2>\n<p>Cet audit concerne les routes non conce\u0301de\u0301es, dont l\u2019e\u0301tat fran\u00e7ais est proprie\u0301taire et responsable de l\u2019entretien.<\/p>\n<p>Il a pour but d\u2019aider l\u2019Etat a\u0300 <strong>de\u0301finir une strate\u0301gie d\u2019entretien et de re\u0301novation du re\u0301seau routier<\/strong> a\u0300 court, moyen et long terme.<\/p>\n<p>Il s\u2019agit d\u2019un <strong>re\u0301seau long de<\/strong> <strong>21\u00a0000 km (9000 km d\u2019autoroutes et 12\u00a0000 km de routes) o\u00f9 se concentre 18.5% du trafic. <\/strong>Il est emprunte\u0301 chaque jour par<strong> plus de 4 millions de personnes.<\/strong><\/p>\n<p>Cela en fait le premier patrimoine de l\u2019Etat, d\u2019une valeur de <strong>140 milliards d\u2019euros.<\/strong><\/p>\n<h2><span style=\"color: #64e600\">17% des routes ne\u0301cessitent des re\u0301parations structurelles<\/span><\/h2>\n<p>Les chausse\u0301es se de\u0301gradent de mani\u00e8re ine\u0301vitable sous l\u2019effet du trafic et des conditions climatiques. <strong>On peut classer les de\u0301gradations les plus courantes en deux grandes cate\u0301gories\u00a0: superficielles et structurelles.<\/strong> Les premi\u00e8res apparaissent au niveau de la couche de surface de la chausse\u0301e et sont en ge\u0301ne\u0301ral de petites fissures ou une le\u0301g\u00e8re usure de la couche de roulement. Elles affectent en premier lieu le confort et l\u2019adhe\u0301rence.<\/p>\n<p>En revanche, les de\u0301gradations structurelles apparaissent dans la structure m\u00eame de la route et sont, elles, re\u0301ellement dangereuses. Il s\u2019agit par exemple de nids de poules, de fissures profondes, de fa\u00efen\u00e7ages ou encore d\u2019affaissements.<\/p>\n<p><strong>Plus de la moitie\u0301 des chausse\u0301es exigent des re\u0301parations depuis 2012, dont 17% des re\u0301parations structurelles, soit 2040 km de routes.<\/strong><\/p>\n<h2><span style=\"color: #64e600\">1 pont sur 3 a\u0300 re\u0301parer<\/span><\/h2>\n<p><strong>Les Ouvrages d\u2019Art ne sont pas exempts de ce constat alarmant et demandent eux aussi des re\u0301parations urgentes<\/strong>. Le re\u0301seau routier fran\u00e7ais non-conce\u0301de\u0301 compte pas moins de 12\u00a0000 ponts, dont plus de 30% ne\u0301cessitent des travaux. A noter que <strong>7% de ces ponts pre\u0301sentent un risque d\u2019effondrement<\/strong> et pourraient \u00eatre ferme\u0301s de mani\u00e8re pre\u0301ventive. Or, un pont du re\u0301seau routier national ne se voit re\u0301pare\u0301 qu\u2019en moyenne 22 ans apr\u00e8s les premi\u00e8res de\u0301gradations\u2026<\/p>\n<h2><span style=\"color: #64e600\">Des budgets fluctuants et insuffisants<\/span><\/h2>\n<p>En moyenne, l\u2019Etat a de\u0301pense\u0301 <strong>666 millions d\u2019euros par an, soit 50\u00a0000 euros par an et par kilom\u00e8tre de route<\/strong>, depuis une dizaine d\u2019anne\u0301es pour l\u2019entretien et la gestion du re\u0301seau routier non-conce\u0301de\u0301. Ces budgets se sont ave\u0301re\u0301s bien insuffisants pour entretenir la totalite\u0301 du re\u0301seau\u2026<\/p>\n<p><strong>Selon les cabinets charge\u0301s de l\u2019e\u0301tude, si on continue a\u0300 de\u0301penser 666 millions par an pendant les 4 prochaines anne\u0301es, il faudra ensuite de\u0301penser 1.3 milliard d\u2019euros par an pendant 15 ans pour que le re\u0301seau retrouve son e\u0301tat actuel.<\/strong><\/p>\n<p><strong>\u00a0<\/strong>Une hausse des budgets va donc se montrer plus que ne\u0301cessaire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Minist\u00e8re des Transport, a\u0300 l\u2019occasion des Assises Nationales de la Mobilite\u0301, a commande\u0301 aux cabinets Nibuxs et IMDM, une [&hellip;]<\/p>\n","protected":false},"author":136,"featured_media":6225,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[26,30],"tags":[],"class_list":["post-6222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-securite-routiere","category-securite-routiere"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/6222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/136"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=6222"}],"version-history":[{"count":1,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/6222\/revisions"}],"predecessor-version":[{"id":13256,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/6222\/revisions\/13256"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/6225"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=6222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=6222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=6222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}