{"id":6273,"date":"2018-12-26T10:45:37","date_gmt":"2018-12-26T09:45:37","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=6273"},"modified":"2018-12-26T10:45:37","modified_gmt":"2018-12-26T09:45:37","slug":"etat-des-lieux-de-lauto-partage-en-france","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/actualites-automobile\/etat-des-lieux-de-lauto-partage-en-france\/","title":{"rendered":"Etat des lieux de l\u2019auto-partage en France"},"content":{"rendered":"<p>L\u2019usage de l\u2019autopartage, ou <em>carsharing<\/em> en anglais, est en plein essor. Le phe\u0301nom\u00e8ne est particuli\u00e8rement remarquable dans les zones urbaines, o\u00f9 la voiture est un embarras et les transports en commun p\u00e8sent a\u0300 la longue. Et le concept e\u0301volue pour satisfaire les pre\u0301fe\u0301rences de chacun en termes de mobilite\u0301\u00a0: ve\u0301lo, voiture, scooter\u2026<\/p>\n<h2 style=\"color: #64e600\">Comment fonctionne l\u2019auto-partage\u00a0?<\/h2>\n<p>Le principe d\u2019autopartage est simple\u00a0: des voitures sont parque\u0301es a\u0300 des endroits-cle\u0301s d\u2019une ville. Pour en utiliser une, il suffit de se rendre a\u0300 une borne sur l\u2019un des parkings d\u2019autopartage, sur le site ou l\u2019application (selon les villes), de re\u0301server son ve\u0301hicule et de le louer pour quelques euros par mois. Deux types d\u2019autopartage sont propose\u0301s par les socie\u0301te\u0301s\u00a0:<\/p>\n<ul>\n<li>Le service en trajet libre\u00a0: au volant d\u2019un mod\u00e8le unique, a\u0300 vous de trouver votre place mais pas besoin de revenir au point de de\u0301part pour rendre le ve\u0301hicule.<\/li>\n<li>Le service en boucle\u00a0: offrant le choix parmi plusieurs mod\u00e8les, ce service requiert toutefois de revenir a\u0300 l\u2019endroit de de\u0301part apr\u00e8s sa course.<\/li>\n<\/ul>\n<p>Les prix pratique\u0301s de\u0301pendent bien entendu du type de service choisi mais aussi de la ville, de la motorisation, du type de ve\u0301hicule ou encore de la fre\u0301quence d\u2019utilisation (tarifs de\u0301gressifs).<\/p>\n<p>Si la formule d\u2019abonnement peut encore rebuter les consommateurs, cela comprend tout de m\u00eame les frais d\u2019assurance, d\u2019entretien, de carburant, de parking, etc. Tout ce que l\u2019on e\u0301conomise si l\u2019on n\u2019a pas de voiture a\u0300 temps plein.<\/p>\n<p>Enfin, il est e\u0301galement possible de faire de l\u2019autopartage entre particuliers, la\u0300 aussi par le biais de prestataires qui permettent de faire le lien entre proprie\u0301taires de ve\u0301hicules et locataire. Toujours gr\u00e2ce a\u0300 une plateforme en ligne ou une application mobile, on peut louer un ve\u0301hicule a\u0300 l\u2019heure ou a\u0300 la journe\u0301e, puis le rendre au point de de\u0301part avec le m\u00eame niveau de carburant.<\/p>\n<h2 style=\"color: #64e600\">Comment s\u2019articulent les diffe\u0301rentes offres\u00a0?<\/h2>\n<p>La re\u0301gion parisienne est particuli\u00e8rement sensibilise\u0301e a\u0300 l\u2019autopartage apr\u00e8s la participation aux premiers tests d\u2019Autolib d\u00e8s 2011. Aujourd\u2019hui, et depuis le 1<sup>er<\/sup> ao\u00fbt 2018, ce ne sont pas moins de 100\u00a0000 abonne\u0301s Autolib que le service d\u2019autopartage de\u0301ficitaire laisse derri\u00e8re lui, apr\u00e8s la rupture de contrat entre la firme de Vincent Bollore\u0301 et de la Ville de Paris.<\/p>\n<p>L\u2019autopartage parisien ne s\u2019arr\u00eate pas pour autant a\u0300 la de\u0301faite d\u2019Autolib. Une des flottes les plus fournies parmi les alternatives les plus proches d\u2019Autolib est celle d\u2019Ubeeqo, appartenant a\u0300 Europcar depuis 2015, qui a mis plus de 300 ve\u0301hicules en libre-service dans la capitale. Du c\u00f4te\u0301 de l\u2019autopartage en boucle, on retrouve Communauto, avec 150 ve\u0301hicules (Clio, Kangoo, Yaris, citadines de Mercedes, Prius\u2026).<\/p>\n<p>Mais ces nouveaux acteurs ne sont pas les seuls a\u0300 pouvoir se positionner sur un marche\u0301 de\u0301sormais ouvert et en pleine croissance. En effet, les constructeurs automobiles sont susceptibles de profiter de cette place a\u0300 prendre pour faire rouler leurs mod\u00e8les (comme le fait Renault a\u0300 Madrid par exemple, avec son mod\u00e8le e\u0301lectrique Zoe\u0301) tout comme les socie\u0301te\u0301s de location de voitures classiques\u00a0! Car ces entreprises s\u2019y connaissent parfaitement dans le domaine\u00a0; il ne leur reste qu\u2019a\u0300 digitaliser leur offre pour certains, voire retravailler les tarifs pratique\u0301s, bien au-dessus des nouveaux services d\u2019autopartage.<\/p>\n<p>Cependant, l\u2019autopartage n\u2019est pas re\u0301serve\u0301 a\u0300 la capitale. Lyon, par exemple, be\u0301ne\u0301ficie du service Bluely, qui propose une flotte de 300 ve\u0301hicules e\u0301lectriques a\u0300 bo\u00eete automatique, disponibles dans plus de 100 stations implante\u0301es a\u0300 Lyon et dans sa pe\u0301riphe\u0301rie. Bordeaux dispose d\u2019une offre similaire, lance\u0301e par la socie\u0301te\u0301 Citiz, pre\u0301sente sur tout le territoire. Baptise\u0301 Yea!, ce service propose e\u0301galement de faire des trajets plus longs, pour partir en vacances par exemple.<\/p>\n<p style=\"text-align: center\">Pensez a\u0300 emporter <a href=\"https:\/\/business.moncoyote.com\/coyote-mini.html\" target=\"_blank\" rel=\"noopener\">votre bo\u00eetier Coyote<\/a> partout avec vous\u00a0!<em><br \/>\n<\/em><\/p>\n<h2 class=\"fig-main-title\"><span style=\"color: #ffb400\">Sondage : utilisez-vous un service d&rsquo;autopartage ?<\/span><\/h2>\n<p>[totalpoll id=\u00a0\u00bb6274&Prime;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019usage de l\u2019autopartage, ou carsharing en anglais, est en plein essor. Le phe\u0301nom\u00e8ne est particuli\u00e8rement remarquable dans les zones urbaines, [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":6277,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-6273","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-automobile"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/6273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=6273"}],"version-history":[{"count":0,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/6273\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/6277"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=6273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=6273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=6273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}