{"id":7271,"date":"2019-07-12T10:12:40","date_gmt":"2019-07-12T08:12:40","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=7271"},"modified":"2019-07-12T10:12:40","modified_gmt":"2019-07-12T08:12:40","slug":"les-drones-policiers-en-france","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/actualites-securite-routiere\/les-drones-policiers-en-france\/","title":{"rendered":"Les drones policiers en France"},"content":{"rendered":"<p>Surveiller les automobilistes avec des drones, de la science-fiction\u00a0? Plus aujourd\u2019hui\u00a0! Les premiers contr\u00f4les de ce genre ont eu lieu en mai dernier sur l\u2019autoroute A126, en re\u0301gion \u00cele-de-France.<\/p>\n<p>Coyote vous en dit plus sur cette nouvelle mani\u00e8re de surveiller les automobilistes.<\/p>\n<h2 style=\"color: #64e600\">Quelles sont les infractions repe\u0301re\u0301es\u00a0?<\/h2>\n<p>Lors de cet essai re\u0301alise\u0301 en Essonne, ce sont les infractions commises par les motards qui ont e\u0301te\u0301 cible\u0301es. En effet, bien qu\u2019ils ne constituent que 5% du volume total du trafic, les motards repre\u0301sentent pourtant 54% des tue\u0301s sur la route dans le de\u0301partement.<\/p>\n<p>La portion de route choisie n\u2019a elle aussi pas e\u0301te\u0301 se\u0301lectionne\u0301e au hasard\u00a0: tr\u00e8s e\u0301troite et dangereuse, elle a e\u0301te\u0301 le the\u0301\u00e2tre de sept accidents mortels en l\u2019espace de dix ans.<\/p>\n<p>Gr\u00e2ce aux drones, les forces de l\u2019ordre ont ainsi releve\u0301 tous les franchissements de ligne blanche continue commis par des conducteurs de deux-roues. 64 infractions, dont 34 franchissements de ligne, ont e\u0301te\u0301 repe\u0301re\u0301s en moins de deux heures, avec a\u0300 la cle\u0301 une amende forfaitaire de 135 \u20ac pour les motards et trois points en moins sur leur permis\u00a0!<\/p>\n<h2 style=\"color: #64e600\">Comment fonctionnent les contr\u00f4les routiers par drones\u00a0?<\/h2>\n<p>L\u2019e\u0301troitesse de la route surveille\u0301e emp\u00eache habituellement les policiers de se placer sur le bas-c\u00f4te\u0301 pour proce\u0301der a\u0300 des contr\u00f4les. Il leur suffit de\u0301sormais de se poster quelques kilom\u00e8tres plus loin, afin de surveiller les images retransmises en direct par les drones pilote\u0301s a\u0300 distance.<\/p>\n<p>D\u00e8s qu\u2019une infraction est repe\u0301re\u0301e, l\u2019information est imme\u0301diatement donne\u0301e aux policiers charge\u0301s d\u2019interpeller les motards, qui les attendent a\u0300 proximite\u0301. La plupart des conducteurs de deux-roues arr\u00eate\u0301s ont e\u0301te\u0301 assez e\u0301tonne\u0301s d\u2019avoir e\u0301te\u0301 pris sur le fait par un drone\u00a0: l\u2019engin vole en effet a\u0300 une trentaine de m\u00e8tres de hauteur, il est donc difficilement repe\u0301rable depuis la route.<\/p>\n<p>Sources\u00a0: <a href=\"https:\/\/www.francetvinfo.fr\/\">France Info<\/a> et <a href=\"https:\/\/www.ouest-france.fr\/\">Ouest-France<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Surveiller les automobilistes avec des drones, de la science-fiction\u00a0? Plus aujourd\u2019hui\u00a0! Les premiers contr\u00f4les de ce genre ont eu lieu [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":7272,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[26,32],"tags":[],"class_list":["post-7271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-securite-routiere","category-innovation"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/7271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=7271"}],"version-history":[{"count":0,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/7271\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/7272"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=7271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=7271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=7271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}