{"id":7408,"date":"2021-11-04T10:27:38","date_gmt":"2021-11-04T09:27:38","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=7408"},"modified":"2021-11-04T10:27:38","modified_gmt":"2021-11-04T09:27:38","slug":"pneus-neige-obligatoires-a-compter-du-1112019-ce-quil-faut-savoir","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/reglementation-routiere\/pneus-neige-obligatoires-a-compter-du-1112019-ce-quil-faut-savoir\/","title":{"rendered":"Pneus neige obligatoires : quelle application ?"},"content":{"rendered":"<p>En octobre 2018, le Conseil National de la Montagne (CNM) s\u2019e\u0301tait entretenu avec le Premier Ministre a\u0300 propos de la se\u0301curite\u0301 routi\u00e8re dans les zones montagneuses fran\u00e7aises. Le de\u0301cret imposant les pneus hiver en montagne e\u0301tait entre\u0301 en vigueur en octobre 2020, mais s\u2019applique a\u0300 partir du 1er novembre 2021. Voici tout ce que vous devez savoir sur cette nouvelle loi.<\/p>\n<h2 style=\"color: #64e600\">Pneus neige : pourquoi une loi maintenant ?<\/h2>\n<p>Chaque anne\u0301e, la pe\u0301riode hivernale voit son lot d\u2019accidents de la route : voitures immobilise\u0301es, sorties de route, carambolages\u2026 Face aux risques lie\u0301s aux conditions me\u0301te\u0301orologiques, l\u2019Etat a donc de\u0301cide\u0301 d\u2019agir en renfor\u00e7ant les dispositions de\u0301ja\u0300 pre\u0301vues par le Code de la route.<\/p>\n<p>Cette nouvelle mesure permettra e\u0301galement de fluidifier la circulation lors des saisons froides. Chaque hiver, des axes routiers sont paralyse\u0301s : en octobre 2018, plus de six-cents conducteurs se sont fait surprendre par la neige et sont reste\u0301s bloque\u0301s toute une nuit sur les routes de Saint-Etienne.<br \/>\nLes proprie\u0301taires de notre GPS connecte\u0301 Coyote avaient pu \u00eatre informe\u0301s en temps re\u0301el sur les conditions extr\u00eames du trafic.<\/p>\n<p>En rendant les pneus hiver obligatoires, la France rattrape enfin son retard. Nos voisins europe\u0301ens, comme l\u2019Allemagne, l\u2019Autriche ou encore l\u2019Italie, avaient de\u0301ja\u0300 franchi le pas depuis longtemps\u2026<\/p>\n<h2 style=\"color: #64e600\">Pneus hiver obligatoires : qui est concerne\u0301 ?<\/h2>\n<p>Du 1er novembre jusqu\u2019au 31 mars 2022, tous les automobilistes circulant dans les zones re\u0301glemente\u0301es devront re\u0301pondre a\u0300 la loi, qu\u2019ils soient habitants du coin ou simples vacanciers.<\/p>\n<p>La mesure concerne de nombreuses communes des massifs montagneux (Alpes, Corse, Massif central\u2026) re\u0301parties sur 34 de\u0301partements. Vous pouvez <a href=\"https:\/\/www.securite-routiere.gouv.fr\/sites\/default\/files\/2021-12\/211207_liste_communes_equipements_hivernaux.xlsx\">te\u0301le\u0301charger la liste des communes concerne\u0301es<\/a> afin de savoir si vous \u00eates soumis a\u0300 l\u2019obligation d\u2019e\u0301quipement.<\/p>\n<p>Par ailleurs, de nouveaux panneaux de signalisation (B58 et B59) indiquent aux automobilistes le de\u0301but et la fin de la zone d\u2019obligation d\u2019e\u0301quipement en pe\u0301riode hivernale. Le panneau de signalisation B26 mentionne l\u2019obligation de porter des cha\u00eenes sur certaines routes enneige\u0301es continue d\u2019exister.<\/p>\n<p>Les conducteurs qui manqueront de s\u2019e\u0301quiper de <a href=\"https:\/\/www.moncoyote.com\/blog\/securite-routiere\/reglementation-routiere\/pneus-neige-obligatoires-a-compter-du-1112019-ce-quil-faut-savoir\/\">pneus neige<\/a> seront soumis a\u0300 <strong>une amende de 135 euros<\/strong>, et a\u0300<strong> l\u2019immobilisation imme\u0301diate de leur ve\u0301hicule<\/strong>.<\/p>\n<p>Cependant, il y aura eu une tole\u0301rance pour 2021 : le Minist\u00e8re de l\u2019Inte\u0301rieur annonce que \u00ab les e\u0301ventuels manquements a\u0300 l\u2019obligation de de\u0301tenir des cha\u00eenes a\u0300 neige dans son coffre ou d\u2019e\u0301quiper son ve\u0301hicule de pneus hiver dans les de\u0301partements concerne\u0301s ne seront pas sanctionne\u0301s cet hiver \u00bb.<\/p>\n<p>Toutefois, mieux vaut donc de ne pas faire l\u2019impasse sur ce nouveau dispositif de se\u0301curite\u0301, et anticiper cet achat.<\/p>\n<h2 style=\"color: #64e600\">Quel e\u0301quipement afin d\u2019\u00eatre en r\u00e8gle ?<\/h2>\n<p>Il y a deux options afin d\u2019\u00eatre en r\u00e8gle face a\u0300 cette nouvelle mesure, vous pouvez soit :<\/p>\n<ul>\n<li>Avoir au moins deux cha\u00eenes (ou autres dispositifs antide\u0301rapants e\u0301quivalents) dans votre coffre ;<\/li>\n<li>Equiper votre ve\u0301hicule de 4 pneus hiver.<\/li>\n<\/ul>\n<p>Si vous optez pour les pneus hiver, pensez a\u0300 bien les choisir ! Dans un premier temps, du 1er novembre 2021 au 31 mars 2024, la loi reconna\u00eetra encore les pneus hiver marque\u0301s \u00ab M+S \u00bb, \u00ab M.S \u00bb ou \u00ab M&amp;S \u00bb.<\/p>\n<p>A partir du 1er novembre 2024, <strong>il s\u2019agira uniquement des pneus alpins<\/strong>, \u00ab identifie\u0301s par la pre\u0301sence conjointe du marquage \u00ab symbole alpin \u00bb (reconnu sous l\u2019appellation \u00ab 3PMSF \u00bb et de l\u2019un des marquages \u00ab M+S \u00bb, \u00ab M.S \u00bb ou \u00ab M&amp;S \u00bb pre\u0301cise le gouvernement.<\/p>\n<p>Si cette loi force la plupart des automobilistes fran\u00e7ais a\u0300 acheter l\u2019e\u0301quipement ne\u0301cessaire, elle est la bienvenue dans les re\u0301gions les plus expose\u0301es au froid afin de re\u0301duire entre autres les risques d\u2019accident. Cet hiver, vous pourrez donc vous de\u0301placer l\u2019esprit plus serein, sans craindre les routes impraticables, le verglas et la neige.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En octobre 2018, le Conseil National de la Montagne (CNM) s\u2019e\u0301tait entretenu avec le Premier Ministre a\u0300 propos de la [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":7409,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-7408","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reglementation-routiere"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/7408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=7408"}],"version-history":[{"count":0,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/7408\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/7409"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=7408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=7408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=7408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}