<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Warning</b>:  Cannot modify header information - headers already sent by (output started at /var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php:129) in <b>/var/www/html/web/wp/wp-includes/rest-api/class-wp-rest-server.php</b> on line <b>1896</b><br />
<br />
<b>Warning</b>:  Cannot modify header information - headers already sent by (output started at /var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php:129) in <b>/var/www/html/web/wp/wp-includes/rest-api/class-wp-rest-server.php</b> on line <b>1896</b><br />
{"id":807,"date":"2016-05-19T13:34:30","date_gmt":"2016-05-19T12:34:30","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=807"},"modified":"2016-05-19T13:34:30","modified_gmt":"2016-05-19T12:34:30","slug":"chrystelle-responsable-des-accessoires","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/interviews\/chrystelle-responsable-des-accessoires\/","title":{"rendered":"Parole de Coyote : Chrystelle, Responsable des accessoires chez Coyote"},"content":{"rendered":"<p><span style=\"color: #8bbf00\"><em>En mai, nous sommes alle\u0301s a\u0300 la rencontre de Chrystelle, Responsable des Accessoires chez Coyote. Son parcours, ses missions et ses nouveaute\u0301s sont a\u0300 de\u0301couvrir sans plus attendre dans notre portrait du mois\u00a0!<\/em><\/span><\/p>\n<p style=\"text-align: justify\"><strong>Salut Chrystelle\u00a0! Peux-tu tout d\u2019abord te pre\u0301senter a\u0300 la Communaute\u0301 en quelques mots ?<\/strong><\/p>\n<p style=\"text-align: justify\">Bonjour\u00a0! Je suis Chrystelle, je travaille chez Coyote depuis maintenant 1 an et suis en charge d\u2019<span style=\"color: #8bbf00\">imaginer, de concevoir et de commercialiser<\/span>\u00a0les accessoires pour nos bo\u00eetiers.<\/p>\n<p style=\"text-align: justify\"><strong>En quoi consistent tes missions chez Coyote\u00a0? <\/strong><\/p>\n<p style=\"text-align: justify\">Je g\u00e8re de A a\u0300 Z notre gamme d&rsquo;accessoires de la fabrication a\u0300 la commercialisation. Je commence tout d&rsquo;abord par <span style=\"color: #8bbf00\">analyser le\u00a0marche\u0301<\/span>\u00a0pour de\u0301gager les grandes tendances mais aussi et surtout, <span style=\"color: #8bbf00\">les attentes de la Communaute\u0301<\/span> en mati\u00e8re d&rsquo;accessoires. D\u00e8s que j&rsquo;ai identifie\u0301 un besoin, je travaille sur une esquisse de l&rsquo;accessoire voulu avec nos designers. Une fois que nos croquis\u00a0sont finalise\u0301s, je lance la <span style=\"color: #8bbf00\">production d&rsquo;un e\u0301chantillon<\/span> aupr\u00e8s de notre fabricant. Apr\u00e8s re\u0301ception, nous <span style=\"color: #8bbf00\">testons ce prototype<\/span> afin de ve\u0301rifier que celui-ci re\u0301ponde a\u0300 toutes nos attentes tant d&rsquo;un point de vue fonctionnel que qualitatif. Si les re\u0301sultats des tests sont concluants, je demande\u00a0alors a\u0300 notre fabricant de produire l&rsquo;accessoire pour la Communaute\u0301. Si non, je modifie alors le prototype afin qu&rsquo;il corresponde parfaitement a\u0300 nos attentes. Enfin, d\u00e8s que nos stocks sont approvisionne\u0301s, je mets a\u0300 disposition\u00a0notre produit dans l&rsquo;ensemble de nos\u00a0points de vente : site internet, boutiques Coyote Store et chez nos distributeurs.<\/p>\n<p style=\"text-align: justify\"><strong>Selon toi, quel est le r\u00f4le des accessoires pour nos bo\u00eetiers\u00a0? <\/strong><\/p>\n<p style=\"text-align: justify\">C\u2019est <span style=\"color: #8bbf00\">indispensable et indissociable<\/span>\u00a0! Pour \u00eatre utilise\u0301 de mani\u00e8re\u00a0optimale, un bo\u00eetier doit \u00eatre place\u0301 a\u0300 un endroit strate\u0301gique, a\u0300 la vue du conducteur mais aussi a\u0300 sa porte\u0301e pour pouvoir de\u0301clarer des e\u0301ventuelles alertes a\u0300 l&rsquo;ensemble de la Communaute\u0301. Il doit e\u0301galement pouvoir \u00eatre charge\u0301 pendant ou apr\u00e8s son utilisation. De plus, nos bo\u00eetiers sont de <span style=\"color: #8bbf00\">ve\u0301ritables condense\u0301s de technologie<\/span> qu\u2019il convient de les\u00a0<span style=\"color: #8bbf00\">prote\u0301ger\u00a0<\/span>!<\/p>\n<p style=\"text-align: justify\"><strong>Il semblerait qu\u2019un tout nouvel accessoire ait fait son apparition ce mois-ci sur notre site web, peux-tu nous en dire plus\u00a0?<\/strong><a title=\"accessoire moto fixation\" href=\"https:\/\/www.moncoyote.com\/fr\/tous-les-accessoires.html\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-829 size-medium\" title=\"Accessoire fixation moto\" src=\"https:\/\/medias.csi.int.coyotesystems.com\/wordpress\/2016\/05\/02-2-300x200.jpg\" alt=\"Accessoires moto\" width=\"300\" height=\"200\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2016\/05\/02-2-300x200.jpg 300w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2016\/05\/02-2-1024x683.jpg 1024w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2016\/05\/02-2-768x512.jpg 768w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2016\/05\/02-2.jpg 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify\">Tout a\u0300 fait\u00a0! Nous venons de lancer un <strong><a title=\"Coyote Mini sur moto\" href=\"https:\/\/www.moncoyote.com\/fr\/tous-les-accessoires.html\">support de fixation pour guidon<\/a><\/strong>, <span style=\"color: #8bbf00\">compatible moto et scooter<\/span>\u00a0! Pour <strong>69,90\u20ac<\/strong>, tous les motards de la Communaute\u0301 peuvent de\u0301sormais utiliser le <strong><a title=\"Fixez votre Coyote sur une moto\" href=\"https:\/\/www.moncoyote.com\/fr\/product\/418\/COYOTE-mini.html\">Coyote mini<\/a> <\/strong>sur leurs 2 roues, en toute se\u0301curite\u0301. Ce kit rider est le re\u0301sultat de plusieurs mois de travail durant lesquels de nombreux tests en situation ont e\u0301te\u0301 mene\u0301s pour re\u0301pondre au mieux aux attentes de la Communaute\u0301. \u00a0Cet accessoire est compose\u0301 d\u2019une bo\u00eete e\u0301tanche, d\u2019un syst\u00e8me de fixation pour guidon tubulaire et d\u2019un second pour guidon non tubulaire.<\/p>\n<p style=\"text-align: justify\"><strong>Une derni\u00e8re information a\u0300 partager avec la Communaute\u0301\u00a0?<\/strong><\/p>\n<p style=\"text-align: justify\">De <span style=\"color: #8bbf00\">nouveaux\u00a0projets d\u2019accessoires<\/span> sont a\u0300 l\u2019e\u0301tude mais je ne peux vous en dire plus pour le moment\u00a0\ud83d\ude09<\/p>\n<p style=\"text-align: justify\"><em>Un grand\u00a0merci a\u0300 Chrystelle pour nous avoir de\u0301voile\u0301 tous ses secrets sur les accessoires ! D\u00e8s le mois prochain, vous pourrez retrouver notre nouveau portrait du mois. D&rsquo;ici la\u0300, bonne route avec Coyote \ud83d\ude42<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En mai, nous sommes alle\u0301s a\u0300 la rencontre de Chrystelle, Responsable des Accessoires chez Coyote. Son parcours, ses missions et [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":845,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-807","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-interviews","post_format-post-format-image"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=807"}],"version-history":[{"count":0,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/807\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/845"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}