<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Warning</b>:  Cannot modify header information - headers already sent by (output started at /var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php:129) in <b>/var/www/html/web/wp/wp-includes/rest-api/class-wp-rest-server.php</b> on line <b>1896</b><br />
<br />
<b>Warning</b>:  Cannot modify header information - headers already sent by (output started at /var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php:129) in <b>/var/www/html/web/wp/wp-includes/rest-api/class-wp-rest-server.php</b> on line <b>1896</b><br />
{"id":8090,"date":"2020-02-18T09:56:29","date_gmt":"2020-02-18T08:56:29","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=8090"},"modified":"2020-02-18T09:56:29","modified_gmt":"2020-02-18T08:56:29","slug":"volkswagen-travaille-sur-un-projet-de-robot-chargeur-de-voitures-electriques","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/innovation\/volkswagen-travaille-sur-un-projet-de-robot-chargeur-de-voitures-electriques\/","title":{"rendered":"Volkswagen travaille sur un projet de robot chargeur de voitures e\u0301lectriques"},"content":{"rendered":"\n<p>Un bras articule\u0301, une communication via une application, un\ndesign sympathique&nbsp;: Volkswagen a re\u0301cemment annonce\u0301 travailler sur un\nprototype de robot chargeur de voitures e\u0301lectriques. Le projet est alle\u0301chant,\nsurtout quand on conna\u00eet les probl\u00e8mes auxquels font face actuellement les\nbornes de recharge fixes.<\/p>\n\n\n\n<h2 style=\"color: #64e600\">Un Wall-e des parkings pour recharger les batteries de votre voiture<\/h2>\n\n\n\n<p>De\u0301ja\u0300 has-been les bornes de recharges e\u0301lectriques\nclassiques&nbsp;? C\u2019est ce que Volkswagen pre\u0301dit pour le futur de la voiture\ne\u0301lectrique.<\/p>\n\n\n\n<p>Pour simplifier la vie des conducteurs, la firme a imagine\u0301 un petit robot autonome qui s\u2019occupe tout seul du rechargement des batteries lorsque la voiture est gare\u0301e dans un parking. Pour cela, il suffira de demander la charge de sa voiture via une application. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"375\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2020\/02\/volkswagen-robot-autonome.jpg\" alt=\"\" class=\"wp-image-8092\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2020\/02\/volkswagen-robot-autonome.jpg 750w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2020\/02\/volkswagen-robot-autonome-300x150.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption>Cre\u0301dits : SP\/Volkswagen<\/figcaption><\/figure>\n\n\n\n<p>Le robot se saisit alors d\u2019un module de charge qu\u2019il vient brancher\net placer a\u0300 c\u00f4te\u0301 de la voiture. Le robot laisse le module en place pendant tout\nle temps de rechargement et peut donc s\u2019occuper de plusieurs voitures en m\u00eame\ntemps. Une fois la batterie pleine, il enl\u00e8ve et range le module de charge et\npre\u0301vient le proprie\u0301taire que sa voiture est pr\u00eate a\u0300 \u00eatre utilise\u0301e.<\/p>\n\n\n\n<h2 style=\"color: #64e600\">Une solution pour recharger plus simplement sa voiture<\/h2>\n\n\n\n<p>Optimiser le chargement de sa voiture est une ne\u0301cessite\u0301 pour les automobilistes qui sont de plus en plus nombreux a\u0300 choisir une voiture e\u0301lectrique. Volkswagen n\u2019est pas le premier a\u0300 s\u2019attaquer au probl\u00e8me de la recharge. Tesla avait notamment pre\u0301sente\u0301 en 2015 un prototype de bras articule\u0301 capable de recharger en autonomie les voitures du constructeur. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2020\/02\/place-parking-electrique-1024x683.jpg\" alt=\"\" class=\"wp-image-8093\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2020\/02\/place-parking-electrique-1024x683.jpg 1024w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2020\/02\/place-parking-electrique-300x200.jpg 300w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2020\/02\/place-parking-electrique-768x512.jpg 768w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2020\/02\/place-parking-electrique-1536x1024.jpg 1536w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2020\/02\/place-parking-electrique-2048x1365.jpg 2048w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2020\/02\/place-parking-electrique-1568x1045.jpg 1568w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Autre solution envisage\u0301e&nbsp;: la recharge par induction de\nla voiture e\u0301lectrique. Si des syst\u00e8mes de recharge de ce type sont de\u0301ja\u0300\ninstalle\u0301s sur des places de parking (notamment sur le Campus de l\u2019EM Lyon), les\ninge\u0301nieurs souhaitent aller encore plus loin. Ils imaginent pour le futur de\npouvoir recharger des voitures en mouvement gr\u00e2ce a\u0300 l\u2019induction. Lorsqu\u2019on\nimagine une autoroute e\u0301quipe\u0301e de cette technologie on comprend tout l\u2019inte\u0301r\u00eat\nd\u2019une telle innovation.<\/p>\n\n\n\n<h2 style=\"color: #64e600\">Recharge des voiture e\u0301lectriques&nbsp;: une proble\u0301matique de plus en plus\npressante<\/h2>\n\n\n\n<p>Chaque anne\u0301e, les Fran\u00e7ais sont de plus en plus nombreux a\u0300\nse tourner vers les voitures e\u0301lectriques. En 2019 on comptait plus de\n40&nbsp;000 voitures e\u0301lectriques immatricule\u0301es en France, soit une augmentation\nde 27% par rapport a\u0300 2018<a href=\"#_ftn1\">[1]<\/a>.&nbsp; <\/p>\n\n\n\n<p>Mais le nombre de points de recharge (hors domicile) a du\nmal a\u0300 tenir le rythme, et les solutions mises en place laissent parfois a\u0300\nde\u0301sirer. En octobre 2019 il y avait 27&nbsp;745 bornes de recharge publiques en\nFrance, ce chiffre peut de\u0301ja\u0300 sembler inte\u0301ressant mais il faut rappeler\nplusieurs probl\u00e8mes&nbsp;: <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Certaines re\u0301gions font face a\u0300 un fort de\u0301ficit\nd\u2019implantation ;<\/li><li>De nombreuses places re\u0301serve\u0301es au rechargement\nsont occupe\u0301es par des voitures non-e\u0301lectriques&nbsp;;<\/li><li>Les pannes sont tr\u00e8s fre\u0301quentes sur les bornes\nde recharge, et quand la prochaine est a\u0300 80 km, c\u2019est proble\u0301matique&nbsp;;<\/li><li>Les temps de recharge sont longs et les\nemplacements peu se\u0301curise\u0301s.<\/li><\/ul>\n\n\n\n<p>Face a\u0300 ce constat, le robot de recharge de Volkswagen qui\nintervient peu importe o\u00f9 la voiture est gare\u0301e, prend tout son sens. Aucune\ndate de lancement pre\u0301vue pour ce projet qui est encore a\u0300 l\u2019e\u0301tape de prototype\net peut donc e\u0301voluer.<\/p>\n\n\n\n<p>Besoin d\u2019informations sur le trafic routier en temps en re\u0301el et des alertes personnalise\u0301es tout en en gardant les mains sur le volant ? Adoptez <a href=\"https:\/\/www.moncoyote.com\/fr\/product\/473\/COYOTE-UP.html\">le Coyote Up e\u0301quipe\u0301 d\u2019un assistant vocal<\/a> pour toujours plus de se\u0301curite\u0301.<br><\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<p><a href=\"#_ftnref1\">[1]<\/a> https:\/\/www.automobile-propre.com\/dossiers\/chiffres-vente-immatriculations-france\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un bras articule\u0301, une communication via une application, un design sympathique&nbsp;: Volkswagen a re\u0301cemment annonce\u0301 travailler sur un prototype de [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":8091,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[32],"tags":[],"class_list":["post-8090","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-innovation"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/8090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=8090"}],"version-history":[{"count":0,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/8090\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/8091"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=8090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=8090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=8090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}