{"id":8417,"date":"2020-08-27T09:47:10","date_gmt":"2020-08-27T07:47:10","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=8417"},"modified":"2020-08-27T09:47:10","modified_gmt":"2020-08-27T07:47:10","slug":"paris-bientot-la-mise-en-place-de-radars-de-covoiturage","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/radars\/paris-bientot-la-mise-en-place-de-radars-de-covoiturage\/","title":{"rendered":"Paris : bient\u00f4t la mise en place de radars de covoiturage"},"content":{"rendered":"<p>Mesure pre\u0301sente dans le programme pour les e\u0301lections municipales par Anne Hidalgo, la voie de gauche du pe\u0301riphe\u0301rique parisienne devrait bient\u00f4t \u00eatre de\u0301die\u0301e aux \u00ab mobilite\u0301s vertueuses \u00bb, entendues au covoiturage, aux ve\u0301hicules propres et aux transports en commun.<\/p>\n<h2 style=\"color: #64e600\">Radars de covoiturage : un de\u0301fi technologique<\/h2>\n<p>Comment s\u2019assurer qu\u2019une mesure comme la voie de gauche de\u0301die\u0301e aux \u00ab mobilite\u0301s vertueuses \u00bb sera respecte\u0301e ? C\u2019est la question que se pose actuellement la Ville de Paris. Pour y re\u0301pondre, plusieurs socie\u0301te\u0301s sont en train de plancher sur un tout nouveau type de radar. Cet e\u0301quipement devra \u00eatre capable de :<\/p>\n<ul>\n<li>De\u0301tecter le nombre d\u2019occupants d\u2019une voiture a\u0300 l\u2019avant et a\u0300 l\u2019arri\u00e8re ;<\/li>\n<li>Diffe\u0301rencier une personne d\u2019un mannequin ;<\/li>\n<li>Faire des cliche\u0301s des ve\u0301hicules ;<\/li>\n<li>Fonctionner jour et nuit ;<\/li>\n<li>Lire la plaque d\u2019immatriculation ;<\/li>\n<li>De\u0301tecter les passagers a\u0300 l\u2019arri\u00e8re d\u2019un deux-roues motorise\u0301 ;<\/li>\n<li>Repe\u0301rer la vignette Crit\u2019Air ou celle d\u2019un VTC.<\/li>\n<\/ul>\n<p>Ce nouveau radar devrait \u00eatre teste\u0301 d\u00e8s la rentre\u0301e au niveau de la porte de Montreuil pour ve\u0301rifier que les automobilistes circulant sur la voie de gauche ne sont pas seuls. L\u2019expe\u0301rimentation du radar de covoiturage permettra de tester en situation re\u0301elle cette technologie et d\u2019inciter les Franciliens a\u0300 ne plus voyager seuls dans leur automobile. Le projet parisien pourrait faire des e\u0301mules : les municipalite\u0301s de Lyon, Bordeaux et Lille cherchent elles aussi des solutions pour mettre en place la loi d\u2019orientation des mobilite\u0301s adopte\u0301e en de\u0301cembre 2019.<\/p>\n<h2 style=\"color: #64e600\">2024 : la voie de gauche pour les mobilite\u0301s vertueuses<\/h2>\n<p>Pour les Jeux olympiques de 2024, la mairie de Paris souhaite cre\u0301er une Olympic Lane sur les 35 kilom\u00e8tres du boulevard pe\u0301riphe\u0301rique afin de faciliter les de\u0301placements pour les athl\u00e8tes et les de\u0301le\u0301gations. Apr\u00e8s la manifestation, cette voie se transformerait en voie 100 % de\u0301die\u0301e aux mobilite\u0301s vertueuses.<\/p>\n<h2 style=\"color: #64e600\">Repenser le pe\u0301riphe\u0301rique parisien<\/h2>\n<p>Pollution, nuisances sonores, \u00ab fronti\u00e8re \u00bb entre Paris et ses communes limitrophes : le pe\u0301riphe\u0301rique parisien, inaugure\u0301 en 1973, est devenu un probl\u00e8me pour la Ville de Paris. Outre la voie de gauche re\u0301serve\u0301e au covoiturage, aux transports en commun et aux ve\u0301hicules, plusieurs sce\u0301narios sont envisage\u0301s comme :<\/p>\n<ul>\n<li>L\u2019abaissement de la vitesse a\u0300 50 km \/ h pour permettre aux cyclistes d\u2019en devenir usagers ;<\/li>\n<li>La ge\u0301ne\u0301ralisation de la couverture du pe\u0301riphe\u0301rique gr\u00e2ce a\u0300 des ope\u0301rations immobili\u00e8res comme cela avait e\u0301te\u0301 le cas dans les anne\u0301es 2000 au niveau des portes de Vanves, des Lilas et de Champerret.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Mesure pre\u0301sente dans le programme pour les e\u0301lections municipales par Anne Hidalgo, la voie de gauche du pe\u0301riphe\u0301rique parisienne devrait [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":8418,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-8417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-radars"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/8417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=8417"}],"version-history":[{"count":0,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/8417\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/8418"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=8417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=8417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=8417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}