<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Warning</b>:  Cannot modify header information - headers already sent by (output started at /var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php:129) in <b>/var/www/html/web/wp/wp-includes/rest-api/class-wp-rest-server.php</b> on line <b>1896</b><br />
<br />
<b>Warning</b>:  Cannot modify header information - headers already sent by (output started at /var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php:129) in <b>/var/www/html/web/wp/wp-includes/rest-api/class-wp-rest-server.php</b> on line <b>1896</b><br />
{"id":8545,"date":"2020-10-13T10:07:10","date_gmt":"2020-10-13T08:07:10","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=8545"},"modified":"2020-10-13T10:07:10","modified_gmt":"2020-10-13T08:07:10","slug":"les-motards-et-les-cyclistes-doivent-ils-porter-le-masque","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/reglementation-routiere\/les-motards-et-les-cyclistes-doivent-ils-porter-le-masque\/","title":{"rendered":"Les motards et les cyclistes doivent-ils porter le masque ?"},"content":{"rendered":"\n<p>Paris, Lyon, Toulouse, Nice, Marseille\u2026 La plupart des grandes villes fran\u00e7aises, et de plus en plus de petites communes, ont adopte\u0301 le port du masque dans la rue. Alors que la France fait face a\u0300 une augmentation rapide des cas de Covid-19, petit point sur ce que cette mesure va changer pour les usagers de la route.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"color: #64e600\"> Qui est concerne\u0301 par le port du masque dans la rue&nbsp;?<\/h2>\n\n\n\n<p>Si les mesures peuvent \u00eatre diffe\u0301rentes dans chaque ville,\nelles sont en re\u0301alite\u0301 tr\u00e8s similaires a\u0300 l\u2019e\u0301chelle de notre territoire. Ainsi la\nr\u00e8gle la plus re\u0301pandue est&nbsp;: toutes les personnes circulant dans la rue\ndoivent porter le masque. Cependant il y a des exceptions&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Les cyclistes ne sont pas oblige\u0301s de porter de\nmasque car exer\u00e7ant une activite\u0301 physique&nbsp;;<\/li><li>Les joggeurs en sont aussi dispense\u0301s pour la\nm\u00eame raison&nbsp;;<\/li><li>Les enfants de moins de 11 ans peuvent aussi\ncirculer visage de\u0301couvert.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"color: #64e600\"> Les motards doivent-ils porter un masque&nbsp;?<\/h2>\n\n\n\n<p>Pour les motards, le masque a d\u2019abord e\u0301te\u0301 obligatoire pour\ntous. Mais cette annonce a suscite\u0301 de vives protestations des organisations de\nmotards. Ainsi, depuis le 21 septembre les motards e\u0301quipe\u0301s d\u2019un casque inte\u0301gral\navec visi\u00e8re sont dispense\u0301s de masque. Pour e\u0301viter les risques de transmission,\nla visi\u00e8re doit bien s\u00fbr rester abaisse\u0301e. En cas de casque non inte\u0301gral, les\nconducteurs de deux-roues devront donc conserver le masque en roulant.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"color: #64e600\">Motards et cyclistes&nbsp;: quel masque choisir&nbsp;?<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"679\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2020\/10\/masque-covid-1024x679.jpg\" alt=\"Masques jetables\" class=\"wp-image-8549\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2020\/10\/masque-covid-1024x679.jpg 1024w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2020\/10\/masque-covid-300x199.jpg 300w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2020\/10\/masque-covid-768x509.jpg 768w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2020\/10\/masque-covid-1536x1019.jpg 1536w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2020\/10\/masque-covid-2048x1359.jpg 2048w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2020\/10\/masque-covid-1568x1040.jpg 1568w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Pour rendre les trajets plus confortables il est important de bien choisir votre masque, notamment si vous \u00eates a\u0300 moto ou a\u0300 ve\u0301lo. <\/p>\n\n\n\n<p>\u00c0 moto, il est conseille\u0301 d\u2019opter pour le casque inte\u0301gral,\nqui en plus de prote\u0301ger efficacement en cas d\u2019accident, e\u0301vite donc de devoir\nporter le masque. <\/p>\n\n\n\n<p>Les cyclistes sont quant a\u0300 eux de plus en plus nombreux a\u0300\nchoisir le masque anti-pollution qui permet de se prote\u0301ger des projections et\nde filtrer les particules fines. Ceux-ci permettent aussi de respirer correctement\npendant un effort. Des mod\u00e8les de masques anti-pollution, adapte\u0301s aux casques,\nsont aussi commercialise\u0301s pour les motards.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"color: #64e600\"> Conducteurs de voitures&nbsp;: quand doit-on porter le masque&nbsp;?<\/h2>\n\n\n\n<p>Dans certaines situations il est aussi demande\u0301 aux\nconducteurs de voitures et a\u0300 leurs passagers de porter le masque. C\u2019est\nnotamment le cas dans les taxis, o\u00f9 le port du masque est obligatoire pour le\nconducteur et les passagers.<\/p>\n\n\n\n<p>C\u2019est aussi le cas si vous faites du covoiturage, qui impose\nd\u2019ailleurs d\u2019autres r\u00e8gles&nbsp;pour e\u0301viter les risques de transmission :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Deux passagers maximum par range\u0301e de\nsi\u00e8ges&nbsp;;<\/li><li>Le ve\u0301hicule doit \u00eatre ae\u0301re\u0301 le plus fre\u0301quemment\npossible&nbsp;;<\/li><li>Le conducteur peut refuser un passager si\ncelui-ci ne porte pas de masque&nbsp;;<\/li><li>Le proprie\u0301taire du ve\u0301hicule doit le de\u0301sinfecter\nentre chaque trajet&nbsp;;<\/li><li>Un passager est de nouveau accepte\u0301 a\u0300 l\u2019avant, a\u0300\nc\u00f4te\u0301 du conducteur.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"color: #64e600\"> Peut-on enlever son masque pour fumer ou manger dans la rue&nbsp;?<\/h2>\n\n\n\n<p>Que les fumeurs et les adeptes des pauses de\u0301jeuner sur le\npouce se rassurent, la pre\u0301fecture de police de Paris a indique\u0301 \u00ab <em>qu&rsquo;il n&rsquo;est pas interdit de fumer ou de manger\ndans l&rsquo;espace public <\/em>\u00bb. Il est donc possible de retirer son masque\nle temps d\u2019une pause cigarette ou pour manger un sandwich. Cependant, rappelons\nque les distances de se\u0301curite\u0301 doivent toujours \u00eatre respecte\u0301es&nbsp;!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Paris, Lyon, Toulouse, Nice, Marseille\u2026 La plupart des grandes villes fran\u00e7aises, et de plus en plus de petites communes, ont [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":8548,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-8545","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reglementation-routiere"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/8545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=8545"}],"version-history":[{"count":0,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/8545\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/8548"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=8545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=8545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=8545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}