{"id":8551,"date":"2020-10-14T09:53:58","date_gmt":"2020-10-14T07:53:58","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=8551"},"modified":"2020-10-14T09:53:58","modified_gmt":"2020-10-14T07:53:58","slug":"outrage-destruction-degradation-de-radars-quelles-sanctions-pour-les-particuliers","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/radars\/outrage-destruction-degradation-de-radars-quelles-sanctions-pour-les-particuliers\/","title":{"rendered":"Outrage, destruction\/de\u0301gradation de radars : quelles sanctions pour les particuliers ?"},"content":{"rendered":"\n<p>Vandaliser\nun radar (de\u0301gradation, destruction, de\u0301te\u0301rioration) est puni par la loi en\nFrance. Les sanctions diff\u00e8rent toutefois selon la nature de l\u2019infraction et\nles circonstances. Outrager un radar est un acte qui, quant a\u0300 lui, peut \u00eatre\nsanctionne\u0301 si la justice reconna\u00eet que l\u2019outrage a e\u0301te\u0301 sciemment adresse\u0301 a\u0300 une\npersonne de\u0301positaire de l\u2019autorite\u0301 publique \u2013 un cas qui ne s\u2019est encore jamais\npre\u0301sente\u0301 en France. <\/p>\n\n\n\n<p>Vous\nvoulez conna\u00eetre en de\u0301tail la re\u0301glementation fran\u00e7aise concernant l\u2019outrage ou\nla de\u0301gradation\/destruction de radars&nbsp;? Coyote vous pre\u0301sente tous les\nrisques et les sanctions encourus dans ces situations. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"color: #64e600\"> De\u0301gradation de radars&nbsp;: diffe\u0301rentes\nsanctions selon la nature des actes perpe\u0301tre\u0301s<\/h2>\n\n\n\n<p>La\nde\u0301gradation d\u2019un radar est conside\u0301re\u0301e par la loi fran\u00e7aise comme un de\u0301lit\nassimile\u0301 a\u0300 une de\u0301gradation du bien public. Ce de\u0301lit, qui rel\u00e8ve des <a href=\"https:\/\/www.legifrance.gouv.fr\/codes\/id\/LEGIARTI000006418260\/2002-09-10\/#:~:text=Article%20322%2D1,-Modifi%C3%A9%20par%20Loi&amp;text=La%20destruction%2C%20la%20d%C3%A9gradation%20ou,r%C3%A9sult%C3%A9%20qu%27un%20dommage%20l%C3%A9ger.\">articles\n322-1 et 322-2 du Code Pe\u0301nal<\/a>,\npeut entra\u00eener une inscription au casier judiciaire. Les sanctions varient\ncependant selon la nature des actes perpe\u0301tre\u0301s, les circonstances et les\ncondamnations ante\u0301rieures e\u0301ventuelles de la personne mise en cause. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">De\u0301gradation du radar avec autocollants,\ngraffitis, inscriptions\u2026<\/h3>\n\n\n\n<p>Toute\npersonne qui \u00ab&nbsp;trace des inscriptions, des signes ou des dessins&nbsp;\u00bb\nsur un e\u0301quipement de type radar risque jusqu\u2019a\u0300 15&nbsp;000 euros d\u2019amende et\nune peine d\u2019inte\u0301r\u00eat ge\u0301ne\u0301ral. Occulter ou b\u00e2cher les vitres d\u2019un radar entrent\ndans la m\u00eame cate\u0301gorie d\u2019infraction. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Destruction\/de\u0301te\u0301rioration du radar<\/h3>\n\n\n\n<p>Toute\npersonne qui de\u0301truit ou endommage un dispositif de contr\u00f4le routier (incendie,\nvol, explosion, arrachage) commet une infraction pouvant \u00eatre punie d\u2019une peine\nd\u2019emprisonnement de 5 ans et de 75&nbsp;000 euros d\u2019amende. Si l\u2019acte a e\u0301te\u0301\nmene\u0301 par un groupe de personnes, ou par un individu masque\u0301, la sanction peut\naller jusqu\u2019a\u0300 100&nbsp;000 euros d\u2019amende et 7 ans d\u2019emprisonnement. <\/p>\n\n\n\n<p>Dans\nla pratique, il est rarissime qu\u2019une personne coupable de vandalisme sur un\nradar e\u0301cope de la peine maximale pre\u0301vue par la loi. Toutefois, ces derni\u00e8res\nanne\u0301es, les tribunaux n\u2019ont pas he\u0301site\u0301, dans certains cas, a\u0300 donner des peines\nde prison avec sursis, et parfois des peines de prison ferme lorsqu\u2019un radar\navait e\u0301te\u0301 totalement de\u0301truit (notamment dans le cas d\u2019une destruction en bande\norganise\u0301e). <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"color: #64e600\"> Outrage a\u0300 un radar&nbsp;: quelles sanctions\npre\u0301vues par la loi&nbsp;?<\/h2>\n\n\n\n<p>Tout\nfait d\u2019outrage (parole injurieuse, cri, sifflement, regard provocateur, doigt\nd\u2019honneur, menace, dessin, symbole) adresse\u0301 a\u0300 une personne de\u0301positaire de\nl\u2019autorite\u0301 publique est sanctionne\u0301 par la loi en France. Toutefois, pour que\nl\u2019infraction soit reconnue comme telle, la justice doit de\u0301montrer que la\npersonne a eu l\u2019intention de porter outrage a\u0300 son interlocuteur et l\u2019a fait en\nconnaissance de cause. Le de\u0301lit d\u2019outrage n\u2019est donc pas reconnu si la personne\nne connaissait pas la qualite\u0301 du destinataire de la parole\/de l\u2019acte\noutrageux.&nbsp;&nbsp; <\/p>\n\n\n\n<p>Avoir\nun geste de\u0301place\u0301 (doigt, bras d\u2019honneur) ou manifester un comportement\ninjurieux envers une cabine de contr\u00f4le peut-il donc entrainer une condamnation\npe\u0301nale pour outrage&nbsp;? En France, dans le cas d\u2019un doigt d\u2019honneur adresse\u0301\na\u0300 un radar, le parquet a de\u0301ja\u0300 engage\u0301 des poursuites pour outrage a\u0300 agent devant\nle tribunal correctionnel, estimant que le conducteur avait de\u0301libe\u0301re\u0301ment\nenfreint la loi. Toutefois, les tribunaux fran\u00e7ais ont pour l\u2019instant toujours\nestime\u0301 que les conducteurs a\u0300 qui on reprochait ces faits n\u2019avaient pas voulu\ndirectement viser les agents de contr\u00f4le visionnant les radars. Le caract\u00e8re\nindirect de l\u2019outrage et le caract\u00e8re inde\u0301termine\u0301 des personnes vise\u0301es n\u2019ont\njusqu\u2019a\u0300 pre\u0301sent jamais paru suffisamment e\u0301tablis pour constituer une\ninfraction. Outrager un radar n\u2019a donc jamais, a\u0300 l\u2019heure actuelle en France,\ndonne\u0301 lieu a\u0300 une condamnation ni a\u0300 une sanction de la part de la justice. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vandaliser un radar (de\u0301gradation, destruction, de\u0301te\u0301rioration) est puni par la loi en France. Les sanctions diff\u00e8rent toutefois selon la nature [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":7879,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-8551","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-radars"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/8551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=8551"}],"version-history":[{"count":0,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/8551\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/7879"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=8551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=8551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=8551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}