{"id":8814,"date":"2021-01-19T09:36:45","date_gmt":"2021-01-19T08:36:45","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=8814"},"modified":"2021-01-19T09:36:45","modified_gmt":"2021-01-19T08:36:45","slug":"pistolet-radar","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/radars\/pistolet-radar\/","title":{"rendered":"Faut-t-il s\u2019inquie\u0301ter du pistolet-radar a\u0300 longue porte\u0301e ?"},"content":{"rendered":"<p>Il arrive lentement en Europe, le Royaume-Uni l\u2019a de\u0301ja\u0300 adopte\u0301 et des tests sont en cours en Espagne\u2026 Mais quel est donc ce nouveau pistolet-radar dont certains automobilistes s\u2019inqui\u00e8tent ? De\u0301veloppe\u0301 par la compagnie ame\u0301ricaine Laser Technology, le \u00ab TruCam II \u00bb peut de\u0301tecter des exc\u00e8s de vitesse jusqu\u2019a\u0300 1500 m\u00e8tres avec une marge d\u2019erreur d\u2019environ 2km\/h.<br \/>\nS\u2019il n\u2019est pas encore homologue\u0301 en France, on peut s\u2019attendre a\u0300 ce que son efficacite\u0301 lui permette de se de\u0301mocratiser rapidement.<\/p>\n<h2 style=\"color: #64e600\">Les spe\u0301cificite\u0301s du nouveau pistolet-radar<\/h2>\n<p>Ce nouvel outil des forces de l\u2019ordre co\u00fbte entre 10 000 et 11 000 euros et est e\u0301quipe\u0301 d\u2019un laser infrarouge capable de de\u0301tecter les ve\u0301hicules de jour comme de nuit. Il peut enregistrer la vitesse d\u2019un ve\u0301hicule avec pre\u0301cision jusqu\u2019a\u0300 320km\/h.<\/p>\n<p>En comparaison, la police fran\u00e7aise utilise encore des <a href=\"https:\/\/www.moncoyote.com\/blog\/securite-routiere\/radars\/zoom-sur-le-radar-jumelle\/\">jumelles nume\u0301riques<\/a> dont la porte\u0301e maximale est d\u2019environ 600 m\u00e8tres et dont la marge d\u2019erreur est de l\u2019ordre de 5km\/h. De plus, leurs outils ne leur permettent pas de travailler de nuit convenablement. L\u2019e\u0301cart technologique est donc conse\u0301quent, d\u2019autant plus que ces nouveaux pistolets-radars e\u0301mettent automatiquement une contravention en traitant l\u2019infraction enregistre\u0301e avant de l\u2019envoyer aux serveurs de police.<\/p>\n<p>Pour une conduite sereine, vous pourrez toujours compter sur <a href=\"https:\/\/www.moncoyote.com\/fr\/application-coyote.html\">l\u2019application Coyote<\/a> pour vous assurer que vous roulez a\u0300 la bonne vitesse !<\/p>\n<h2 style=\"color: #64e600\">Une arrive\u0301e en France a\u0300 pre\u0301voir ?<\/h2>\n<p>L\u2019achat et la mise en place de ces nouveaux e\u0301quipements repre\u0301senteraient un co\u00fbt conse\u0301quent pour la France, sans pour autant assurer des rentre\u0301es d\u2019argent plus importantes. Si l\u2019efficacite\u0301 de ce nouveau pistolet-radar est incontestable et qu\u2019il permet certainement de contr\u00f4ler davantage d\u2019automobilistes, il renforce davantage l\u2019effet pre\u0301ventif de la pre\u0301sence polici\u00e8re qu\u2019il ne rapporte d\u2019argent.<\/p>\n<p>La France a connu une anne\u0301e difficile e\u0301conomiquement dans le domaine de la se\u0301curite\u0301 routi\u00e8re, comme dans la plupart des autres secteurs, notamment a\u0300 cause des <a href=\"https:\/\/www.moncoyote.com\/blog\/securite-routiere\/radars\/gilets-jaunes-bilan-de-la-degradation-des-radars\/\">de\u0301gradations de radars<\/a> suite aux nombreux mouvements sociaux et aux <a href=\"https:\/\/www.moncoyote.com\/blog\/securite-routiere\/radars\/recettes-radars-2020\/\">recettes des radars<\/a> plus faibles que pre\u0301vu en raison du confinement.<\/p>\n<p>Au vu de la situation, il semble peu probable que la France fasse l\u2019achat de ces nouveaux outils de contr\u00f4le sa priorite\u0301 ! Une affaire a\u0300 suivre e\u0301videmment puisque l\u2019arrive\u0301e de ces pistolets-radars impliquerait tr\u00e8s certainement de redoubler d\u2019efforts face aux contr\u00f4les policiers. D\u2019ici-la\u0300, prenez garde en cas de voyage sur les routes britanniques puisque ces pistolets-radars high tech sont de\u0301ja\u0300 en cours d\u2019utilisation !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il arrive lentement en Europe, le Royaume-Uni l\u2019a de\u0301ja\u0300 adopte\u0301 et des tests sont en cours en Espagne\u2026 Mais quel [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":8815,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-8814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-radars"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/8814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=8814"}],"version-history":[{"count":0,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/8814\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/8815"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=8814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=8814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=8814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}