{"id":8873,"date":"2021-03-10T09:25:23","date_gmt":"2021-03-10T08:25:23","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=8873"},"modified":"2023-12-04T14:36:50","modified_gmt":"2023-12-04T13:36:50","slug":"prix-innovations-securite-routiere-2021","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/securite-routiere\/prix-innovations-securite-routiere-2021\/","title":{"rendered":"Prix Innovation se\u0301curite\u0301 routi\u00e8re : de nouveaux outils"},"content":{"rendered":"<p>Cette anne\u0301e a eu lieu la cinqui\u00e8me e\u0301dition du \u00ab Prix Innovation \u00bb de\u0301cerne\u0301 par les institutions en charge de la Se\u0301curite\u0301 Routi\u00e8re. Ce prix a pour but d\u2019encourager et de motiver la recherche et l\u2019innovation dans le domaine de la pre\u0301vention et de la se\u0301curite\u0301 routi\u00e8re.<\/p>\n<h2 style=\"color: #64e600;\">Retour sur l\u2019e\u0301dition 2021 du Prix Innovation<\/h2>\n<p>Cette anne\u0301e encore, l\u2019honneur est aux objets connecte\u0301s et la tendance est a\u0300 la digitalisation ! Les entreprises s\u2019appuient sur les nouvelles technologies afin de proposer des solutions toujours plus efficaces.<br \/>\nDans un premier temps, 17 candidats sur 38 ont e\u0301te\u0301 se\u0301lectionne\u0301s dans six cate\u0301gories diffe\u0301rentes pour leurs efforts dans le de\u0301veloppement de nouveaux outils afin de rendre nos routes plus s\u00fbres. Par la suite, un jury compose\u0301 de professionnels du secteur a de\u0301libe\u0301re\u0301. Voici un aper\u00e7u des innovations qui ont remporte\u0301 le prix dans leur cate\u0301gorie !<\/p>\n<h3>\u00ab Aide aux deux-roues \u00bb : un casque connecte\u0301<\/h3>\n<p>Abus France a e\u0301te\u0301 re\u0301compense\u0301 pour son casque connecte\u0301 \u00ab Abus Quin \u00bb qui permet aux cyclistes de pre\u0301venir automatiquement un proche en cas d\u2019accident. Le casque est capable de mesurer l\u2019impact d\u2019une collision et d\u2019e\u0301valuer les risques avant d\u2019envoyer un signal indiquant la ge\u0301o-localisation. La personne informe\u0301e peut ensuite contacter les secours en cas de besoin.<\/p>\n<h3>\u00ab Aide aux premiers secours \u00bb : informer plus rapidement<\/h3>\n<p>Le laure\u0301at 2021 de la cate\u0301gorie \u00ab Aide aux premiers secours \u00bb est l\u2019entreprise De\u0301sin\u2019car et son application RescueCode. En cas d\u2019accident, l\u2019application permet aux premiers secours de lire un QR Code place\u0301 au pre\u0301alable sur le ve\u0301hicule. Ce dernier donne instantane\u0301ment acc\u00e8s instantane\u0301ment a\u0300 la fiche de de\u0301sincarce\u0301ration afin d\u2019obtenir toutes les informations ne\u0301cessaires.<\/p>\n<h3>\u00ab Applications et plateformes nume\u0301riques \u00bb : des ultrasons pour alerter<\/h3>\n<p>La RATP a de\u0301veloppe\u0301 une application nomme\u0301e AMY en partenariat avec CopSonic. Sa fonction permet d\u2019alerter les pie\u0301tons distraits par leur te\u0301le\u0301phone au niveau des passages pie\u0301tons ou le long des voies de tramway. Face a\u0300 la recrudescence des accidents autour de ces zones, l\u2019application utilise diffe\u0301rentes alertes afin de pre\u0301venir les pie\u0301tons de l\u2019arrive\u0301e d\u2019un ve\u0301hicule.<\/p>\n<h3>\u00ab Ame\u0301lioration des e\u0301quipements de ve\u0301hicules \u00bb : un pare-soleil intelligent<\/h3>\n<p>Un pare-soleil intelligent et connecte\u0301, voila\u0300 la derni\u00e8re invention de la compagnie Bosch. Intitule\u0301 \u00ab Virtual Visor \u00bb, ce pare-soleil digital remplace le rectangle plastique habituel par un e\u0301cran LCD transparent e\u0301quipe\u0301 d\u2019une came\u0301ra. Ce dernier est capable d\u2019identifier a\u0300 la fois le visage du conducteur et les rayons du soleil.<\/p>\n<p>Il identifie donc les zones a\u0300 assombrir afin d\u2019e\u0301viter que le conducteur ne soit e\u0301bloui tout en laissant le reste de l\u2019e\u0301cran transparent.<\/p>\n<h3>\u00ab Pre\u0301vention du risque routier en entreprise \u00bb : automatiser l\u2019e\u0301tat des lieux<\/h3>\n<p>L\u2019entreprise Proov Group a de\u0301veloppe\u0301 une application destine\u0301e a\u0300 la pre\u0301vention des risques au sein des flottes automobiles. Elle permet aux conducteurs d\u2019effectuer eux-m\u00eames l\u2019e\u0301tat des lieux de leur ve\u0301hicule. Outre un ve\u0301ritable gain de temps, cela permet un meilleur suivi de l\u2019e\u0301tat des ve\u0301hicules de la flotte afin d\u2019e\u0301viter tout probl\u00e8me.<\/p>\n<h3>\u00ab Ame\u0301lioration des infrastructures \u00bb : un nouveau marquage routier<\/h3>\n<p>L\u2019entreprise 3M a invente\u0301 un nouveau type de marquage au sol bien plus visible que ceux utilise\u0301s aujourd\u2019hui, y compris pendant la nuit ou en cas d\u2019intempe\u0301ries. Gr\u00e2ce a\u0300 des e\u0301le\u0301ments optiques a\u0300 indice de re\u0301fraction e\u0301leve\u0301, ce marquage routier devient lumineux sous les feux des ve\u0301hicules sans avoir besoin d\u2019alimentation e\u0301lectrique.<\/p>\n<p>Vous l\u2019aurez compris, cette cinqui\u00e8me e\u0301dition du Prix Innovation en se\u0301curite\u0301 routi\u00e8re a e\u0301te\u0301 un ve\u0301ritable succ\u00e8s et l\u2019ensemble des outils qui ont e\u0301te\u0301 pre\u0301sente\u0301s te\u0301moignent d\u2019un progr\u00e8s certain pour la s\u00fbrete\u0301 de nos routes.<\/p>\n<p>N\u2019he\u0301sitez pas a\u0300 vous rendre sur <a href=\"https:\/\/www.youtube.com\/channel\/UC6HBB1-4e6-6A54eB6ADXow\">la cha\u00eene YouTube de la se\u0301curite\u0301 routi\u00e8re<\/a> afin d\u2019en apprendre davantage sur les innovations de cette anne\u0301e !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette anne\u0301e a eu lieu la cinqui\u00e8me e\u0301dition du \u00ab Prix Innovation \u00bb de\u0301cerne\u0301 par les institutions en charge de [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":13114,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[30],"tags":[],"class_list":["post-8873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-securite-routiere"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/8873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=8873"}],"version-history":[{"count":1,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/8873\/revisions"}],"predecessor-version":[{"id":13116,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/8873\/revisions\/13116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/13114"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=8873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=8873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=8873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}