{"id":9291,"date":"2021-08-15T10:02:08","date_gmt":"2021-08-15T08:02:08","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=9291"},"modified":"2021-08-15T10:02:08","modified_gmt":"2021-08-15T08:02:08","slug":"quelles-sont-les-differentes-arnaques-a-eviter-lorsquon-achete-une-voiture-electrique-doccasion","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/automobile\/quelles-sont-les-differentes-arnaques-a-eviter-lorsquon-achete-une-voiture-electrique-doccasion\/","title":{"rendered":"Quelles sont les diffe\u0301rentes arnaques a\u0300 e\u0301viter lorsqu\u2019on ach\u00e8te une voiture e\u0301lectrique d\u2019occasion ?"},"content":{"rendered":"<p>Les voitures e\u0301lectriques ont fait leur arrive\u0301e sur le marche\u0301 de l\u2019occasion : le moyen r\u00eave\u0301 de passer a\u0300 la voiture propre tout en me\u0301nageant son budget. Pourtant, devant ce type de ve\u0301hicule propre, il faut avoir en t\u00eate les bons re\u0301flexes pour e\u0301viter les arnaques, qui ne sont pas force\u0301ment celles que l\u2019on est habitue\u0301 a\u0300 e\u0301viter avec des moteurs a\u0300 combustion. Si les pre\u0301cautions d\u2019usage demeurent, certains de\u0301tails spe\u0301cifiques aux moteurs e\u0301lectriques peuvent vous mettre la puce a\u0300 l\u2019oreille.<\/p>\n<p>La vente de ve\u0301hicules propres de particulier a\u0300 particulier commence timidement a\u0300 augmenter en France. Moins ch\u00e8res qu\u2019un mod\u00e8le neuf, les voitures e\u0301lectriques, re\u0301centes ou anciennes, pre\u0301sentent ne\u0301anmoins le risque de re\u0301parations bien plus co\u00fbteuses que pour les mod\u00e8les thermiques.<\/p>\n<p>D\u2019habitude, il est assez facile en tant qu\u2019acheteur d\u2019e\u0301valuer l\u2019usure des pi\u00e8ces ou de ne\u0301gocier le prix en fonction de l\u2019e\u0301tat ge\u0301ne\u0301ral. Mais leur caract\u00e8re ine\u0301dit permet a\u0300 certains vendeurs peu scrupuleux de vous induire en erreur en vous cachant certains de\u0301fauts ou des re\u0301parations a\u0300 faire.<\/p>\n<h2 style=\"color: #64e600\">Que vaut re\u0301ellement la batterie d\u2019une voiture e\u0301lectrique d\u2019occasion ?<\/h2>\n<p>La batterie des voitures e\u0301lectriques, comme toutes les autres, s\u2019use quotidiennement, si bien qu\u2019un mod\u00e8le avec assez de kilom\u00e8tres au compteur devra afficher un prix plus bas. C\u2019est donc la m\u00eame situation que pour un ve\u0301hicule classique, mais certains vendeurs peuvent affirmer que cette usure est ne\u0301gligeable, a\u0300 tort. D\u2019autres avancent qu\u2019un changement de batterie, lorsque celle-ci est trop ab\u00eeme\u0301e, revient a\u0300 quelques centaines d\u2019euros.<\/p>\n<p>C\u2019est parfois bel et bien un simple composant qui devra \u00eatre remplace\u0301, mais un changement de batterie complet peut entra\u00eener jusqu\u2019a\u0300 environ 15 000\u20ac de frais selon les mod\u00e8les, l\u2019ensemble des pi\u00e8ces concerne\u0301es e\u0301tant trop use\u0301es.<\/p>\n<p>Ainsi, fuyez-donc par pre\u0301caution les mod\u00e8les les plus anciens, dont l\u2019entretien a rarement pu \u00eatre effectue\u0301 correctement.<\/p>\n<h3>Autonomie et recharge, deux crit\u00e8res essentiels<\/h3>\n<p>N\u2019he\u0301sitez pas a\u0300 e\u0301valuer l\u2019e\u0301tat de la batterie afin d\u2019e\u0301viter les mauvaises surprises, soit <a href=\"https:\/\/www.moncoyote.com\/blog\/automobile\/innovation\/voiture-electrique-une-solution-pour-evaluer-letat-et-les-performances-de-la-batterie\/\" target=\"_blank\" rel=\"noopener noreferrer\">avec un kit de test de capacite\u0301<\/a>, soit en consultant des forums spe\u0301cialise\u0301s pour de\u0301terminer si elle permet d\u2019assurer vos trajets quotidiens. L\u2019autonomie est souvent sure\u0301value\u0301e par les vendeurs dans leurs offres, de m\u00eame que le temps de recharge, une nuit pouvant ne pas suffire selon les kilom\u00e8tres parcourus.<\/p>\n<p>Dans tous les cas, <a href=\"https:\/\/www.moncoyote.com\/blog\/automobile\/les-bornes-de-voitures-electriques-sont-elles-suffisantes-en-france\/\" target=\"_blank\" rel=\"noopener noreferrer\">ve\u0301rifiez o\u00f9 se trouvent les bornes de recharge pr\u00e8s de chez vous<\/a>, afin de ne pas vous retrouver de\u0301pourvu lorsque la batterie faible sera venue. Ces derni\u00e8res ne sont pas toujours adapte\u0301es a\u0300 tous les mod\u00e8les : un vendeur de bonne foi saura vous renseigner sur la compatibilite\u0301 de la prise.<\/p>\n<h3>Batteries en location : un mod\u00e8le obsol\u00e8te ?<\/h3>\n<p>Lors de leurs premi\u00e8res commercialisations, la plupart des voitures e\u0301lectriques proposaient obligatoirement la location des batteries. Sur le papier, cela vous garantit une batterie comme neuve d\u2019anne\u0301e en anne\u0301e.<br \/>\nCependant, cela signifie qu\u2019un loyer pouvant aller jusqu\u2019a\u0300 100\u20ac s\u2019ajoute chaque mois pour e\u0301changer la batterie. Surtout, cette offre de location n\u2019existe plus pour la majorite\u0301 de ces ve\u0301hicules propres, comme la Renault Zoe\u0301. Attention aux vendeurs qui se gardent bien de vous le pre\u0301ciser\u2026<\/p>\n<h2 style=\"color: #64e600\">Comment prendre en compte les aides a\u0300 l\u2019achat de ve\u0301hicules e\u0301lectriques ?<\/h2>\n<p>Il arrive de trouver des annonces de\u0301duisant les aides propose\u0301es par l\u2019Etat pour gonfler le prix de vente. Parfois, l\u2019ensemble de ces primes et bonus sont cumule\u0301s, sans tenir compte de votre e\u0301ligibilite\u0301. Avant de vous de\u0301placer, ve\u0301rifiez donc par exemple que la prime a\u0300 la conversion concerne votre ve\u0301hicule (sans oublier qu\u2019elle n\u2019est que de 2500\u20ac maximum). On recommandera donc de pre\u0301fe\u0301rer un vendeur annon\u00e7ant un prix hors-aides. L\u2019e\u0301cart entre prix annonce\u0301 et prix re\u0301el peut \u00eatre conse\u0301quent, ne serait-ce qu\u2019avec le bonus e\u0301cologique de 6 000 \u20ac.<\/p>\n<p>Avec cela en t\u00eate, n\u2019he\u0301sitez pas a\u0300 consulter <a href=\"https:\/\/www.moncoyote.com\/blog\/automobile\/comment-choisir-une-voiture-doccasion\/\">notre guide pour bien choisir une voiture d\u2019occasion<\/a>, dont les conseils s\u2019appliquent toujours. Notez que si vous n\u2019avez jamais conduit une voiture e\u0301lectrique, on conseille d\u2019essayer le mod\u00e8le neuf chez un concessionnaire, avant d\u2019essayer le mod\u00e8le d\u2019occasion, pour les comparer en ayant un re\u0301fe\u0301rentiel !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les voitures e\u0301lectriques ont fait leur arrive\u0301e sur le marche\u0301 de l\u2019occasion : le moyen r\u00eave\u0301 de passer a\u0300 la [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":9293,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-9291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-automobile"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/9291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=9291"}],"version-history":[{"count":0,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/9291\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/9293"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=9291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=9291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=9291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}