<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Deprecated</b>:  strtolower(): Passing null to parameter #1 ($string) of type string is deprecated in <b>/var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php</b> on line <b>129</b><br />
<br />
<b>Warning</b>:  Cannot modify header information - headers already sent by (output started at /var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php:129) in <b>/var/www/html/web/wp/wp-includes/rest-api/class-wp-rest-server.php</b> on line <b>1896</b><br />
<br />
<b>Warning</b>:  Cannot modify header information - headers already sent by (output started at /var/www/html/web/app/plugins/windows-azure-storage/includes/class-windows-azure-helper.php:129) in <b>/var/www/html/web/wp/wp-includes/rest-api/class-wp-rest-server.php</b> on line <b>1896</b><br />
{"id":9367,"date":"2021-10-06T10:34:24","date_gmt":"2021-10-06T08:34:24","guid":{"rendered":"https:\/\/www.moncoyote.com\/blog\/?p=9367"},"modified":"2021-10-06T10:34:24","modified_gmt":"2021-10-06T08:34:24","slug":"paris-decouvrez-la-liste-des-rues-qui-restent-a-50mk-h","status":"publish","type":"post","link":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/non-classe\/paris-decouvrez-la-liste-des-rues-qui-restent-a-50mk-h\/","title":{"rendered":"Limitation de vitesse a\u0300 Paris : de\u0301couvrez la liste des rues qui restent a\u0300 50km\/h"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<p class=\"has-text-color has-very-dark-gray-color\"><strong>Depuis le 30 ao\u00fbt dernier, la vitesse maximale autorise\u0301e dans les rues de Paris est de\u0301sormais limite\u0301e a\u0300 30km\/h. Cette mesure mise en place par la maire de Paris, Anne Hidalgo, a pour objectif de diminuer la pollution sonore et atmosphe\u0301rique. Certains grands axes conservent cependant leur limitation a\u0300 50km\/h. Voici la liste compl\u00e8te : <\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><\/h3>\n\n\n\n<p style=\"color:#64e61e\" class=\"has-text-color\"><strong>4<sup>\u00e8me<\/sup> arrondissement de Paris : <\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Voie Georges Pompidou depuis le boulevard Bourdon jusqu\u2019a\u0300 la voie Cu\/12 (porte de Bercy)<br><\/li><\/ul>\n\n\n\n<p style=\"color:#64e61e\" class=\"has-text-color\"><strong>8<sup>\u00e8me<\/sup> arrondissement de Paris : <\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Avenue des Champs-E\u0301lyse\u0301es<\/li><li>Rue Royale<\/li><li>Voie Georges Pompidou depuis le quai Saint-Exupe\u0301ry jusqu\u2019a\u0300 la place de la Concorde, et depuis la place de la Concorde jusqu\u2019a\u0300 la rue Beethoven<\/li><li>Boulevard Malesherbes entre la place de la Madeleine et la rue Cardinet<\/li><\/ul>\n\n\n\n<p style=\"color:#64e61e\" class=\"has-text-color\"><strong>12<sup>\u00e8me<\/sup> arrondissement de Paris : <\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Boulevard Soult entre l\u2019avenue de la Porte de Vincennes et la rue Montempoivre, et entre la rue Rottembourg et la rue de l\u2019Amiral la Ronci\u00e8re le Noury<\/li><li>Boulevard Poniatowski<\/li><li>Avenue de Gravelle<\/li><li>Avenue de Nogent<\/li><li>Avenue de Saint-Maurice<\/li><li>Avenue du Tremblay<\/li><li>Boulevard Diderot entre la place de la Nation et la rue de Picpus, entre la rue Pierre Bourdan et l\u2019avenue Daumesnil, et entre la rue Jean Bouton et le quai de la R\u00e2pe\u0301e<\/li><li>Route de la Pyramide entre la route de la Ferme et l\u2019Esplanade Saint-Louis (a\u0300 l&rsquo;exception d&rsquo;une bande de 90 m)<\/li><li>Voie Georges Pompidou depuis la voie Ct\/12 jusqu\u2019a\u0300 la rue Traversi\u00e8re, et depuis le boulevard Bourdon vers et jusqu\u2019a\u0300 la voie Cu\/12<\/li><li>Pont National<\/li><li>Avenue de la Porte de Vincennes<\/li><li>Cours de Vincennes<\/li><\/ul>\n\n\n\n<p style=\"color:#64e61e\" class=\"has-text-color\"><strong>13<sup>\u00e8me<\/sup> arrondissement de Paris : <\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Boulevard du Ge\u0301ne\u0301ral Jean Simon<\/li><li>Boulevard Masse\u0301na<\/li><li>Boulevard Kellermann<\/li><li>Pont National<\/li><\/ul>\n\n\n\n<p style=\"color:#64e61e\" class=\"has-text-color\"><strong>14<sup>\u00e8me<\/sup> arrondissement de Paris : <\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Boulevard Jourdan (sauf une bande de 50 m de part et d\u2019autre de la Cite\u0301 Universitaire)<\/li><li>Boulevard Brune<\/li><li>Avenue de la Porte d\u2019Orle\u0301ans<\/li><li>Avenue Denfert-Rochereau<\/li><li>Avenue du Ge\u0301ne\u0301ral Leclerc<\/li><li>Avenue du Maine<\/li><li>Place du 25 ao\u00fbt 1944<\/li><li>Rue de la Le\u0301gion E\u0301trang\u00e8re<br>      &nbsp;<\/li><\/ul>\n\n\n\n<p style=\"color:#64e61e\" class=\"has-text-color\"><strong>15<sup>\u00e8me<\/sup> arrondissement de Paris : <\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Boulevard Lefebvre<\/li><li>Boulevard Victor<\/li><li>Boulevard du Ge\u0301ne\u0301ral Martial Valin<\/li><li>Pont du Garigliano<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"572\" src=\"https:\/\/csi.int.coyotesystems.com\/blog\/app\/uploads\/sites\/16\/2021\/09\/AdobeStock_180448302-1024x572.png\" alt=\"\" class=\"wp-image-9383\" srcset=\"https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2021\/09\/AdobeStock_180448302-1024x572.png 1024w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2021\/09\/AdobeStock_180448302-300x168.png 300w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2021\/09\/AdobeStock_180448302-768x429.png 768w, https:\/\/stwordpressint.blob.core.windows.net\/wordpress\/sites\/16\/2021\/09\/AdobeStock_180448302.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p style=\"color:#64e61e\" class=\"has-text-color\"><strong>16<sup>\u00e8me<\/sup> arrondissement de Paris : <\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Pont du Garigliano<\/li><li>Boulevard Exelmans<\/li><li>Boulevard Suchet<\/li><li>Boulevard Lannes entre la Place de la Colombie et la rue Dufrenoy, et entre l\u2019avenue de Pologne et le passage souterrain Henri Gaillard<\/li><li>Passage souterrain Henri Gaillard<\/li><li>Boulevard de l\u2019Amiral Bruix entre le passage souterrain Henri Gaillard et le boulevard Thierry de Martel<\/li><li>Boulevard Thierry de Martel entre le boulevard de l\u2019Amiral Bruix et le passage souterrain Maillo<\/li><li>Alle\u0301e de Longchamps<\/li><li>Alle\u0301e du Bord de l\u2019Eau<\/li><li>Avenue de la Porte d\u2019Auteuil<\/li><li>Avenue de l\u2019Hippodrome<\/li><li>Avenue Foch<\/li><li>Boulevard Anatole France<\/li><li>Route de S\u00e8vres a\u0300 Neuilly<\/li><li>Route de Suresnes entre l\u2019alle\u0301e du Bord de l\u2019Eau et le carrefour de Longchamps<\/li><li>Route des Lacs a\u0300 Passy<\/li><li>Passage souterrain Maillot<\/li><li>Avenue de la Grande Arme\u0301e<\/li><li>Voie Georges Pompidou depuis le quai Saint-Exupe\u0301ry jusqu\u2019a\u0300 la place de la Concorde, et depuis la place de la Concorde jusqu\u2019a\u0300 la rue Beethoven<\/li><\/ul>\n\n\n\n<p style=\"color:#64e61e\" class=\"has-text-color\"><strong>17<sup>\u00e8me<\/sup> arrondissement de Paris : <\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Boulevard Pershing<\/li><li>Boulevard Gouvion-Saint-Cyr entre le boulevard Pershing et le passage souterrain Champerret<\/li><li>Passage souterrain Champerret<\/li><li>Boulevard Berthier entre la place Paul Le\u0301autaud et la rue de l\u2019Abbe\u0301 Rousselot, entre le n\u00b0110 et l\u2019avenue de la Porte d\u2019Asni\u00e8res, et entre la rue Marguerite Long et l\u2019avenue de la Porte de Clichy<\/li><li>Boulevard Bessi\u00e8res l\u2019avenue de la Porte de Clichy et la rue Guttin, entre la rue Bessi\u00e8res et la rue du Docteur Paul Brousse, et entre la rue Pouchet et l\u2019avenue de la Porte de Saint-Ouen<\/li><li>Boulevard Malesherbes entre la rue Jouffroy d\u2019Abbans et l\u2019avenue de la Porte d\u2019Asni\u00e8res<\/li><li>Avenue de la Porte d\u2019Asni\u00e8res<\/li><li>Passage souterrain Maillot<\/li><li>Avenue de la Grande Arme\u0301e<\/li><li>Boulevard Malesherbes entre la place de la Madeleine et la rue Cardinet<\/li><\/ul>\n\n\n\n<p style=\"color:#64e61e\" class=\"has-text-color\"><strong>18<sup>\u00e8me<\/sup> arrondissement de Paris :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Boulevard Ney<br>      &nbsp;<\/li><\/ul>\n\n\n\n<p style=\"color:#64e61e\" class=\"has-text-color\"><strong>19<sup>\u00e8me<\/sup> arrondissement de Paris :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Boulevard MacDonald par le passage souterrain Villette<\/li><li>Passage souterrain Villette<\/li><li>Boulevard Se\u0301rurier depuis le boulevard MacDonald jusqu\u2019a\u0300 la voie Cz\/19, depuis la voie Cy\/19 vers et jusqu\u2019au boulevard MacDonald, et entre l\u2019avenue de la Porte du Pre\u0301-Saint-Gervais et l\u2019avenue de la Porte des Lilas<\/li><li>Voie Cz\/19 depuis le boulevard Se\u0301rurier jusqu\u2019au boulevard d\u2019Indochine<\/li><li>Voie Cy\/19 depuis la place de la Porte de Chaumont jusqu\u2019au boulevard Se\u0301rurier<\/li><li>Boulevard d\u2019Indochine entre la place de la Porte de Chaumont et l\u2019avenue de la Porte Brunet<\/li><li>Boulevard d&rsquo;Alge\u0301rie<\/li><\/ul>\n\n\n\n<p style=\"color:#64e61e\" class=\"has-text-color\"><strong>20<sup>\u00e8me<\/sup> arrondissement de Paris : <\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Boulevard Mortier<\/li><li>Boulevard Davout entre l\u2019avenue de la Porte de Bagnolet et le N\u00b060, et entre la rue Paganini et l\u2019avenue de la Porte de Vincennes<\/li><li>Avenue de la Porte de Vincennes<\/li><li>Cours de Vincennes<\/li><\/ul>\n\n\n\n<p>Quel que soit l\u2019axe que vous empruntez a\u0300 Paris, votre <strong><a href=\"https:\/\/www.moncoyote.com\/fr\/products-fr.html\">boitier<\/a><\/strong> connecte\u0301 ou <strong><a href=\"https:\/\/www.moncoyote.com\/fr\/application-coyote.html\">Application<\/a><\/strong> Coyote vous indique en temps re\u0301el la bonne limitation de vitesse. De\u0301couvrez tous nos outils d\u2019aide a\u0300 la conduite : <a href=\"https:\/\/www.moncoyote.com\/fr\/\">L\u2019assistant d&rsquo;aide a\u0300 la conduite et application GPS Coyote &#8211; Coyote (moncoyote.com)<\/a><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis le 30 ao\u00fbt dernier, la vitesse maximale autorise\u0301e dans les rues de Paris est de\u0301sormais limite\u0301e a\u0300 30km\/h. Cette [&hellip;]<\/p>\n","protected":false},"author":106,"featured_media":9369,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[26,1],"tags":[],"class_list":["post-9367","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-securite-routiere","category-non-classe"],"acf":[],"_links":{"self":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/9367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/users\/106"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/comments?post=9367"}],"version-history":[{"count":0,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/posts\/9367\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media\/9369"}],"wp:attachment":[{"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/media?parent=9367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/categories?post=9367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.csi.int.coyotesystems.com\/blog\/wp-json\/wp\/v2\/tags?post=9367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}